{"id":39439,"date":"2019-07-16T17:15:55","date_gmt":"2019-07-16T15:15:55","guid":{"rendered":"https:\/\/www.courzyvite.run\/blog\/?p=39439"},"modified":"2021-04-05T12:40:18","modified_gmt":"2021-04-05T10:40:18","slug":"resultats-et-compte-rendu-de-la-course-de-la-dent-doche-30-06-19","status":"publish","type":"post","link":"https:\/\/www.courzyvite.run\/blog\/2019\/07\/16\/resultats-et-compte-rendu-de-la-course-de-la-dent-doche-30-06-19\/","title":{"rendered":"RESULTATS ET COMPTE RENDU DE LA COURSE DE LA DENT D\u2019OCHE \/ 30-06-19"},"content":{"rendered":"<p><strong>HELENE DARRAGON AU SOMMET DE SON ART<\/strong><\/p>\n<p>1h03\u201940 : eh bien voil\u00e0 un chrono qui nous a fait sortir, en ce dimanche 30 juin, de notre torpeur estivale ! En l\u2019occurrence celui r\u00e9alis\u00e9 par la Vacheressande <strong>H\u00e9l\u00e8ne Darragon <\/strong>lors de la Course de la Dent d\u2019Oche, concoct\u00e9e depuis 2010 par la Mairie de Bernex, et longue de 7 km pour 1170 m de d\u00e9nivel\u00e9 positif (1).<\/p>\n<p><strong>Quatri\u00e8me meilleur temps f\u00e9minin<\/strong><br \/>\nSeules trois grimpeuses auraient l\u00e9g\u00e8rement fait mieux qu\u2019H\u00e9l\u00e8ne dans l\u2019histoire de cette embl\u00e9matique mont\u00e9e s\u00e8che (2), au demeurant de sacr\u00e9es clientes :<br \/>\n&#8211; La Suissesse <strong>Catherine Mabillard<\/strong> en 1h03\u201938 en 2002.<br \/>\n&#8211; L\u2019Anglaise<strong> Victoria Wilkinson<\/strong> en 1h02\u201913 en 2005.<br \/>\n&#8211; Enfin, l\u2019Allingeoise <strong>C\u00e9lia Chiron<\/strong> en 1h03\u201922 en 2015.<br \/>\nLa premi\u00e8re \u00e9tait internationale de ski-alpinisme, les deux autres internationales de course en montagne.<br \/>\nC\u2019est dire la prouesse d\u2019H\u00e9l\u00e8ne pour son galop d\u2019essai \u00e0 la dent d\u2019Oche. Elle aurait m\u00eame pu caresser encore un peu plus le record de Victoria s\u2019il n\u2019y avait eu cette satan\u00e9e canicule, sans parler de sa laryngite qui s\u2019est r\u00e9veill\u00e9e pendant l\u2019ascension de la chemin\u00e9e, ultime \u00e9tape avant l\u2019\u00e9pilogue.<\/p>\n<p><strong>Une ann\u00e9e faste&#8230;<\/strong><br \/>\nSon succ\u00e8s est le sixi\u00e8me engrang\u00e9 cette saison. Auparavant, cette femme originaire d\u2019Abondance, \u00e2g\u00e9e de 33 ans, avait d\u00e9croch\u00e9 :<br \/>\n&#8211; Le 11 km de l\u2019Anthychoise.<br \/>\n&#8211; Le Trail and Bike des Moises en compagnie de sa co\u00e9quipi\u00e8re d\u2019Evian Off Course (EOC) <strong>Odile Curdy<\/strong>.<strong><br \/>\n<\/strong>&#8211; Les 4 h 00 de l\u2019Ultra Mont\u00e9e Thollon-les-M\u00e9mises.<br \/>\n&#8211; Le 12,5 km des Trails de la Vall\u00e9e du Brevon.<br \/>\n&#8211; Enfin, le 35 km du Trail des Cr\u00eates du Chablais.<br \/>\nPar ailleurs, elle avait boucl\u00e9 le 19 km de l\u2019Allingeoise au 2\u00e8me rang, derri\u00e8re une autre camarade d\u2019EOC en la personne d\u2019<strong>Ana\u00efs Boucansaud<\/strong> (3).<br \/>\nSon ann\u00e9e est d\u2019autant plus \u00e9clatante qu\u2019elle succ\u00e8de \u00e0 une ann\u00e9e blanche, hormis une 4\u00e8me place en janvier au Trail Blanc du Semnoz. La raison ? La naissance de <strong>L\u00e9a<\/strong>, son premier enfant, qui surviendra le 17 septembre.<\/p>\n<p><strong>&#8230; mais en m\u00eame temps transitoire<\/strong><br \/>\nD\u2019ores et d\u00e9j\u00e0, on piaffe d\u2019impatience de la revoir le 11 ao\u00fbt, non pas sur le 23 km du Trail des Hauts-Forts o\u00f9 elle avait d\u00e9j\u00e0 paraph\u00e9 son engagement, mais \u00e0&#8230; Sierre-Zinal ! T\u00e9moignant de ses ambitions, elle a profit\u00e9 en effet d\u2019un d\u00e9sistement &#8211; les inscriptions \u00e9tant closes &#8211; pour aller d\u00e9couvrir, et en m\u00eame temps d\u00e9fier, ce parcours de l\u00e9gende qui accueillera pour la premi\u00e8re fois la prestigieuse Golden Trail World Series, et ce en tant que 4\u00e8me manche. L\u2019occasion bien s\u00fbr de se mesurer \u00e0 la fine fleure de la course de montagne, et pourquoi pas de la titiller&#8230;<br \/>\nCependant, elle continuera en 2019 de donner priorit\u00e9 \u00e0 sa famille, \u00e0 son boulot, mais aussi \u00e0 ses entra\u00eenements dans l\u2019optique d\u2019une ann\u00e9e 2020 o\u00f9 elle compte bien s\u2019introduire pour de bon dans la cour des grands, et ainsi bousculer la hi\u00e9rarchie. Du coup, les autres \u00e9ch\u00e9ances qu\u2019elle a officialis\u00e9es cette saison, m\u00eame si elles ne manquent pas de sel, n\u2019attirent pas vraiment le gratin, qu\u2019il s\u2019agisse du 32 km du Trail des Dents du Midi, le 14 septembre, ou du D\u00e9fi de Fort-l\u2019Ecluse, le 13 octobre.<\/p>\n<p><strong>Grande premi\u00e8re pour Bouther<\/strong><br \/>\nSon ultime prestation \u00e0 \u00ab La Bec (4) \u00bb remontait d\u00e9j\u00e0 \u00e0 2013 o\u00f9 il s\u2019\u00e9tait class\u00e9 6\u00e8me en 57\u201902. Pour son retour, \u00e0 l\u2019occasion de cette 33\u00e8me \u00e9dition, le redoutable cycliste <strong>Romain Bouther<\/strong> n\u2019a pas fait dans la dentelle, signant en effet une victoire in\u00e9dite. 56\u201936 ont \u00e9t\u00e9 n\u00e9cessaires \u00e0 cet artisan-paysagiste de Saint-Paul-en-Chablais, \u00e2g\u00e9 de 38 ans, pour jaillir comme l\u2019\u00e9clair au refuge o\u00f9 est jug\u00e9e l\u2019arriv\u00e9e. La chaleur torride l\u2019a sans doute dissuad\u00e9 d\u2019effacer sa marque r\u00e9f\u00e9rence, du moins de s\u2019en approcher. Une marque r\u00e9f\u00e9rence port\u00e9e \u00e0 55\u201937 en 2012, et ce pour sa quatri\u00e8me participation (5).<br \/>\nPour ce pensionnaire d\u2019Evian V\u00e9lo o\u00f9 il fait figure de mythe, la dent d\u2019Oche est l\u2019une des rares courses \u00e0 pied qu\u2019il s\u2019autorise, pr\u00e9f\u00e9rant jeter son d\u00e9volu sur le VTT. Ce qui ne l\u2019emp\u00eache pas d\u2019accomplir de belles perfs, baskets aux pieds, sur les grimp\u00e9es s\u00e8ches (Assaut des M\u00e9mises) et autres kilom\u00e8tres verticaux (Fully, Nantaux).<\/p>\n<p><strong>La r\u00e9v\u00e9lation Bouvet<br \/>\n<\/strong>Sinon, on mettra en exergue les quatre autres laur\u00e9ats :<br \/>\n&#8211; Le Meurian <strong>Eddy Bouvet<\/strong>, 22 ans, 2\u00e8me (1er espoir). 46\u2019\u2019 le s\u00e9parent seulement de Romain qui ne l\u2019a devanc\u00e9 qu\u2019en fin de course. Talentueux skieur-alpiniste au sein du CAF Haut-Chablais Morzine, il a termin\u00e9 10\u00e8me du classement national espoirs, seniors et v\u00e9t\u00e9rans hommes durant la saison 2018-2019. Ses adversaires sont d\u00e9sormais pr\u00e9venus : il est \u00e0 surveiller comme le lait sur le feu !<br \/>\n&#8211; Le Chamoniard <strong>Lionel Chatelard<\/strong>, 46 ans, 3\u00e8me (1er quadra), \u00e0 1\u201934 de Romain. Disposant d\u2019une faible notori\u00e9t\u00e9, ce St\u00e9phanois d\u2019origine, licenci\u00e9 \u00e0 Chamonix-Mont-Blanc Marathon, n\u2019en excelle pas moins sur les pentes de catastrophe comme le prouve son palmar\u00e8s forg\u00e9 depuis trois ans :<br \/>\n&#8211; 2016 : 12\u00e8me sur le TPS Vertical K2 Villaroger &#8211; Les Arcs ; 7\u00e8me sur Lavy des Cimes.<br \/>\n&#8211; 2017 : 13\u00e8me sur le TPS Vertical K2 Villaroger &#8211; Les Arcs ; 2\u00e8me sur la Mont\u00e9e de Lancebranlette.<br \/>\n&#8211; 2018 : 3\u00e8me sur l\u2019Ultra Verticale du M\u00f4le ; 10\u00e8me sur le KM Vertical du Mont-Blanc ; 10\u00e8me sur le TPS Vertical K2 Villaroger &#8211; Les Arcs ; 7\u00e8me sur la Verticale du Chaberton.<br \/>\n&#8211; 2019 : 2\u00e8me sur la Mont\u00e9e S\u00e8che de l\u2019Ultra Mont\u00e9e Thollon-les-M\u00e9mises.<br \/>\n&#8211; La Thononaise <strong>Aline Viard<\/strong>, 28 ans, 2\u00e8me \u00e0 8\u201932 d\u2019H\u00e9l\u00e8ne. Une belle prestation pour cette ancienne gloire du hockey sur glace. Un sport que cette Morzinoise de souche a \u00e9trenn\u00e9 d\u00e8s l\u2019\u00e2ge de 6 ans avant d\u2019int\u00e9grer en 2005 l\u2019\u00e9quipe de France dont elle est devenue aujourd\u2019hui l\u2019une des deux kin\u00e9s.<br \/>\n&#8211; La Bernolande <strong>Manon Baverel<\/strong>, 33 ans, 3\u00e8me \u00e0 10\u201913 d\u2019H\u00e9l\u00e8ne. Victorieuse en 2012 en 1h11\u201919 (contre 1h13\u201954 cette ann\u00e9e), la n\u00e9o-soci\u00e9taire de l\u2019Athl\u00e9tic Club Evian trouve \u00e9galement son bonheur dans les aventures au long cours o\u00f9 elle est tr\u00e8s loin de jouer les faire-valoir. N\u2019a-t\u2019elle pas enlev\u00e9 l\u2019an pass\u00e9 le 67 km des Allobroges puis le 84 km des Cr\u00eates du Chablais ?<\/p>\n<p><strong>F.V.<\/strong><\/p>\n<p>(1) Avec un d\u00e9part donn\u00e9 entre l\u2019\u00e9glise Saint-Ours et la mairie de Bernex, un peu plus bas que le point cot\u00e9 945 m sur la carte IGN Top 25, et une arriv\u00e9e jug\u00e9e \u00e0 2114 m d\u2019altitude au refuge de la Dent d\u2019Oche, le d\u00e9nivel\u00e9 positif de cette course de montagne doit l\u00e9g\u00e8rement d\u00e9passer les 1170 m.<br \/>\n(2) Les r\u00e9sultats obtenus par les femmes entre 1986 et 2001 sur la Course de la Dent d\u2019Oche sont introuvables. Raison pour laquelle le conditionnel est de mise lorsqu\u2019on parle des quatre meilleurs chronos f\u00e9minins<strong>\u00a0<\/strong>dans le palmar\u00e8s de cette comp\u00e8te.<br \/>\n(3) Apr\u00e8s la Course de la Dent d\u2019Oche,<strong> H\u00e9l\u00e8ne Darragon<\/strong> s\u2019est align\u00e9e sur les deux \u00e9preuves suivantes :<br \/>\n&#8211; La Pierra Menta Et\u00e9, du 5 au 7 juillet \u00e0 Ar\u00eaches-Beaufort, o\u00f9 elle se classe 18\u00e8me parmi les \u00e9quipes f\u00e9minines (221\u00e8me au scratch) en compagnie de <strong>Karen Sache<\/strong>. 18h16\u201912 est leur temps cumul\u00e9 sur les trois journ\u00e9es programm\u00e9es.<br \/>\n&#8211; L\u2019Assaut des M\u00e9mises, le 14 juillet \u00e0 Thollon-les-M\u00e9mises, qu\u2019elle d\u00e9croche (16\u00e8me au scratch) en 54\u201926. Elle pulv\u00e9rise ainsi de 3\u201930 le record du parcours emprunt\u00e9 depuis 1998, le deuxi\u00e8me dans l\u2019histoire de cette mont\u00e9e s\u00e8che apparue en 1990. Par la m\u00eame occasion, elle progresse de 5\u201905 par rapport \u00e0 son chrono r\u00e9alis\u00e9 en 2017, ce qui est d\u2019autant plus remarquable que la distance ne d\u00e9passe pas les 9 km (pour un diff\u00e9rentiel de 700 m). In fine, un exploit comparable \u00e0 celui de la Dent d\u2019Oche.<br \/>\n(4) \u00ab La Bec \u00bb ou encore \u00ab Bec \u00e0 d\u2019Oche \u00bb sont les deux noms attribu\u00e9s par les habitants de Bernex \u00e0 la dent d\u2019Oche. Bec \u00e9mane du patois becca qui signifie pointe ou sommet pointu.<br \/>\n(5) Avant 2019, <strong>Romain Bouther <\/strong>avait accouru \u00e0 cinq reprises \u00e0 la Course de la Dent d\u2019Oche, r\u00e9coltant les r\u00e9sultats suivants :<br \/>\n&#8211; 2005 : 4\u00e8me en 56\u201906.<br \/>\n&#8211; 2010 : 3\u00e8me en 56\u201929.<br \/>\n&#8211; 2011 : 2\u00e8me en 56\u201900.<br \/>\n&#8211; 2012 : 2\u00e8me en 55\u201937.<br \/>\n&#8211; 2013 : 6\u00e8me en 57\u201902.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nL\u2019OPINIATRETE DE GILLES FARINA :<\/strong><\/p>\n<p>Apr\u00e8s cinq mois de gal\u00e8re puis seulement dix s\u00e9ances d\u2019entra\u00eenement, c\u2019\u00e9tait jour de reprise pour l\u2019\u00e9g\u00e9rie du Faucigny Athl\u00e9tic Club de Cluses.<br \/>\nEtant donn\u00e9 les circonstances, on s\u2019attendait donc \u00e0 une prestation moyenne de<strong> Gilles Farina<\/strong>, devenu entre-temps sexag\u00e9naire. Il n\u2019en fut rien, le vice-champion de France V2 de marathon 2010 s\u2019octroyant au classement g\u00e9n\u00e9ral une magnifique 9\u00e8me place en 1h01\u201923. Cerise sur le g\u00e2teau, il bonifiait son chrono de 17\u2019\u2019 par rapport \u00e0 sa premi\u00e8re exp\u00e9rience \u00e0 la Dent d\u2019Oche, remontant \u00e0 la saison pass\u00e9e et sold\u00e9e par une 22\u00e8me position au scratch, r\u00e9colt\u00e9e il est vrai dans un contexte plus relev\u00e9.<br \/>\nLaur\u00e9at chez les masters 3, le Marignerod avait en outre le bonheur de voir monter sur la 2\u00e8me marche son fr\u00e8re <strong>Denis<\/strong>, 61 ans, arriv\u00e9 4\u2019 apr\u00e8s lui. Mais quelle fratrie !<br \/>\nGilles revient pour nous sur sa longue blessure qui illustre, on ne peut mieux, toute sa pers\u00e9v\u00e9rance pour revenir au premier plan quand tant d\u2019autres auraient l\u00e2ch\u00e9 prise&#8230;<\/p>\n<p><strong>F.V.<\/strong><\/p>\n<p>Ca y est, je suis redevenu enfin un coureur ! Il \u00e9tait temps ! Petit retour en arri\u00e8re \u00e0 l\u2019occasion des championnats d\u00e9partementaux de cross, concourus le 13 janvier dernier \u00e0 La Motte-Servolex. Cette premi\u00e8re sortie est h\u00e9las marqu\u00e9e par une douleur au mollet qui persistera jusqu\u2019au 10 mars, co\u00efncidant avec les France \u00e0 Vittel (1).<br \/>\nEnsuite, la souffrance est telle qu\u2019il m\u2019est impossible de courir. Ce qui est dingue, c\u2019est que les radios et autres IRM ne r\u00e9v\u00e8lent rien, notamment aucune d\u00e9chirure. Sans doute, est-ce d\u00fb \u00e0 un muscle fatigu\u00e9 qui s\u2019est mal soign\u00e9 parce que tout bonnement je ne m\u2019arr\u00eate jamais !<br \/>\nDu coup, kin\u00e9 et huit semaines sans cavaler avant de reprendre tranquillou par de brefs footings n\u2019exc\u00e9dant pas les 5 km maximum, sinon la douleur revenait au triple galop, et ce pendant six longues semaines&#8230; La mort dans l\u2019\u00e2me, je dois renoncer au Marathon du Mont-Blanc mais surtout aux France de montagne \u00e0 Saint-Gervais, programm\u00e9s respectivement les 30 et 9 juin. Mais bon, je me rattraperai l\u2019an prochain ! Eh oui, il faut toujours voir le bon c\u00f4t\u00e9 des choses !<br \/>\nCe n\u2019est qu\u2019\u00e0 compter du 18 juin que je renoue avec des s\u00e9ances d\u2019entra\u00eenement dignes de ce nom. Ce qui m\u2019am\u00e8ne \u00e0 prendre le d\u00e9part de\u00a0la Dent d\u2019Oche avant d\u2019encha\u00eener le 7 juillet par la Grimp\u00e9e du M\u00f4le, le 11 par le Relais Nocturne de Meg\u00e8ve, enfin le 14 par l\u2019Assaut des M\u00e9mises (2).<br \/>\nEt pas question de s\u2019arr\u00eater en si bon chemin, le mois de juillet se poursuivant, le 21 par la Mont\u00e9e du Nid d\u2019Aigle, le 28 par la Mont\u00e9e des Pav\u00e9s Taninges Praz-de-Lys, sans oublier, pour se faire un peu de jus, les relais nocturnes, disput\u00e9s les jeudis soirs, et qui d\u00e9borderont en ao\u00fbt. Ma foi, un menu bien copieux et bien sympa !<\/p>\n<p><strong>Gilles Farina<\/strong><\/p>\n<p>(1) Les r\u00e9sultats 2019 de <strong>Gilles Farina<\/strong> en cross-country ont \u00e9t\u00e9 les suivants :<br \/>\n&#8211; Les Championnats D\u00e9partementaux de Cross-Country V\u00e9t\u00e9rans Hommes, le 13 janvier \u00e0 La Motte-Servolex : 34\u00e8me en 34\u201910.<br \/>\n&#8211; Les Championnats de la Zone Alpes de Cross-Country V\u00e9t\u00e9rans Hommes, le 27 janvier \u00e0 Echirolles : 60\u00e8me en 37\u201937.<br \/>\n&#8211; Les Championnats de France de Cross-Country V2-V3-V4-V5, le 10 mars \u00e0 Vittel : 65\u00e8me en 32\u201932.<br \/>\n(2) Les r\u00e9sultats 2019 de <strong>Gilles Farina<\/strong> apr\u00e8s la Course de la Dent d\u2019Oche ont \u00e9t\u00e9 les suivants :<br \/>\n&#8211; La Grimp\u00e9e du M\u00f4le, le 7 juillet \u00e0 Marignier : 3\u00e8me au scratch (1er V3) en 1h01\u201922.<br \/>\n&#8211; Le Relais Nocturne de Meg\u00e8ve, le 11 juillet : 18\u00e8me par \u00e9quipes avec son entra\u00eeneur <strong>Daniel Vanel<\/strong>.<br \/>\n&#8211; L\u2019Assaut des M\u00e9mises, le 14 juillet \u00e0 Thollon-les-M\u00e9mises : 12\u00e8me au scratch (1er V3) en 53\u201918.<span style=\"color: #ffffff;\"><span style=\"color: #ffffff;\"><br \/>\n<\/span><span style=\"color: #ffffff;\">.<br \/>\n<\/span>.<\/span><strong><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nARTICLES DU QUOTIDIEN <em>LE DAUPHINE LIBERE<\/em>\u00a0:<br \/>\n<\/strong><span style=\"font-size: 0.95em;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<\/span>Ci-dessous, vous trouverez le compte rendu figurant en page sports des \u00e9ditions de la Haute-Savoie, en date du lundi 1er juillet 2019. Son auteur est le correspondant <strong>Yves Theveniau<\/strong>.<\/p>\n<p>\n\t\t<div class=\"wppdfemb-frame-container-1\" style=\"-webkit-overflow-scrolling:auto;\">\n\t\t\t<iframe class=\"pdfembed-iframe nonfullscreen wppdf-emb-iframe-1\"\n\t\t\t\tsrc=\"https:\/\/www.courzyvite.run\/blog\/?pdfemb-data=eyJ1cmwiOiJodHRwczpcL1wvd3d3LmNvdXJ6eXZpdGUucnVuXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wN1wvUERGLVBhZ2UtMzktZWRpdGlvbi1kZS10aG9ub24tbGVzLWJhaW5zLWV0LWxlLWNoYWJsYWlzLTIwMTkwNzAxLnBkZiIsImluZGV4IjoxLCJwZGZJRCI6Mzk0NzJ9\"\n\t\t\t\t\t\t\t\tdata-pdf-id=\"39472\"\n\t\t\t\tdata-pdf-index=\"1\"\n\t\t\t\tstyle=\"border:none;width:100%;max-width:100%;height:100vh;\"\n\t\t\t\tscrolling=\"yes\">\n\t\t\t<\/iframe>\n\t\t<\/div>\n\n\t\t<br \/>\n<span style=\"font-size: 0.95em;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<\/span>Ci-dessous, vous trouverez le compte rendu figurant en page locale de l\u2019\u00e9dition de Thonon-les-Bains et Le Chablais, en date du mercredi 3 juillet 2019. Son auteur est le correspondant <strong>L.G.<\/strong><\/p>\n<p>\n\t\t<div class=\"wppdfemb-frame-container-2\" style=\"-webkit-overflow-scrolling:auto;\">\n\t\t\t<iframe class=\"pdfembed-iframe nonfullscreen wppdf-emb-iframe-2\"\n\t\t\t\tsrc=\"https:\/\/www.courzyvite.run\/blog\/?pdfemb-data=eyJ1cmwiOiJodHRwczpcL1wvd3d3LmNvdXJ6eXZpdGUucnVuXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE5XC8wN1wvUERGLVBhZ2UtMTQtZWRpdGlvbi1kZS10aG9ub24tbGVzLWJhaW5zLWV0LWxlLWNoYWJsYWlzLTIwMTkwNzAzLnBkZiIsImluZGV4IjoyLCJwZGZJRCI6Mzk0NzN9\"\n\t\t\t\t\t\t\t\tdata-pdf-id=\"39473\"\n\t\t\t\tdata-pdf-index=\"2\"\n\t\t\t\tstyle=\"border:none;width:100%;max-width:100%;height:100vh;\"\n\t\t\t\tscrolling=\"yes\">\n\t\t\t<\/iframe>\n\t\t<\/div>\n\n\t\t<br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #ffffff;\">.<br \/>\n<\/span>.<\/span><br \/>\n<strong>RESULTATS PARTIELS :<\/strong><\/p>\n<p><strong>Scratch<\/strong>\u00a0<strong>(109 partants, 107 class\u00e9s, 2 abandons) :<\/strong><br \/>\n\u2013 1er (1er senior)\u00a0:<strong> Romain Bouther<\/strong> (Evian V\u00e9lo) en 56\u201936.<br \/>\n\u2013 2\u00e8me (1er espoir) : <strong>Eddy Bouvet<\/strong> (Club Alpin Fran\u00e7ais Haut-Chablais Morzine) en 57\u201922.<br \/>\n\u2013 3\u00e8me (1er V1) :<strong> Lionel Chatelard<\/strong> (Chamonix-Mont-Blanc Marathon) en 58\u201910.<br \/>\n\u2013 4\u00e8me (2\u00e8me espoir) : <strong>Julien Bernaz<\/strong> (Lou Tavan) en 59\u201904.<br \/>\n\u2013 5\u00e8me (3\u00e8me espoir) :<strong> Maxime Giorgiani<\/strong><b>\u00a0<\/b>(Evian Off Course) en 59\u201921.<br \/>\n\u2013 6\u00e8me (1er V1) : <strong>Benjamin Bechet<\/strong> (Evian-les-Bains) en 59\u201924.<br \/>\n\u2013 7\u00e8me (2\u00e8me senior) : <strong>Jean-Charles Baud-Geniaux<\/strong> (Team BG\u201974) en 59\u201943.<br \/>\n\u2013 8\u00e8me (3\u00e8me senior) : <strong>Anthony Dejour<\/strong> (Club Athl\u00e9tique d\u2019Ambilly) en 1h01\u201908.<br \/>\n\u2013 9\u00e8me (1er V3) :<strong> Gilles Farina<\/strong> (Faucigny Athl\u00e9tic Club) en 1h01\u201923.<br \/>\n\u2013 10\u00e8me (4\u00e8me senior) :<b> Micka\u00ebl Voisin <\/b>(Athl\u00e9tic Club Evian) en 1h01\u201926.<br \/>\n\u2013 34\u00e8me (1er V2) :<b> Christian Lamarque d\u2019Arrouzat <\/b>(Esp\u00e9rance Favergienne) en 1h12\u201919.<br \/>\n\u2013 54\u00e8me (1er junior) : <strong>Mathieu Neuraz<\/strong> (Allinges) en 1h19\u201932.<br \/>\n\u2013 61\u00e8me (1er V4) : <strong>R\u00e9gis Jordan<\/strong><b>\u00a0<\/b>(Margencel) en 1h21\u201957.<\/p>\n<p><strong>Femmes (15 partantes, 15 class\u00e9es) :<\/strong><br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 16\u00e8me au scratch) :<strong> H\u00e9l\u00e8ne<\/strong> <strong>Darragon<\/strong> (Team Terre de Running Anthy-sur-L\u00e9man, Team Instinct-France et Evian Off Course) en 1h03\u201940.<br \/>\n\u2013 2\u00e8me (2\u00e8me senior, 35\u00e8me au scratch) : <strong>Aline Viard<\/strong> (Thonon-les-Bains) en 1h12\u201913.<br \/>\n\u2013 3\u00e8me (3\u00e8me senior, 42\u00e8me au scratch) : <strong>Manon Baverel<\/strong> (Athl\u00e9tic Club Evian) en 1h13\u201954.<br \/>\n\u2013 4\u00e8me (4\u00e8me senior, 48\u00e8me au scratch) : <strong>Virginie Pailloux<\/strong> (Evian Off Course) en 1h15\u201952.<br \/>\n\u2013 5\u00e8me (5\u00e8me senior, 58\u00e8me au scratch) : <strong>Laurie Barralon<\/strong> (Chamonix-Mont-Blanc Marathon) en 1h19\u201903.<br \/>\n\u2013 6\u00e8me (1\u00e8re junior, 67\u00e8me au scratch) :<strong> Estelle Gillet <\/strong>(Saint-Paul-en-Chablais) en 1h21\u201959.<br \/>\n\u2013 7\u00e8me (6\u00e8me senior, 68\u00e8me au scratch) : <strong>Joana Escobet<\/strong> <strong>Selga<\/strong> (Bernex, gardienne du refuge de la Dent d\u2019Oche o\u00f9 est jug\u00e9e l\u2019arriv\u00e9e) en 1h22\u201905.<br \/>\n\u2013 8\u00e8me (7\u00e8me senior, 83\u00e8me au scratch) : <strong>Coralie Antoine <\/strong>(Bernex) en 1h27\u201930.<br \/>\n\u2013 9\u00e8me (1\u00e8re V2, 85\u00e8me au scratch) : <strong>Gis\u00e8le Fournival<\/strong> (Club Athl\u00e9tique d\u2019Ambilly) en 1h28\u201941.<br \/>\n\u2013 10\u00e8me (8\u00e8me senior, 87\u00e8me au scratch) : <strong>Carole Gallay<\/strong> (Maison M\u00e9dicale de Publier) en 1h29\u201930.<span style=\"font-size: 0.95em;\"><br \/>\n<\/span><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nRESULTATS COMPLETS :<\/strong><\/p>\n<p>Ils figurent sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/19Resultats\/DentDOche2019.pdf\">https:\/\/www.courzyvite.run\/19Resultats\/DentDOche2019.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPALMARES DEPUIS 1986 :<\/strong><\/p>\n<p><strong>1986 :<br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Jean-Michel Lenta <\/strong>(Athl\u00e9tic Club Evian) en 53\u201904.<\/p>\n<p><strong>1987 :<\/strong><br \/>\n&#8211; 1er (1er senior) : <strong>Thierry Gazan<\/strong> (Hab\u00e8re-Poche) en 54\u201923.<\/p>\n<p><strong>1988 :<\/strong><br \/>\n&#8211; 1er (1er senior) : <strong>Jean-Michel Lenta<\/strong> (Athl\u00e9tic Club Evian) en 51\u201922.<\/p>\n<p><strong>1989 :<\/strong><br \/>\n&#8211; 1er (1er V1) :<strong> Jean-Fran\u00e7ois Seigneur<\/strong> (Meg\u00e8ve) en 53\u201926.<\/p>\n<p><strong>1990 :<\/strong><br \/>\n&#8211; 1er :<strong> Patrick Niveleau<\/strong> (Annecy) en 53\u201913.<\/p>\n<p><strong>1991 :<\/strong><br \/>\n&#8211; 1er (1er senior) : le Suisse <strong>Pascal Fortis<\/strong> (Gen\u00e8ve) en 52\u201921.<\/p>\n<p><strong>1992 :<\/strong><br \/>\n&#8211; 1er (1er senior) :<strong> Ren\u00e9 Amoudruz<\/strong> (Office National des For\u00eats et Athl\u00e9tic Club Evian) en 51\u201916.<\/p>\n<p><strong>1993 :<\/strong><br \/>\n&#8211; 1er (1er senior) : <strong>Patrick Cretin-Maitenaz<\/strong> (Bois-d\u2019Amont) en 52\u201908.<\/p>\n<p><strong>1994 :<\/strong><br \/>\n&#8211; 1er (1er senior) :<strong> Patrick Cretin-Maitenaz<\/strong> (Bois-d\u2019Amont) en 50\u201900.<\/p>\n<p><strong>1995 :<\/strong><br \/>\n&#8211; 1er (1er senior) :<strong> Ren\u00e9 Amoudruz<\/strong> (Office National des For\u00eats et Athl\u00e9tic Club Evian) en 50\u201940.<\/p>\n<p><strong>1996 :<\/strong><br \/>\n&#8211; 1er (1er senior) :<strong> Ren\u00e9 Amoudruz<\/strong> (Team Socquet Sports, Office National des For\u00eats et Athl\u00e9tic Club Evian) en 51\u201950.<\/p>\n<p><strong>1997 :<\/strong><br \/>\n&#8211; 1er (1er senior) :<strong> Michel Dizin<\/strong> (Pays Rochois Athl\u00e9tic) en 53\u201943.<\/p>\n<p><strong>1998 :<\/strong><br \/>\n&#8211; 1er (1er senior) : <strong>Michel Dizin<\/strong> (Pays Rochois Athl\u00e9tic) en 50\u201902.<\/p>\n<p><strong>1999 :<br \/>\n<\/strong>&#8211; 1er (1er senior) :<strong> Michel Dizin<\/strong> (Pays Rochois Athl\u00e9tic) en 50\u201942.<\/p>\n<p><strong>2000 :<\/strong><br \/>\n&#8211; 1er (1er V1) :<strong> Michel Dizin<\/strong> (Pays Rochois Athl\u00e9tic) en 48\u201933.<br \/>\nParcours r\u00e9duit, l\u2019arriv\u00e9e ayant lieu au pied de la chemin\u00e9e, celle-ci \u00e9tant gel\u00e9e, et donc impraticable.<\/p>\n<p><strong>2001 :<\/strong><br \/>\n&#8211; 1er (1er senior) : le Suisse <strong>Alexis Gex-Fabry<\/strong> (Club d\u2019Athl\u00e9tisme du Bas-Valais Martigny) en 49\u201950.<\/p>\n<p><strong>2002 <\/strong>(114 inscrits, 114 class\u00e9s) :\u00a0<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Thierry Icart<\/strong> (Cross Sport Serre Chevalier, section du Gap Hautes-Alpes Athl\u00e9tisme) en 49\u201935.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 33\u00e8me au scratch) : la Suissesse <strong>Catherine Mabillard<\/strong> (Swiss Team) en 1h03\u201938.<\/p>\n<p><strong>2003 <\/strong>(111 inscrits, 111 class\u00e9s) :<br \/>\n&#8211;\u00a01er (1er senior) : le Suisse <strong>Fr\u00e9dy Schmid<\/strong> (Berne) en 51\u201921.<br \/>\n&#8211; 1\u00e8re (1\u00e8re V1, 73\u00e8me au scratch) :<strong> Annie Benier<\/strong> (Issoire) en 1h15\u201913.<\/p>\n<p><strong>27 juin 2004 (132 inscrits, 132 class\u00e9s, record de participation) :<\/strong><br \/>\n&#8211; 1er (1er senior) : le Suisse <strong>Alexis Gex-Fabry<\/strong> (Club d\u2019Athl\u00e9tisme du Bas-Valais Martigny) en <strong>48\u201946, record scratch du parcours emprunt\u00e9 depuis 1986 (except\u00e9 en 2000)<\/strong>.<br \/>\n&#8211; 1\u00e8re (1\u00e8re V1, 48\u00e8me au scratch) :<strong> Cathy Jonnier<\/strong> (Saint-Claude) en 1h07\u201932.<\/p>\n<p><strong>26 juin 2005 <\/strong>(123 inscrits, 120 class\u00e9s, 3 abandons) :<br \/>\n&#8211; 1er (1er senior) :<strong> Florian Jacquier<\/strong> (Saint-Paul-en-Chablais) en 54\u201925.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 15\u00e8me au scratch) : l\u2019Anglaise <strong>Victoria Wilkinson<\/strong> (Rugby) en<strong> 1h02\u201913, record f\u00e9minin du parcours emprunt\u00e9 depuis 1986 (except\u00e9 en 2000)<\/strong>.<\/p>\n<p><strong>25 juin 2006 <\/strong>(103 inscrits, 103 class\u00e9s) :<br \/>\n&#8211; 1er (1er senior) :<strong> Alexandre Aubert<\/strong> (Saint-Gervais-les-Bains) en 54\u201922.<br \/>\n&#8211; 1\u00e8re (1\u00e8re espoir, 32\u00e8me au scratch) :<strong> Aur\u00e9lie Jacquier<\/strong> (La Foul\u00e9e d\u2019Annemasse) en 1h06\u201958.<\/p>\n<p><strong>24 juin 2007 <\/strong>(126 inscrits, 125 class\u00e9s, 1 abandon) :<br \/>\n&#8211; 1er (1er senior) :<strong> Guillaume Fontaine<\/strong> (Team Socquet Sports et La Foul\u00e9e d\u2019Annemasse) en 50\u201941.<br \/>\n&#8211; 1\u00e8re (1\u00e8re espoir, 31\u00e8me au scratch) : <strong>Aur\u00e9lie Jacquier<\/strong> (La Foul\u00e9e d\u2019Annemasse) en 1h04\u201922.<\/p>\n<p><strong>29 juin 2008 <\/strong>(91 inscrits, 91 class\u00e9s).<br \/>\n&#8211; 1er (1er senior) : le Suisse <strong>Fr\u00e9dy Schmid<\/strong> (TV L\u00e4nggasse Bern) en 54\u201902.<br \/>\n&#8211; 1\u00e8re (1\u00e8re espoir, 27\u00e8me au scratch) : <strong>Aur\u00e9lie Jacquier<\/strong> (La Foul\u00e9e d\u2019Annemasse) en 1h10\u201923.<\/p>\n<p><strong>28 juin 2009 :<\/strong><br \/>\nEdition annul\u00e9e par l\u2019Office de Tourisme de Bernex, faute de b\u00e9n\u00e9voles pour assurer la s\u00e9curit\u00e9 dans la chemin\u00e9e.<\/p>\n<p><strong>27 juin 2010 <\/strong>(89 inscrits dont 8 femmes, 89 class\u00e9s dont 8 femmes) :<strong><br \/>\n<\/strong>&#8211; 1er (1er V1) : <strong>J\u00e9r\u00f4me Bosch<\/strong> (Team Technicien du Sport Seynod et Corsica Sport Mezzavia) en 52\u201936.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 46\u00e8me au scratch) : <strong>Aur\u00e9lie Jacquier<\/strong> (La Foul\u00e9e d\u2019Annemasse) en 1h14\u201927.<\/p>\n<p><strong>26 juin 2011 <\/strong>(97 inscrits dont 6 femmes, 97 class\u00e9s dont 6 femmes) :<strong><br \/>\n<\/strong>&#8211; 1er (1er V2) : <strong>Ren\u00e9 Amoudruz<\/strong> (Team Socquet Sports et La Foul\u00e9e d\u2019Annemasse) en 55\u201943.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 52\u00e8me au scratch) : <strong>Karine Soto<\/strong> (Evian Off Course) en 1h15\u201928.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/11Resultats\/Dentdoche2011.pdf\">https:\/\/www.courzyvite.run\/11Resultats\/Dentdoche2011.pdf\u00a0<\/a><\/p>\n<p><strong>24 juin 2012 <\/strong>(127 inscrits dont 7 femmes, 124 class\u00e9s dont 7 femmes, 3 abandons) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Damien Piquemal<\/strong> (Team Scott Odlo Les Saisies et Esp\u00e9rance Favergienne) en 52\u201932.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 43\u00e8me au scratch) : <strong>Manon Baverel<\/strong> (Les Foul\u00e9es Chablaisiennes) en 1h11\u201919.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/12Resultats\/DentDoche2012.pdf\">https:\/\/www.courzyvite.run\/12Resultats\/DentDoche2012.pdf<\/a><\/p>\n<p><strong>23 juin 2013 <\/strong>(108 inscrits dont 12 femmes, 107 class\u00e9s dont 12 femmes, 1 abandon) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Alain Gillet<\/strong> (Team Scott Odlo Les Saisies et Evian Off Course) en 50\u201945.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 31\u00e8me au scratch) : la Suissesse <strong>Jennifer Fiechter<\/strong> (Leysin) en 1h04\u201928.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/13Resultats\/Dent-dOche2013.pdf\">https:\/\/www.courzyvite.run\/13Resultats\/Dent-dOche2013.pdf<\/a><\/p>\n<p><strong>29 juin 2014 :<\/strong><br \/>\nEdition annul\u00e9e par la Mairie de Bernex en raison d\u2019une m\u00e9t\u00e9o franchement mauvaise (pluie, vent et froid).<\/p>\n<p><strong>28 juin 2015 <\/strong>(95 inscrits dont 10 femmes, 94 class\u00e9s dont 10 femmes, 1 DNF) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Vincent Deage<\/strong> (Le Lyaud) en 56\u201911.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 22\u00e8me au scratch) : <strong>C\u00e9lia Chiron<\/strong> (Team Optisport Uglow et Coureurs du Monde en Is\u00e8re) en 1h03\u201922.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/15Resultats\/DentDOche2015.pdf\">https:\/\/www.courzyvite.run\/15Resultats\/DentDOche2015.pdf<\/a><\/p>\n<p><strong>26 juin 2016 <\/strong>(87 inscrits dont 8 femmes, 86 class\u00e9s dont 8 femmes, 1 abandon) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) : <strong>Alain Gillet<\/strong> (Evian Off Course) en 52\u201902.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 29\u00e8me au scratch) : la N\u00e9palaise <strong>Manikala Rai<\/strong> (Hoka Team Trail France et Club Athl\u00e9tique du Bassin Bellegardien) en 1h07\u201958.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/16Resultats\/DentdOche2016.pdf\">https:\/\/www.courzyvite.run\/16Resultats\/DentdOche2016.pdf<\/a><\/p>\n<p><strong>25 juin 2017 <\/strong>(116 inscrits dont 10 femmes, 115 class\u00e9s dont 10 femmes, 1 abandon) :<strong><br \/>\n<\/strong>&#8211; 1er (1er espoir) : le Belge <strong>Maximilien Drion du Chapois<\/strong> (BCVS Mount Asics Team) en 53\u201928.<br \/>\n&#8211; 1\u00e8re (1\u00e8re V2, 55\u00e8me au scratch) : <strong>Christiane Lacombe<\/strong> (Athl\u00e9 Saint-Julien 74) en 1h12\u201949.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/17Resultats\/CourseDentDOche2017.pdf\">https:\/\/www.courzyvite.run\/17Resultats\/CourseDentDOche2017.pdf<\/a><\/p>\n<p><strong>24 juin 2018 <\/strong>(128 inscrits dont 15 femmes, 128 class\u00e9s dont 15 femmes) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) :<strong> Alexis Sevennec<\/strong> (Team Scott France) en 50\u201902.<br \/>\n&#8211; 1\u00e8re (1\u00e8re espoir, 34\u00e8me au scratch) : <strong>Manon Gaydon<\/strong> (Club Alpin Fran\u00e7ais Haut-Chablais Morzine) en 1h04\u201920.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/18Resultats\/DentDOche2018.pdf\">https:\/\/www.courzyvite.run\/18Resultats\/DentDOche2018.pdf<\/a><\/p>\n<p><strong>30 juin 2019 <\/strong>(109 inscrits dont 15 femmes, 107 class\u00e9s dont 15 femmes, 2 abandons) :<strong><br \/>\n<\/strong>&#8211; 1er (1er senior) :<strong> Romain Bouther<\/strong> (Evian V\u00e9lo) en 56\u201936.<br \/>\n&#8211; 1\u00e8re (1\u00e8re senior, 16\u00e8me au scratch) : <strong>H\u00e9l\u00e8ne Darragon<\/strong> (Team Terre de Running Anthy-sur-L\u00e9man, Team Instinct-France et Evian Off Course) en 1h03\u201940.<br \/>\n&#8211; R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"https:\/\/www.courzyvite.run\/19Resultats\/DentDOche2019.pdf\">https:\/\/www.courzyvite.run\/19Resultats\/DentDOche2019.pdf<\/a><\/p>\n<p>Avant 2002, on citera les succ\u00e8s des femmes suivantes :<br \/>\n&#8211; <strong>Martine Delplanques<\/strong> (Chamonix-Mont-Blanc).<br \/>\n&#8211;<strong> Brigitte Eustache<\/strong> (Chamonix-Mont-Blanc).<br \/>\n&#8211; La Suissesse <strong>Fran\u00e7oise Gibini<\/strong> (Gen\u00e8ve).<br \/>\n&#8211; <strong>Dominique Robert<\/strong> (Meg\u00e8ve), d\u00e9c\u00e9d\u00e9e en juin 2003 lors du Raid Gauloises.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPHOTOS :<\/strong><\/p>\n<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39551 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65396081_2747959678609277_4165594720606617600_n.jpg?resize=860%2C645&#038;ssl=1\" alt=\"\" width=\"860\" height=\"645\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65396081_2747959678609277_4165594720606617600_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65396081_2747959678609277_4165594720606617600_n.jpg?resize=420%2C315&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65396081_2747959678609277_4165594720606617600_n.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/strong>33\u00e8me \u00e9dition de la Course de la Dent d\u2019Oche, 30 juin 2019.<br \/>\nArriv\u00e9e au refuge de la Dent d\u2019Oche, \u00e0 2114 m d\u2019altitude. Son \u00e9dification remonte \u00e0 1913 avant d\u2019\u00eatre inaugur\u00e9 l\u2019ann\u00e9e suivante.<br \/>\nAu premier plan : <b>Micka\u00ebl Voisin <\/b>(Athl\u00e9tic Club Evian), 10\u00e8me (4\u00e8me senior) en 1h01\u201926.<br \/>\nClich\u00e9 de <strong>Joana Escobet<\/strong> <strong>Selga<\/strong>.<br \/>\nGardienne du refuge de la Dent d\u2019Oche, celle-ci s\u2019est class\u00e9e 7\u00e8me f\u00e9minine (6\u00e8me senior, 68\u00e8me au scratch) en 1h22\u201905.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39552 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65423896_2747959528609292_5948293602017804288_n.jpg?resize=860%2C412&#038;ssl=1\" alt=\"\" width=\"860\" height=\"412\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65423896_2747959528609292_5948293602017804288_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65423896_2747959528609292_5948293602017804288_n.jpg?resize=420%2C201&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65423896_2747959528609292_5948293602017804288_n.jpg?resize=768%2C368&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>33\u00e8me \u00e9dition de la Course de la Dent d\u2019Oche, 30 juin 2019.<br \/>\nArriv\u00e9e au refuge de la Dent d\u2019Oche, \u00e0 2114 m d\u2019altitude.<br \/>\nClich\u00e9 de <strong>Joana Escobet<\/strong> <strong>Selga<\/strong>, gardienne du refuge de la Dent d\u2019Oche.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39562 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/66180354_2747959425275969_6557911789609156608_n-e1563288225542.jpg?resize=525%2C700&#038;ssl=1\" alt=\"\" width=\"525\" height=\"700\" \/>33\u00e8me \u00e9dition de la Course de la Dent d\u2019Oche, 30 juin 2019.<br \/>\nArriv\u00e9e au refuge de la Dent d\u2019Oche, \u00e0 2114 m d\u2019altitude.<br \/>\n&#8211; Dossard 70 : <strong>Rapha\u00ebl Piettre <\/strong>(Ski Club de la Dent d\u2019Oche Bernex), 41\u00e8me (19\u00e8me senior) en 1h13\u201924.<br \/>\n&#8211; Au deuxi\u00e8me plan : \u00ab La Bec \u00bb, culminant \u00e0 2221 m d\u2019altitude, que surmonte une croix en fer forg\u00e9, \u00e9rig\u00e9e le 17 octobre 1981 apr\u00e8s avoir \u00e9t\u00e9 port\u00e9e depuis la F\u00e9tiu\u00e8re par <strong>Pierre Mercier<\/strong>, un des deux pr\u00e9curseurs en 1986 de la Course de la Dent d\u2019Oche en compagnie de <strong>Pierre Ozenda<\/strong>.<br \/>\nClich\u00e9 de <strong>Joana Escobet Selga<\/strong>, gardienne du refuge de la Dent d\u2019Oche.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39542 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/66069535_354863451865266_3209955129922945024_n-e1563221750972.jpg?resize=467%2C700&#038;ssl=1\" alt=\"\" width=\"467\" height=\"700\" \/>33\u00e8me \u00e9dition de la Course de la Dent d\u2019Oche, 30 juin 2019.<br \/>\nRemise des prix \u00e0 Bernex.<br \/>\n<strong>Romain Bouther <\/strong>(Evian V\u00e9lo), 1er (1er senior) en 56\u201936.<strong><br \/>\n<\/strong>Clich\u00e9 d\u2019<strong>Yves Theveniau<\/strong> (quotidien <em>Le Dauphin\u00e9 lib\u00e9r\u00e9<\/em>).<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39545 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65595847_1342953465853373_7664988422456475648_n-1.jpg?resize=860%2C860&#038;ssl=1\" alt=\"\" width=\"860\" height=\"860\" \/>33\u00e8me \u00e9dition de la Course de la Dent d\u2019Oche, 30 juin 2019.<br \/>\nRemise des prix \u00e0 Bernex.<br \/>\nPodium scratch f\u00e9minin.<br \/>\n&#8211; A gauche : <strong>Aline Viard<\/strong> (Thonon-les-Bains), 2\u00e8me en 1h12\u201913.<br \/>\n&#8211; Au centre : <strong>H\u00e9l\u00e8ne Darragon<\/strong> (Team Terre de Running Anthy-sur-L\u00e9man, Team-Instinct France et Evian Off Course), laur\u00e9ate en 1h03\u201940.<br \/>\n&#8211; A droite : <strong>Manon Baverel<\/strong> (Athl\u00e9tic Club Evian), 3\u00e8me en 1h13\u201954.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HELENE DARRAGON AU SOMMET DE SON ART 1h03\u201940 : eh bien voil\u00e0 un chrono qui nous a fait sortir, en ce dimanche 30 juin, de notre torpeur estivale ! En l\u2019occurrence celui r\u00e9alis\u00e9 par la Vacheressande H\u00e9l\u00e8ne Darragon lors de la Course de la Dent d\u2019Oche, concoct\u00e9e depuis 2010 par la Mairie de Bernex, et longue de 7 km pour 1170 m de d\u00e9nivel\u00e9 positif (1). Quatri\u00e8me meilleur temps f\u00e9minin [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":39545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"RESULTATS ET COMPTE RENDU DE LA COURSE DE LA DENT D\u2019OCHE \/ 30-06-19","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[19,36,5],"tags":[11],"class_list":["post-39439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comptes-rendus","category-cr-haute-savoie","category-resultats","tag-news"],"views":4803,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2019\/07\/65595847_1342953465853373_7664988422456475648_n-1-e1563352913193.jpg?fit=960%2C470&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7PZ3h-ag7","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/39439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/comments?post=39439"}],"version-history":[{"count":0,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/39439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media\/39545"}],"wp:attachment":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media?parent=39439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/categories?post=39439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/tags?post=39439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}