{"id":19310,"date":"2018-10-28T07:11:21","date_gmt":"2018-10-28T06:11:21","guid":{"rendered":"https:\/\/www.courzyvite.run\/blog\/?p=19310"},"modified":"2025-01-01T20:43:43","modified_gmt":"2025-01-01T19:43:43","slug":"presentation-du-cross-de-la-semine-28-10-18","status":"publish","type":"post","link":"https:\/\/www.courzyvite.run\/blog\/2018\/10\/28\/presentation-du-cross-de-la-semine-28-10-18\/","title":{"rendered":"PRESENTATION DU CROSS DE LA SEMINE \/ 28-10-18"},"content":{"rendered":"<p><strong>COUP DE POKER A HAUT RISQUE !<\/strong><\/p>\n<p>Pour les vaillantes chevilles ouvri\u00e8res du <strong>Cross de la Semine<\/strong>, on pr\u00e9f\u00e8re d\u00e9sormais le mouvement \u00e0 la scl\u00e9rose. Install\u00e9 \u00e0 Saint-Germain-sur-Rh\u00f4ne en 1991 en provenance du d\u00e9partement de l\u2019Yonne, <strong>Philippe Guichard <\/strong>a d\u2019abord pris, \u00e0 la t\u00eate de l\u2019organisation, la succession de l\u2019embl\u00e9matique\u00a0<strong>Christian Baron<\/strong>, une fois les lampions de l\u2019\u00e9dition 2017 \u00e9teints. Il faut dire que Christian \u00e9tait \u00e0 l\u2019ouvrage depuis 1983 en compagnie d\u2019<strong>Albert Duchene<\/strong>\u00a0lorsque la comp\u00e8te, alors non officielle, co\u00efncidait en juillet avec la vogue. S\u2019il a donc pris incontestablement du recul, Christian continue cependant \u00e0 jouer un r\u00f4le qui n\u2019est pas anodin.<br \/>\nAutre changement, l\u2019av\u00e8nement de la soci\u00e9t\u00e9 L-Chrono qui prend en main les inscriptions en ligne, le chronom\u00e9trage, enfin les classements. Son pr\u00e9sident <strong>Ludovic Galland<\/strong> viendra en personne repr\u00e9senter l\u2019entreprise qu\u2019il a fond\u00e9e en f\u00e9vrier 2014 \u00e0 Th\u00f4nes avant de se fixer \u00e0 Villaz. On n\u2019en saluera pas moins son pr\u00e9d\u00e9cesseur, le L\u00e9azien <strong>Jo\u00ebl Raisin<\/strong>, qui officiait depuis des lustres.<\/p>\n<p><strong>Statu quo avec le cross<\/strong><br \/>\nDans un deuxi\u00e8me temps, la bande \u00e0 Philippe (1) a d\u00e9cid\u00e9 de prendre le taureau par les cornes apr\u00e8s avoir constat\u00e9, l\u2019an pass\u00e9, un reflux sensible de la participation. De 182 en 2015, record pour l\u2019occasion, puis 171 en 2016, le nombre d\u2019inscrits \u00e9tait en effet pass\u00e9 \u00e0 133.<br \/>\nApr\u00e8s avoir l\u00e9g\u00e8rement h\u00e9sit\u00e9, les t\u00eates pensantes de la Semine ont maintenu le sacro-saint 12 km, pr\u00e9cis\u00e9ment 12,3, que pimente un d\u00e9nivel\u00e9 de 309 m. Une comp\u00e8te qui, contrairement \u00e0 son appellation, n\u2019est pas un cross mais une course nature ou encore un trail d\u00e9couverte en reprenant le jargon actuel. Assur\u00e9ment, l\u2019un des anc\u00eatres en la mati\u00e8re en Haute-Savoie ! En effet, le parcours en question comprend des parties asphalt\u00e9es non n\u00e9gligeables, absolument \u00e9trang\u00e8res au cross-country qui se dispute, ne l\u2019oublions pas, sur des boucles sillonnant g\u00e9n\u00e9ralement des stades, des parcs ou des hippodromes, ce qui n\u2019est bien s\u00fbr pas le cas de ce 12 bornes.<br \/>\nPour un grand nombre de trailers, le terme cross a aujourd\u2019hui, \u00e0 tort avons-nous envie d\u2019ajouter, une connotation p\u00e9jorative, ce qui ne peut qu\u2019entraver leur venue \u00e0 Saint-Germain-sur-Rh\u00f4ne. Du coup, les hommes-orchestres de la Semine remplaceront la saison prochaine le terme cross par celui de trail.<\/p>\n<p><b>R\u00e9volution avec le trail<\/b><br \/>\nIls le feront d\u2019autant plus, et c\u2019est l\u00e0 un tournant dans l\u2019histoire de cette manifestation, qu\u2019ils ont con\u00e7u cette ann\u00e9e, comme deuxi\u00e8me \u00e9preuve, un trail de 19,6 km, avec un diff\u00e9rentiel de 586 m, la portion accident\u00e9e couvrant principalement les six premi\u00e8res km, contre les trois premiers pour le 12,3 km. Le summum intervient \u00e0 partir du km 4 dans la seconde descente sur le Rh\u00f4ne, d\u00e9nomm\u00e9e fort \u00e0 propos \u00ab Tire-Cul \u00bb en raison de son caract\u00e8re tr\u00e8s escarp\u00e9, en particulier \u00e0 son \u00e9pilogue. S\u2019ensuivent dans un d\u00e9cor sauvage la travers\u00e9e, au km 5, du ruisseau de Balavent, affluent du deuxi\u00e8me fleuve fran\u00e7ais, puis une rude grimp\u00e9e en direction de l\u2019autoroute blanche \u00e0 travers, grande premi\u00e8re, la commune d\u2019Eloise (2).<\/p>\n<p><strong>Attentisme<\/strong><br \/>\nA la cl\u00f4ture des inscriptions en ligne et par courrier, samedi 27 octobre \u00e0 20 h, on comptait 107 adultes dont 53 sur le 19,6 km et 54 sur le 12,3 km. Une affluence maigrichonne qui a conduit les organisateurs, vendredi soir, \u00e0 prolonger opportun\u00e9ment les inscriptions de 24 h, ce qui a permis de grossir la participation sans qu\u2019il n\u2019y ait pourtant, h\u00e9las, une vraie dynamique.<br \/>\nQu\u2019en sera-t-il au moment du d\u00e9part, fix\u00e9 \u00e0 9 h 15 pour le trail puis \u00e0 9 h 25 pour le \u00ab cross \u00bb ? Il est trop pour le dire, le jour J \u00e9tant marqu\u00e9 parfois par des d\u00e9ferlantes prenant un tour irrationnel, y compris quand il tombe des cordes, ce qui ne sera finalement pas le cas, la m\u00e9t\u00e9o annon\u00e7ant maintenant un temps quasiment sec.\u00a0De quoi donner du baume au coeur \u00e0 l\u2019escouade dirigeante !<br \/>\nN\u2019emp\u00eache, certains se posent d\u2019ores et d\u00e9j\u00e0 la question de la l\u00e9gitimit\u00e9 d\u2019un trail sur le plateau de la Semine, avec un ratio distance-d\u00e9nivel\u00e9 aussi modeste, en particulier sur les 13 derniers km. Mais quoi qu\u2019il advienne, Philippe et ses potes ne regretteront pas de s\u2019\u00eatre lanc\u00e9s dans cette aventure, certes hasardeuse, risqu\u00e9e en diable, mais \u00f4 combien envo\u00fbtante par la d\u00e9couverte de nouveaux horizons et le resserrement des liens d\u2019amiti\u00e9s. Et cela, \u00e7a n\u2019a pas de prix !<\/p>\n<p><strong>F.V.<\/strong><\/p>\n<p>(1) L\u2019\u00e9quipe de<strong> Philippe Guichard<\/strong> tourne autour des cinq personnalit\u00e9s suivantes :<br \/>\n&#8211; Philippe, charg\u00e9 de remplir le dossier administratif et de d\u00e9marcher les sponsors.<br \/>\n&#8211; <strong>Fran\u00e7ois Blanchet<\/strong> et <strong>Jean-Fran\u00e7ois Cattin<\/strong>, charg\u00e9s des parcours des deux courses.<br \/>\n&#8211; <strong>Gaby Giet<\/strong> et\u00a0<strong>Christian Revilloud<\/strong>, charg\u00e9s des parcours des trois marches.<br \/>\n(2) Certes, le 12,3 km du <strong>Cross de la Semine<\/strong> rend visite \u00e0 la commune d\u2019Eloise, mais de fa\u00e7on tr\u00e8s \u00e9ph\u00e9m\u00e8re, en l\u2019occurrence entre les km 6 et 7, et donc peu significative pour qu\u2019on y pr\u00eate attention.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>ARTICLE DU QUOTIDIEN <em>LE DAUPHINE LIBERE<\/em> :<\/strong><\/p>\n<p>Ci-dessous, vous trouverez l\u2019annonce figurant en page sports des \u00e9ditions de la Haute-Savoie, en date du vendredi 26 octobre 2018. Son auteur est le correspondant<strong>\u00a0Georges Ongaro<\/strong>.<\/p>\n<p>\n\t\t<div class=\"wppdfemb-frame-container-1\" style=\"-webkit-overflow-scrolling:auto;\">\n\t\t\t<iframe class=\"pdfembed-iframe nonfullscreen wppdf-emb-iframe-1\"\n\t\t\t\tsrc=\"https:\/\/www.courzyvite.run\/blog\/?pdfemb-data=eyJ1cmwiOiJodHRwczpcL1wvd3d3LmNvdXJ6eXZpdGUucnVuXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE4XC8xMFwvUERGLVBhZ2UtMjctZWRpdGlvbi1kLWFubmVjeS1ydW1pbGx5LWxlcy1hcmF2aXMtMjAxODEwMjYtMS5wZGYiLCJ0aXRsZSI6IlBERi1QYWdlLTI3LWVkaXRpb24tZC1hbm5lY3ktcnVtaWxseS1sZXMtYXJhdmlzLTIwMTgxMDI2IiwiaW5kZXgiOjEsInBkZklEIjo3MTc4MX0\"\n\t\t\t\ttitle=\"PDF-Page-27-edition-d-annecy-rumilly-les-aravis-20181026\"\t\t\t\tdata-pdf-id=\"71781\"\n\t\t\t\tdata-pdf-index=\"1\"\n\t\t\t\tstyle=\"border:none;width:100%;max-width:100%;height:100vh;\"\n\t\t\t\tscrolling=\"yes\">\n\t\t\t<\/iframe>\n\t\t<\/div>\n\n\t\t<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>PRONOSTICS :<\/strong><\/p>\n<p>Une chose est certaine : les deux vainqueurs sortants du cross renoncent \u00e0 d\u00e9fendre leurs titres. Le Suisse <strong>Simon Senn<\/strong> (Club Athl\u00e9tique du Bassin Bellegardien) prend en effet la direction de Lausanne pour battre son record personnel sur 10 km, qui s\u2019\u00e9l\u00e8ve actuellement \u00e0 32\u201933. Une perf accomplie le 8 avril dernier \u00e0 Aix-les-Bains. De son c\u00f4t\u00e9, la Franco-Anglaise <strong>Emilie Shaw<\/strong>\u00a0(Run Valserine) qui avait port\u00e9, la saison pass\u00e9e, la marque r\u00e9f\u00e9rence \u00e0 56\u201916 est bless\u00e9e.<\/p>\n<p>Sinon, les retardataires du dimanche matin pourraient bien faire la diff\u00e9rence au regard des athl\u00e8tes d\u00e9j\u00e0 engag\u00e9s o\u00f9 on ne remarque aucun grand nom. Ce qui n\u2019emp\u00eache pas de souligner la pr\u00e9sence de coureurs confirm\u00e9s.<\/p>\n<p>A l\u2019image, sur le cross, du Sillingien<strong>\u00a0Beno\u00eet Berth\u00e9<\/strong>\u00a0(Les Alligators Seynod Triathlon), ainsi que des ins\u00e9parables duettistes du Faucigny Athl\u00e9tic Club que sont :<br \/>\n&#8211; Le pr\u00e9sident-entra\u00eeneur, et master 1,\u00a0<strong>Daniel Vanel<\/strong>.<strong><br \/>\n<\/strong>&#8211; Le vice-pr\u00e9sident\u00a0<strong>Gilles Farina<\/strong>, vice-champion de France V2 de marathon en 2010 en 2h45\u201931, dont ce sera l\u2019ultime \u00e9preuve en tant que quinqua, le\u00a0Margnerot basculant dans la cat\u00e9gorie des masters 3 le 1er novembre prochain. Mais que le temps passe vite !<br \/>\nOn n\u2019oubliera surtout pas la Tch\u00e8co-Suissesse de Gen\u00e8ve, et master 2,\u00a0<strong>Yvona Jenc<\/strong>, octuple laur\u00e9ate en 1999, 2000, 2003, 2005, 2008, 2009, 2011 et 2012.<\/p>\n<p>Sur le trail, on mettra en avant les deux personnalit\u00e9s suivantes :<br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #000000;\">\u2013 Le <\/span><\/span>Franclinois\u00a0<strong>S\u00e9bastien Chatelain<\/strong>, champion de France de trekking en \u00e9quipe mixte chez les sapeurs-pompiers, les 7 et 8 septembre dernier \u00e0 Saint-Sorlin-d\u2019Arves.<br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #000000;\">\u2013 La Desingeoise\u00a0<\/span><\/span><strong>Nad\u00e8ge Vignand\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), championne de France de trail court en 2014 puis vice-championne de France de kilom\u00e8tre vertical en 2016 parmi les v\u00e9t\u00e9ranes. Preuve de sa fid\u00e9lit\u00e9, \u00e0 l\u2019instar d\u2019Yvona, Nad\u00e8ge se d\u00e9placera \u00e0 Saint-Germain-sur-Rh\u00f4ne pour la neuvi\u00e8me ann\u00e9e cons\u00e9cutive, le mill\u00e9sime 2010 co\u00efncidant avec sa premi\u00e8re exp\u00e9rience en course \u00e0 pied, conclue par une 2\u00e8me place, avant de l\u2019emporter en 2014, 2015 et 2016.<\/p>\n<p><strong>F.V.<br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nTrail de la Semine (19,6 km) :<\/strong><\/p>\n<p><strong>Liste des inscrits :<\/strong><br \/>\nElle figure sur le site Web L-Chrono :<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/crossdelasemine2018\/registrations-list\">https:\/\/inscriptions-l-chrono.com\/crossdelasemine2018\/registrations-list<\/a><\/p>\n<p><strong>Favori :<br \/>\n<\/strong><strong>\u2013 S\u00e9bastien Chatelain<\/strong>, n\u00e9 le 28 ao\u00fbt 1980 et demeurant \u00e0 Franclens.<\/p>\n<p><span style=\"color: #ffffff;\"><span style=\"color: #000000;\"><strong>Outisiders masculins :<br \/>\n<\/strong><strong>\u2013 Maxime Duclos<\/strong>\u00a0(Football Club de Frangy), n\u00e9 le 17 septembre 1998 et demeurant \u00e0 Desingy.<br \/>\n<strong>\u2013 Emmanuel Maison\u00a0<\/strong>(Albanais Athl\u00e9), n\u00e9 le 15 d\u00e9cembre 1978 et demeurant \u00e0 Rumilly.<br \/>\n<strong>\u2013 Loris Pettini\u00a0<\/strong>(L\u2019Alcoloc), n\u00e9 le 22 janvier 1993 et demeurant \u00e0 Annecy.<br \/>\n<strong>\u2013 Jacques Soulier\u00a0<\/strong>(Run Valserine), n\u00e9 le 12 mai 1967 et demeurant \u00e0 Bellegarde.<br \/>\n<strong>\u2013 Florian Zuccalli<\/strong>\u00a0(Les Princes en Foul\u00e9es), n\u00e9 le 28 octobre 1989 et demeurant \u00e0 Seyssel (Haute-Savoie).<\/span><\/span><\/p>\n<p><span style=\"color: #ffffff;\"><span style=\"color: #000000;\"><strong>Favorite :<\/strong><br \/>\n<strong>\u2013 Nad\u00e8ge Vignand\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), n\u00e9e le 19 d\u00e9cembre 1972 et demeurant \u00e0 Desingy.<\/span><\/span><\/p>\n<p><span style=\"color: #ffffff;\"><span style=\"color: #000000;\"><strong>Outsiders f\u00e9minins :<\/strong><br \/>\n<strong>\u2013 M\u00e9lanie Devynck\u00a0<\/strong>(Triathlon Bassin Bellegardien), n\u00e9e le 8 d\u00e9cembre 1986 et demeurant \u00e0 Usinens.<br \/>\n<strong>\u2013 Marie Roupioz<\/strong>, n\u00e9e le 5 avril 1991 et demeurant \u00e0 Boussy.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Cross de la Semine (12,3 km) :<\/strong><\/span><\/span><\/p>\n<p><strong>Liste des inscrits :<\/strong><br \/>\nElle figure sur le site Web L-Chrono :<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/crossdelasemine2018\/registrations-list\">https:\/\/inscriptions-l-chrono.com\/crossdelasemine2018\/registrations-list<\/a><\/p>\n<p><strong>Records \u00e0 battre :<br \/>\n<\/strong>\u2013 Participation : 182\u00a0inscrits\u00a0en 2015.<br \/>\n\u2013 Hommes :\u00a0le Marocain\u00a0<strong>Abdesalam Kiday<\/strong> (Club Athl\u00e9tique du Bassin Bellegardien) en 44\u201928\u00a0en 2011.<br \/>\n\u2013 Femmes : la Franco-Anglaise\u00a0<strong>Emilie Shaw<\/strong>\u00a0(Run Valserine) en 56\u201916 en 2017.<br \/>\nConcernant les records hommes et femmes, je n\u2019ai retenu que ceux r\u00e9alis\u00e9s \u00e0 partir de l\u2019\u00e9dition 2010, hormis celle de 2013 o\u00f9 le parcours avait \u00e9t\u00e9 r\u00e9duit \u00e0 11,2 km au lieu de 12,3 km, et ce en raison d\u2019une m\u00e9t\u00e9o ex\u00e9crable.<\/p>\n<p><strong>Favoris :<\/strong><br \/>\n<strong>\u2013 Beno\u00eet Berth\u00e9\u00a0<\/strong>(Les Alligators Seynod Triathlon), n\u00e9 le 15 septembre 1982 et demeurant \u00e0 Sillingy.<strong><br \/>\n\u2013 Daniel Vanel\u00a0<\/strong>(Faucigny Athl\u00e9tic Club), n\u00e9 le 31 ao\u00fbt 1972 et demeurant \u00e0 Cluses.<strong><br \/>\n<\/strong><\/p>\n<p><strong>Outsiders masculins :<br \/>\n\u2013 Thomas Carminati<\/strong> (Run Valserine), n\u00e9 le 19 f\u00e9vrier 1987 et demeurant \u00e0 Maillat.<br \/>\n<strong>\u2013 Gilles Dagniaux<\/strong> (M\u2019y Tribe Triathlon), n\u00e9 le 20 mai 1965 et demeurant \u00e0 Saint-Jorioz.<br \/>\n<strong>\u2013 Morgan Delorme<\/strong>, n\u00e9 le 21 septembre 1987 et demeurant \u00e0 Ch\u00e9zery-Forens.<br \/>\n\u2013 <strong>Gilles Farina<\/strong>\u00a0(Faucigny Athl\u00e9tic Club), n\u00e9 le 4 mars 1959 et demeurant \u00e0 Marignier.<br \/>\n<strong>\u2013 Julien Maillet<\/strong>, n\u00e9 le 17 ao\u00fbt 1978 et demeurant \u00e0 Desingy.<br \/>\n<strong>\u2013 Thierry Mossiere<\/strong>, n\u00e9 le 5 novembre 1986 et demeurant \u00e0 Annecy.<\/p>\n<p><strong>Favorite :<\/strong><br \/>\n<strong>\u2013 Yvona Jenc<\/strong>\u00a0(Suisse et Tch\u00e9quie), n\u00e9e le 26 mars 1967 et demeurant \u00e0 Gen\u00e8ve.<\/p>\n<p><strong>Outsider f\u00e9minin :<\/strong><br \/>\n<strong>\u2013 Christelle Goutaz <\/strong>(Les Princes en Foul\u00e9es), n\u00e9e le 7 mars 1983 et demeurant \u00e0 Droisy.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong><span style=\"color: #000000;\">PALMARES EN 1991 ET DEPUIS 1995 :<br \/>\n<\/span><\/strong><span style=\"font-size: 0.95em;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<\/span>Cr\u00e9\u00e9 en <strong>1987<\/strong>, le Cross de la Semine a connu depuis 1996 trois types de parcours :<br \/>\n<strong>\u2013 De 1996 \u00e0 2006 :<\/strong> 12 km (d\u00e9nivel\u00e9 inconnu).<br \/>\n<strong>\u2013\u00a0De 2007 \u00e0 2009 :<\/strong> 12 km (d\u00e9nivel\u00e9 inconnu).<br \/>\n<strong>\u2013 A partir de 2010 :<\/strong> 12,3 km pour 309 m de d\u00e9nivel\u00e9, except\u00e9 en\u00a02013 o\u00f9 le mauvais temps a contraint les organisateurs \u00e0 r\u00e9duire le trac\u00e9, long alors de 11,2 km pour 170 m de d\u00e9nivel\u00e9.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>27 octobre 1991 :<\/strong><\/p>\n<p><strong>12 km<\/strong> (51 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) :\u00a0<strong>Dominique Delbe<\/strong>\u00a0(Coquelicot Saint-Etienne) en 42\u201948.<span style=\"font-size: 0.95em;\"><br \/>\n<\/span><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>29 octobre 1995 :<\/strong><\/p>\n<p><strong>12km<\/strong> (64 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>J\u00e9r\u00f4me Bosch<\/strong>\u00a0(Athl\u00e9tic Club Evian) en 42\u201917.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) : <strong>Monique Renaud<\/strong>\u00a0(Ski Club de Bellegarde) en 56\u201949\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>27 octobre 1996 :<\/strong><\/p>\n<p><strong>12km, nouveau parcours :<\/strong><br \/>\n\u2013 1er (1er senior) : <strong>Antonio Campos<\/strong>\u00a0(Portugal, Pays Rochois Athl\u00e9tic) en\u00a0<strong>39\u201932\u2019\u20190, record scratch du parcours emprunt\u00e9 entre 1996 et 2006<\/strong>.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior) : <strong>Rosine Tournier<\/strong>\u00a0(La Foul\u00e9e d\u2019Annemasse) en 56\u201923\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>26 octobre 1997 :<\/strong><\/p>\n<p><strong>12km :<\/strong><br \/>\n\u2013 1er (1er senior) : <strong>Antonio Campos<\/strong>\u00a0(Portugal, Pays Rochois Athl\u00e9tic) en 39\u201948\u2019\u201901.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior) : <strong>Fatima Dos Santos<\/strong>\u00a0(Portugal, Team Oxyg\u00e8ne) en 48\u201937\u2019\u20198.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>25 octobre 1998 :<\/strong><\/p>\n<p><strong>12km :<\/strong><br \/>\n\u2013 1er (1er senior) : <strong>Antonio Campos<\/strong>\u00a0(Portugal, Pays Rochois Athl\u00e9tic) en 42\u201901\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) : <strong>Marie-Laure Duchene<\/strong>\u00a0(Annecy) en 1h00\u201915.<span style=\"font-size: 0.95em;\"><br \/>\n<\/span><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>31 octobre 1999 :<\/strong><\/p>\n<p><strong>12km :<\/strong><br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer<\/strong>\u00a0(Union Sportive Oyonnax) en 40\u201944\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) : <strong>Yvona Jenc<\/strong>\u00a0(Suisse et Tch\u00e9quie, Uriana Sports Gen\u00e8ve) en 56\u201937\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n29 octobre 2000 :<\/strong><\/p>\n<p><strong>12km<\/strong> (71 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer<\/strong>\u00a0(Union Sportive Oyonnax) en 41\u201903\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior) :<strong>\u00a0Yvona Jenc<\/strong> (Suisse et Tch\u00e9quie, Foul\u00e9es Athl\u00e9tiques Saconn\u00e9siennes) en 50\u201933\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>28 octobre 2001 :<\/strong><\/p>\n<p><strong>12km<\/strong> (69 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer<\/strong>\u00a0(Union Sportive Oyonnax) en 40\u201930\u2019\u201902.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) : <strong>Fatima Dos Santos<\/strong>\u00a0(Portugal, Team Oxyg\u00e8ne) en 50\u201956\u2019\u20196.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>27 octobre 2002 :<\/strong><\/p>\n<p><strong>12km<\/strong> (72 class\u00e9s) :<br \/>\n\u2013 1er (1er V1) : <strong>Antonio Campos<\/strong>\u00a0(Portugal, Pays Rochois Athl\u00e9tic) en 41\u201941\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) :<strong>\u00a0Fatima Dos Santos\u00a0<\/strong>(Portugal, Team Oxyg\u00e8ne) en 53\u201931\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>26 octobre 2003 :<\/strong><\/p>\n<p><strong>12km<\/strong> (87 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer\u00a0<\/strong>(Union Sportive Oyonnax) en 41\u201946\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) :<strong>\u00a0Yvona Jenc<\/strong>\u00a0(Suisse et Tch\u00e9quie, Gen\u00e8ve) en 51\u201952\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>31 octobre 2004 :<\/strong><\/p>\n<p><strong>12km<\/strong> (102 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 42\u201905\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) :<strong>\u00a0Nina Belikova\u00a0<\/strong>(Russie, Patronage La\u00efque de Pierre-B\u00e9nite, section de l\u2019Entente Sud Lyonnais) en 49\u201943\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>30 octobre 2005 : <\/strong><\/p>\n<p><strong>12km<\/strong> (91 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Eric Vasmer<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 41\u201916\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior) : <strong>Yvona Jenc<\/strong>\u00a0(Suisse et Tch\u00e9quie, La Foul\u00e9e d\u2019Annemasse) en 52\u201934\u2019\u20190.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>29 octobre 2006 :<\/strong><\/p>\n<p><strong>12km<\/strong> (97 class\u00e9s) :<br \/>\n\u2013 1er (1er senior) : <strong>Sergue\u00ef Kaledine<\/strong>\u00a0(Russie ; Patronage La\u00efque de Pierre-B\u00e9nite, section de l\u2019Entente Sud Lyonnais) en 41\u201936\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1) : <strong>Sevtlana Netchaeva<\/strong>\u00a0(Russie ; Patronage La\u00efque de Pierre-B\u00e9nite, section de l\u2019Entente Sud Lyonnais) en\u00a0<strong>48\u201923\u2019\u20190, record f\u00e9minin du parcours emprunt\u00e9 entre 1996 et 2006<\/strong>.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>28 octobre 2007 :<\/strong><\/p>\n<p><strong>12 km, nouveau parcours<\/strong> (54 class\u00e9s dont 7 femmes) :<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Antonio Campos<\/strong>\u00a0(Portugal, Arve Athl\u00e9tisme Bonneville Pays Rochois) en 43\u201936\u2019\u20197.<br \/>\n\u2013 1\u00e8re (1\u00e8re espoir-senior, 26\u00e8me au scratch)\u00a0:\u00a0<strong>Audrey Begey Paccard<\/strong>\u00a0(La Foul\u00e9e d\u2019Annemasse) en 1h00\u201901\u2019\u20190.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2007-pdf.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2007-pdf.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>26 octobre 2008 :<\/strong><\/p>\n<p><strong>12 km<\/strong> (74 class\u00e9s dont 17 femmes) :<br \/>\n\u2013\u00a01er (1er V1)\u00a0:\u00a0<strong>Antonio Campos\u00a0<\/strong>(Portugal, Arve Athl\u00e9tisme Bonneville Pays Rochois) en 43\u201936\u2019\u20197.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 17\u00e8me au scratch)\u00a0:\u00a0<strong>Yvona Jenc\u00a0<\/strong>(Suisse et Tch\u00e9quie, La Foul\u00e9e d\u2019Annemasse) en\u00a0<strong>52\u201925\u2019\u20193, record f\u00e9minin du parcours emprunt\u00e9 entre 2007 et 2009<\/strong>.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2008-pdf.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2008-pdf.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>25 octobre 2009 :<\/strong><\/p>\n<p><strong>12 km<\/strong> (90 inscrits, 89 partants dont 16 femmes, 87 class\u00e9s dont 15 femmes) :<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Antonio Campos<\/strong>\u00a0(Portugal, Arve Athl\u00e9tisme Bonneville Pays Rochois) en\u00a0<strong>42\u201950\u2019\u20195, record scratch du parcours emprunt\u00e9 entre 2007 et 2009<\/strong>.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 28\u00e8me au scratch)\u00a0:<strong>\u00a0Yvona Jenc<\/strong>\u00a0(Suisse et Tch\u00e9quie, La Foul\u00e9e d\u2019Annemasse) en 53\u201927\u2019\u20199.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2009pdf.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-2009pdf.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>31 octobre 2010 :<\/strong><\/p>\n<p><strong>12,3 km, nouveau parcours<\/strong> (143 partants dont 21 femmes, 142 class\u00e9s dont 20 femmes) :<br \/>\n\u2013 1er ex aequo (1er espoir-senior ex aequo)\u00a0:\u00a0<strong>Philippe Robin\u00a0<\/strong>(Entente Athl\u00e9tique Bressane) en 47\u201934\u2019\u20195.<br \/>\n\u2013 1er ex aequo (1er espoir-senior ex aequo)\u00a0:\u00a0<strong>S\u00e9bastien Bernardo<\/strong> (Annecy-le-Vieux Of Course) en 47\u201934\u2019\u20198.<br \/>\n\u2013 1\u00e8re (1\u00e8re espoir-senior, 58\u00e8me au scratch)\u00a0:<strong>\u00a0Daciana Vulliet<\/strong>\u00a0(Clermont-en-Genevois) en 48\u201914.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/ffsski-resultats-officieux.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/ffsski-resultats-officieux.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>30 octobre 2011 :<\/strong><\/p>\n<p><strong>12,3 km<\/strong> (152 inscrits dont 32 femmes, 138 partants dont 31 femmes, 133 class\u00e9s dont 30 femmes) :<br \/>\n\u2013 1er (1er espoir-senior)\u00a0:\u00a0<strong>Abdesalam Kiday<\/strong>\u00a0(Maroc,\u00a0La Foul\u00e9e d\u2019Annemasse) en\u00a0<strong>44\u201928\u2019\u20195, record scratch du parcours emprunt\u00e9 depuis 2010 (except\u00e9 en 2013)<\/strong>.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 32\u00e8me au scratch)\u00a0:<strong>\u00a0Yvona Jenc\u00a0<\/strong>(Suisse et Tch\u00e9quie, La Foul\u00e9e d\u2019Annemasse) en 58\u201906\u2019\u20191.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/nor-resultat-course.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/nor-resultat-course.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>28 octobre 2012 :<\/strong><\/p>\n<p><strong>12,3 km<\/strong> (137 inscrits dont 25 femmes, 109 partants dont 21 femmes, 107 partants dont 21 femmes) :<br \/>\n\u2013 1er (1er espoir-senior)\u00a0:\u00a0<strong>Abdesalam Kiday<\/strong>\u00a0(Maroc,\u00a0La Foul\u00e9e d\u2019Annemasse) en 44\u201957\u2019\u20197.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 36\u00e8me au scratch)\u00a0:\u00a0<strong>Yvona Jenc\u00a0<\/strong>(Suisse et Tch\u00e9quie, La Foul\u00e9e d\u2019Annemasse) en 58\u201934\u2019\u20195.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-12-km-2012.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/scratch-12-km-2012.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>27 octobre 2013 :<\/strong><\/p>\n<p><strong>12,3 r\u00e9duit \u00e0 11,2 km<\/strong> (107 inscrits dont 28 femmes, 101 class\u00e9s dont 26 femmes) :<br \/>\n\u2013 1er (1er espoir-senior)\u00a0:\u00a0<strong>El Yazid El Madi<\/strong>\u00a0(Maroc, Team Technicien du Sport Seynod et Club Athl\u00e9tique du Bassin Bellegardien) en 40\u201943\u2019\u20190.<br \/>\n\u2013 1\u00e8re (1\u00e8re espoir-senior, 24\u00e8me au scratch)\u00a0:<strong> Anne-Lise Chamiot-Poncet<\/strong>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien) en 50\u201942\u2019\u20198.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/11-2-km-resultats-cad-a-v4.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/11-2-km-resultats-cad-a-v4.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>26 octobre 2014 :<\/strong><\/p>\n<p><strong>12,3 km<\/strong> (115 partants dont 19 femmes ; 114 class\u00e9s dont 19 femmes) :<br \/>\n\u2013 1er (1er espoir-senior)\u00a0:\u00a0<strong>El Yazid El Madi<\/strong>\u00a0(Maroc, Team Technicien du Sport Seynod et Club Athl\u00e9tique du Bassin Bellegardien) en 47\u201940\u2019\u20194.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 20\u00e8me au scratch)\u00a0:<strong>\u00a0Nad\u00e8ge Vignand\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme) en 58\u201949\u2019\u20193.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/2014-sa.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/2014-sa.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>25 octobre 2015 :<\/strong><\/p>\n<p><strong>12,3 km<\/strong> <strong>(182 inscrits, 179 partants dont 45 femmes, 175 class\u00e9s dont 43 femmes, record de participation) :<\/strong><br \/>\n\u2013\u00a01er (1er V1) :<strong>\u00a0El Yazid El Madi<\/strong>\u00a0(Maroc, Club Athl\u00e9tique du Bassin Bellegardien) en 44\u201954\u2019\u20197.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 36\u00e8me au scratch) :<strong>\u00a0Nad\u00e8ge Vignand<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 57\u201906\u2019\u20194.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/classement-scratch-12-km.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/classement-scratch-12-km.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>30 octobre 2016 :<\/strong><\/p>\n<p><strong>12,3 km<\/strong> (171 inscrits dont 41 femmes, 168 partants dont 40 femmes, 167 class\u00e9s dont 40 femmes) :<br \/>\n\u2013\u00a01er (1er V1) :\u00a0<strong>El Yazid El Madi<\/strong>\u00a0(Maroc, Club Athl\u00e9tique du Bassin Bellegardien) en 45\u201951\u2019\u20194.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 28\u00e8me au scratch) :<strong>\u00a0Nad\u00e8ge Vignand<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en\u00a057\u201902\u2019\u20195.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/resultats-cross-semine-12-km-1.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/resultats-cross-semine-12-km-1.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>29 octobre 2017 : <\/strong><\/p>\n<p><strong>12,3 km<\/strong> (134 inscrits dont 31 femmes, 133 partants dont 31 femmes, 131 class\u00e9s dont 30 femmes) :<br \/>\n\u2013\u00a01er (1er espoir-senior) :\u00a0<strong>Simon Senn<\/strong>\u00a0(Suisse, Club Athl\u00e9tique du Bassin Bellegardien) en 45\u201952\u20191.<br \/>\n\u2013 1\u00e8re (1\u00e8re espoir-senior, 18\u00e8me au scratch) :\u00a0<strong>Emilie Shaw<\/strong>\u00a0(France et Angleterre, Run Valserine) en\u00a0<strong>56\u201916\u2019\u20190, record f\u00e9minin du parcours emprunt\u00e9 depuis 2010 (except\u00e9 en 2013)<\/strong>.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la manifestation :<br \/>\n<a href=\"http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/resultat-cross-semine-2017-v00.pdf\">http:\/\/st-germain-sur-rhone-comite.e-monsite.com\/medias\/files\/resultat-cross-semine-2017-v00.pdf<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>LE CROSS DE LA SEMINE SUR LE SITE WEB COURZYVITE :<\/strong><\/p>\n<p><strong>\u2013 R\u00e9sultats, comptes rendus et photos de l\u2019\u00e9dition 2015 :<\/strong><br \/>\n<a href=\"https:\/\/www.courzyvite.run\/blog\/2015\/10\/26\/retour-a-ledition-du-31-octobre-2015-par-le-texte-et-limage\/\">https:\/\/www.courzyvite.run\/blog\/2015\/10\/26\/retour-a-ledition-du-31-octobre-2015-par-le-texte-et-limage\/<\/a><\/p>\n<p><strong>\u2013 Pr\u00e9sentation de l\u2019\u00e9dition 2016 :<\/strong><br \/>\n<a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/10\/30\/presentation-du-cross-de-la-semine-30-10-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/10\/30\/presentation-du-cross-de-la-semine-30-10-16\/<\/a><\/p>\n<p><strong>\u2013 R\u00e9sultats, comptes rendus et premi\u00e8res photos de l\u2019\u00e9dition 2016 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/11\/06\/resultats-compte-rendu-et-premieres-photos-du-cross-de-la-semine-30-10-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/11\/06\/resultats-compte-rendu-et-premieres-photos-du-cross-de-la-semine-30-10-16\/<\/a><\/p>\n<p><strong>\u2013 Photos de l\u2019\u00e9dition 2016 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/11\/07\/photos-du-cross-de-la-semine-30-10-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/11\/07\/photos-du-cross-de-la-semine-30-10-16\/<\/a><\/p>\n<p><strong>\u2013 Pr\u00e9sentation de l\u2019\u00e9dition 2017 : les pronostics ; le parcours en images :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2017\/10\/28\/presentation-du-cross-de-la-semine-le-parcours-en-images-29-10-17\/\">https:\/\/www.courzyvite.run\/blog\/2017\/10\/28\/presentation-du-cross-de-la-semine-le-parcours-en-images-29-10-17\/<\/a><strong><br \/>\n<\/strong><\/p>\n<p><strong>\u2013 R\u00e9sultats et comptes rendus de l\u2019\u00e9dition 2017 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2017\/11\/02\/resultats-et-compte-rendu-du-cross-de-la-semine-29-10-17\/\">https:\/\/www.courzyvite.run\/blog\/2017\/11\/02\/resultats-et-compte-rendu-du-cross-de-la-semine-29-10-17\/<\/a><strong><br \/>\n<\/strong><\/p>\n<p><strong>\u2013 Photos de l\u2019\u00e9dition 2017 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2017\/11\/03\/photos-du-cross-de-la-semine-29-10-17\/\">https:\/\/www.courzyvite.run\/blog\/2017\/11\/03\/photos-du-cross-de-la-semine-29-10-17\/<\/a><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPHOTOS :<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/treksp2018-j1-3609071CF8-7538-F6AC-1DA2-50AAEBB6A6D3-e1540802315577.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19354 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/treksp2018-j1-3609071CF8-7538-F6AC-1DA2-50AAEBB6A6D3-e1540802315577.jpg?resize=860%2C571&#038;ssl=1\" alt=\"\" width=\"860\" height=\"571\" \/><\/a>S\u00e9bastien Chatelain<\/strong> (Franclens), favori du 1er Trail de la Semine (19,6 km), disput\u00e9 le dimanche 28 octobre 2018 \u00e0 Saint-Germain-sur-Rh\u00f4ne dans le cadre de la 32\u00e8me \u00e9dition du Cross de la Semine.<br \/>\nClich\u00e9 pris le 7 septembre 2018 \u00e0 l\u2019occasion du premier jour des 16\u00e8mes Championnats de France de Trekking Sapeurs-Pompiers, concourus \u00e0 Saint-Sorlin d\u2019Arves, o\u00f9 S\u00e9bastien s\u2019appropriera la 7\u00e8me place par \u00e9quipe (1er en \u00e9quipe mixte) en 4h17\u201908.<br \/>\nA l\u2019issue, le 8 septembre, des deux jours de comp\u00e8te, S\u00e9bastien et son escouade, d\u00e9nomm\u00e9e\u00a0\u00ab La Yaute \u00bb, termineront 6\u00e8mes (1ers en \u00e9quipe mixte) en 10h17\u201936.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46646 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-1.jpg?resize=860%2C571&#038;ssl=1\" alt=\"\" width=\"860\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-1.jpg?w=886&amp;ssl=1 886w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-1.jpg?resize=820%2C544&amp;ssl=1 820w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-1.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>La Tch\u00e8co-Suissesse <b>Yvona Jenc\u00a0<\/b>(Gen\u00e8ve), favorite du 12,3 km, disput\u00e9 le dimanche 28 octobre 2018 \u00e0 Saint-Germain-sur-Rh\u00f4ne dans le cadre de la 32\u00e8me \u00e9dition du Cross de la Semine.<br \/>\nClich\u00e9 pris le 29 octobre 2017 par\u00a0<strong>Jean-Claude Delachenal<\/strong>, \u00e0 l\u2019occasion du 31\u00e8me Cross de la Semine, o\u00f9 Yvona s\u2019appropriera la 2\u00e8me place f\u00e9minine (1\u00e8re V2, 21\u00e8me au scratch) en 56\u201923.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 150 m de l\u2019arriv\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUP DE POKER A HAUT RISQUE ! Pour les vaillantes chevilles ouvri\u00e8res du Cross de la Semine, on pr\u00e9f\u00e8re d\u00e9sormais le mouvement \u00e0 la scl\u00e9rose. Install\u00e9 \u00e0 Saint-Germain-sur-Rh\u00f4ne en 1991 en provenance du d\u00e9partement de l\u2019Yonne, Philippe Guichard a d\u2019abord pris, \u00e0 la t\u00eate de l\u2019organisation, la succession de l\u2019embl\u00e9matique\u00a0Christian Baron, une fois les lampions de l\u2019\u00e9dition 2017 \u00e9teints. Il faut dire que Christian \u00e9tait \u00e0 l\u2019ouvrage depuis 1983 en [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":19306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[32,16,6,24,13],"tags":[11],"class_list":["post-19310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-sur-les-courses","category-haute-savoie","category-articles","category-le-cross-de-la-semine","category-presentations-des-courses","tag-news"],"views":2604,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/10\/DSC_0406-e1540741866516.jpg?fit=886%2C493&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7PZ3h-51s","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/19310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/comments?post=19310"}],"version-history":[{"count":3,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/19310\/revisions"}],"predecessor-version":[{"id":71785,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/19310\/revisions\/71785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media\/19306"}],"wp:attachment":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media?parent=19310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/categories?post=19310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/tags?post=19310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}