{"id":15793,"date":"2018-05-12T16:55:27","date_gmt":"2018-05-12T14:55:27","guid":{"rendered":"https:\/\/www.courzyvite.run\/blog\/?p=15793"},"modified":"2020-09-05T19:52:10","modified_gmt":"2020-09-05T17:52:10","slug":"presentation-de-la-course-des-etangs-13-05-18","status":"publish","type":"post","link":"https:\/\/www.courzyvite.run\/blog\/2018\/05\/12\/presentation-de-la-course-des-etangs-13-05-18\/","title":{"rendered":"PRESENTATION DE LA COURSE DES ETANGS \/ 13-05-18"},"content":{"rendered":"<p><strong>UNE COURSE DE VILLAGE QUI PARVIENT A S\u2019IMMISCER DANS LA COUR DES GRANDS<\/strong><\/p>\n<p>Concourue \u00e0 Saint-F\u00e9lix, la<strong> Course des Etangs<\/strong>\u00a0qui f\u00eatera ce dimanche 13 mai son 10\u00e8me anniversaire se porte comme un charme, l\u2019accessibilit\u00e9 de ses deux parcours vallonn\u00e9s, un 15 et un 8 km, constituant son ADN. Un \u00e9v\u00e9nement qui tire \u00e9galement partie de sa localisation dans l\u2019Albanais, un territoire \u00e0 forte croissance d\u00e9mographique s\u2019\u00e9tendant sur les Deux Savoie.<\/p>\n<p>D\u2019embl\u00e9e, la greffe aura pris, l\u2019affluence s\u2019\u00e9levant en cette ann\u00e9e 2009 \u00e0 351 engag\u00e9s avant de fr\u00f4ler en 2013 la barre des 400 (393) puis de la franchir en 2016 (415). La saison\u00a0pass\u00e9e, la manifestation a poursuivi son irr\u00e9sistible ascension en s\u2019approchant des 500 inscrits (487), mettant ainsi \u00e0 profit la nouvelle date, fix\u00e9e au deuxi\u00e8me dimanche de mai, et non plus au premier, ce qui lui permettait d\u2019\u00e9chapper au voisinage de la Chambottine. Ironie de l\u2019histoire, ce changement \u00e9tait voulu dans l\u2019unique but de ne pas co\u00efncider le rendez-vous avec le deuxi\u00e8me tour de l\u2019\u00e9lection pr\u00e9sidentielle du 7 mai.<\/p>\n<p>Du coup, cette d\u00e9ferlante incita\u00a0<strong>Philippe Jacquelin<\/strong>, pionnier puis homme lige de la Course des Etangs, \u00e0 reconduire cette ann\u00e9e cette \u00e9ch\u00e9ance. Il \u00e9tait\u00a0d\u2019autant plus enclin \u00e0 agir de la sorte que cette date \u00e9vitait la redoutable concurrence du Nivolet-Revard, disput\u00e9 une semaine auparavant. Une date qui ne peut donc que drainer du monde et faire de son \u00e9v\u00e9nement un rendez-vous phare, sinon incontournable. Fid\u00e8le \u00e0 sa r\u00e9putation d\u2019homme discret et modeste, le pr\u00e9sident de <strong>Saint-F\u00e9lix Notre Village<\/strong>\u00a0n\u2019en tient pas moins \u00e0 pr\u00e9server la taille humaine de son entreprise.<strong>\u00a0<\/strong>Raison pour laquelle il continue \u00e0 limiter le nombre de comp\u00e9titeurs \u00e0 499 et, parall\u00e8lement, refuse de corser les dimensions des deux \u00e9preuves au menu ou bien d\u2019en\u00a0sortir une troisi\u00e8me de son chapeau.<\/p>\n<p>Le succ\u00e8s populaire attendu ne pourra que r\u00e9jouir les parents d\u2019<strong>Oxana<\/strong>. Pour la deuxi\u00e8me \u00e9dition d\u2019affil\u00e9e,\u00a0un euro par dossard leur sera en effet revers\u00e9 afin de pourvoir soigner leur fille de 32 mois, victime d\u2019un n\u00e6vus g\u00e9ant cong\u00e9nital survenu dans les premiers mois de grossesse (voir ci-dessous l\u2019article).<\/p>\n<p><strong>F.V.<\/strong><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>COURIR POUR OXANA :<\/strong><\/p>\n<p>En lan\u00e7ant en 2009 la Course des Etangs,<strong> Philippe Jacquelin<\/strong>\u00a0s\u2019est fix\u00e9 comme mission de verser un euro par inscription \u00e0 une personne en souffrance. Depuis 2017, le choix s\u2019est port\u00e9 sur\u00a0<strong>Oxana<\/strong>, une petite fille atteinte d\u2019un n\u00e6vus g\u00e9ant cong\u00e9nital surgi dans les premiers mois de grossesse. Il se caract\u00e9rise par d\u2019immenses grains de beaut\u00e9 pouvant recouvrir jusqu\u2019\u00e0 80 % du corps des nouveau n\u00e9s, ce qui est le cas d\u2019Oxana.<\/p>\n<p>Cette tumeur b\u00e9nigne a de fortes chances de d\u00e9g\u00e9n\u00e9rer en tumeur maligne de la peau. La gu\u00e9rison d\u00e9pend alors \u00e0 la fois de la taille du naevus et de sa localisation. Elle intervient en enlevant le naevus \u00e0 la suite de plusieurs op\u00e9rations chirurgicales, au nombre de six au minimum s\u2019il est de taille moyenne. C\u2019est \u00e0 l\u2019\u00e2ge de 4 mois qu\u2019Oxana est pass\u00e9 pour la premi\u00e8re fois sur le billard.<\/p>\n<p>Le co\u00fbt des d\u00e9passements d\u2019honoraires, anesth\u00e9sie et chirurgie confondues, peut atteindre par op\u00e9ration 2000 euros. Les parents d\u2019Oxana ont donc un besoin imp\u00e9ratif d\u2019\u00eatre \u00e9paul\u00e9s financi\u00e8rement, d\u2019autant plus que leur fille se fait op\u00e9rer tous les trois \u00e0 six mois. En outre, leur mutuelle ne prendra les remboursements \u00e0 sa charge qu\u2019\u00e0 200 % \u00e0 partir de novembre 2018 alors que la famille escomptait 400 %.<\/p>\n<p><strong>F.V.<\/strong><\/p>\n<p><strong>\u2013 Page Facebook A Fleur de Peau d\u2019Oxana :<\/strong><br \/>\n<a href=\"https:\/\/www.facebook.com\/%C3%80-fleur-de-peau-250067705416791\/\">https:\/\/www.facebook.com\/%C3%80-fleur-de-peau-250067705416791\/<\/a><\/p>\n<p><strong>\u2013 Site Web A Fleur de Peau d\u2019Oxana :<br \/>\n<\/strong><a href=\"http:\/\/www.afleurdepeau-oxana.org\/\">http:\/\/www.afleurdepeau-oxana.org\/<\/a><strong><br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #ffffff;\">.<br \/>\n<\/span>.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nPRONOSTICS SUR LE 15 KM :<br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nRecords \u00e0 battre sur le parcours emprunt\u00e9 en 2009-2010 et depuis 2014 :<\/strong><\/p>\n<p>\u2013 Participation : <strong>249 inscrits<\/strong> en 2017.<br \/>\n\u2013 Hommes :\u00a0<strong>Lhoussine Boussague<\/strong>\u00a0(Maroc, Annecy Haute-Savoie Athl\u00e9tisme et Wifaq Sportive Athletic Chichaoua) en\u00a0<strong>49\u201943 <\/strong>en 2017.<br \/>\n\u2013 Femmes : <strong>Karine Marguerettaz\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme) en<strong>\u00a058\u201959 <\/strong>en 2014. <span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<br \/>\n.<strong><br \/>\n<\/strong><\/span><strong>Liste des inscrits :<\/strong><\/p>\n<p>Elle figure sur le site Web L-Chrono :<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/registrations-list\">https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/registrations-list<\/a><br \/>\n<span style=\"color: #ffffff;\">.<br \/>\n.<br \/>\n<\/span><strong>Analyse :<\/strong><\/p>\n<p>Pensionnaires l\u2019un comme l\u2019autre du Team Rrun Seynod, <strong>Maxime Grenot<\/strong> et<strong>\u00a0<\/strong>le junior<strong> Simon Paccard <\/strong>se disputeront en toute logique la victoire. Leur affrontement devrait \u00eatre de toute beaut\u00e9.<\/p>\n<p>Ces deux purs trailers se sont rencontr\u00e9s pour la premi\u00e8re fois le 8 avril dernier \u00e0 l\u2019occasion du 23,5 du Trail Ch\u00e9ran Semnoz, concouru \u00e0 Gruffy. Victime de d\u00e9shydratation et d\u2019une grosse hypoglyc\u00e9mie, Simon qui faisait course en t\u00eate depuis le d\u00e9part a craqu\u00e9 \u00e0 une borne du but. Il se fera alors d\u00e9poser\u00a0par <strong>Paul Burette<\/strong> puis Maxime, futurs laur\u00e9at et dauphin, lui-m\u00eame se contentant de la 3\u00e8me position. Ce probl\u00e8me alimentaire lui avait d\u00e9j\u00e0 co\u00fbt\u00e9 la 2\u00e8me place en 2017 sur le 14 km de la Gruff\u2019\u00e0 l\u2019Eau, et ce au m\u00eame endroit.<br \/>\nN\u2019emp\u00eache, il respire la grande forme comme en atteste sa prouesse, h\u00e9las sans dossard, sur le 13 bornes de la Voglanaise qui le voyait conclure en m\u00eame temps que le vainqueur espagnol\u00a0<strong>Moa Aarab\u00a0<\/strong>apr\u00e8s avoir saisi les r\u00eanes d\u00e8s l\u2019entame.<\/p>\n<p>La marche restante pourrait revenir \u00e0 un autre pensionnaire du Team Rrun Seynod en la personne de <strong>Samuel Caillet<\/strong>, auteur d\u2019un \u00e9poustouflant d\u00e9but de saison. Toutefois, il devra prendre garde de cet ancien grand cycliste, aujourd\u2019hui quadra, qu\u2019est\u00a0<strong>Nicolas Inaudi<\/strong>.\u00a0Mais aussi de son propre manager, le quinqua <strong>Michel Barralon<\/strong> qui, pas plus tard qu\u2019en f\u00e9vrier dernier, a r\u00e9ussi le tour de force de se qualifier individuellement aux championnats de France de cross-country.<\/p>\n<p>Et que dire de ces deux jeunes pousses, p\u00e9tries de talent, que sont <strong>Dorian Marchal<\/strong>, pote de Paccard au sein de la nouvelle escouade Crazyounguys,\u00a0et<strong> Emilien Grillet<\/strong>, un autre fan de la petite reine mais celui-l\u00e0 cadet. Beaucoup moins exp\u00e9riment\u00e9 que Dorian, Emilien cherchera surtout \u00e0 mieux g\u00e9rer sa cavalcade. Il \u00e9vitera ainsi de r\u00e9p\u00e9ter l\u2019erreur fatale qu\u2019il avait commise il y a un mois \u00e0 Gruffy quand il avait tenu d\u2019embl\u00e9e les manettes du 14 km, et ce en compagnie de l\u2019homme victorieux Moa Aarab, avant d\u2019exploser \u00e0 7 bornes de l\u2019arriv\u00e9e puis de d\u00e9gringoler au 17\u00e8me rang.<\/p>\n<p>Connu pour \u00eatre le coach de Paccard,<strong> Julien Tapiero\u00a0<\/strong>ne devrait certainement pas jouer les faire-valoir. Idem pour le gendarme <strong>Thierry Belzuz<\/strong>, 5\u00e8me en 2016 puis 6\u00e8me en 2017, dont c\u2019est la derni\u00e8re ann\u00e9e en tant que master 1. Ce qui ne l\u2019emp\u00eache pas de r\u00e9aliser encore de belles perfs, \u00e0 l\u2019instar du Trail Ch\u00e9ran Semnoz (4\u00e8me) puis du 35 km du Trail de la Cochette, au Laudon (5\u00e8me).<\/p>\n<p>Hormis 2015, la triathl\u00e8te<strong> Nathalie Peillex<\/strong> est toujours rest\u00e9e fid\u00e8le \u00e0 la Course des Etangs, avec \u00e0 la clef trois succ\u00e8s, dont deux partag\u00e9s avec <strong>Karine Marguerettaz,<\/strong> et cinq 2\u00e8mes places ! Inutile de dire qu\u2019elle sera la grandissime favorite \u00e0 moins que&#8230; Karine ne pointe le bout de son nez \u00e0 l\u2019ultime minute, comme elle en a l\u2019habitude.<\/p>\n<p><strong>F.V.<\/strong><br \/>\n<span style=\"color: #ffffff;\"><strong>.<\/strong><\/span><br \/>\n<strong><span style=\"color: #ffffff;\">.<\/span><br \/>\nFavoris :<\/strong><\/p>\n<p><strong>\u2013 Maxime Grenot<\/strong> (Team Rrun Seynod et ASPTT Annecy Athl\u00e9tisme), n\u00e9 le 22 mai 1989 et demeurant \u00e0 Sevrier.<br \/>\n* 2018 : 26\u00e8me sur les Championnats des Savoie de Cross-Country Hommes ; 2\u00e8me sur le Trail Blanc du Semnoz ; 6\u00e8me sur la F\u00e9e Blanche ; 8\u00e8me sur le 27 km du Trail du Petit Ballon ; 2\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy ; 6\u00e8me sur les 8 h 00 de l\u2019Ultra Mont\u00e9e Thollon-les-M\u00e9mises.<br \/>\n* 2017 : 10\u00e8me sur le Trail de l\u2019Aigle Blanc ; 25\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy ; 4\u00e8me sur le 40 km du Be Run ; 9\u00e8me sur la Verticale Race du Lac d\u2019Annecy ; 3\u00e8me sur la Short-Race du Lac d\u2019Annecy ; 2\u00e8me sur le 22 km de la Cusy\u2019Hard ; 12\u00e8me sur le 29 km du Trail Faverges-Seythenex ; 10\u00e8me sur le Kilom\u00e8tre Vertical de l\u2019Aravis Sky Pursuit ; 4\u00e8me sur le 20 km de l\u2019Aravis Sky Pursuit ; 4\u00e8me sur le 51 km du Trail des Hauts-Forts ; 1er sur le 12 km du Trail Semnoz Tour ; 11\u00e8me sur les Championnats de France de Trail Long ; 2\u00e8me par \u00e9quipe sur le 63 km du Trail des Gli\u00e8res ; 1er sur le 75 km du Grand Trail du Lac ; 20\u00e8me\u00a0\u00e0 Lavy des Cimes ; 2\u00e8me sur le 8 km de la Corrida des Abbesses ; 13\u00e8me sur le 7,3 km de la Corrida des Abbesses.<\/p>\n<p><strong>\u2013 Simon Paccard<\/strong> (Crazyounguys, Team Rrun Seynod et ASPTT Annecy Athl\u00e9tisme), n\u00e9 le 25 juillet 2000 et demeurant \u00e0 Gruffy.<br \/>\n* 2018 : 1er\u00a0sur les Championnats des Savoie de Cross-Country Juniors Hommes ; 3\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Juniors Hommes ; 6\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Juniors Hommes ; 1er sur le 16 km de la Massingienne ; 3\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy ; 1er ex aequo sur le 13 km du Trail Nivolet-Revard (non officiel car sans dossard).<br \/>\n* 2017 : 3\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 6\u00e8me sur la Short-Race du Lac d\u2019Annecy ; 4\u00e8me sur la Young Race Marathon ; 11\u00e8me sur la Youth Chamonix Courmayeur ; 7\u00e8me sur le 15 km du Trail des Aiguilles Rouges ; 1er en \u00e9quipe mixte en 2h33\u201956 pour le compte de l\u2019ASPTT Annecy Athl\u00e9tisme sur l\u2019Ekiden de Grenoble ; 1er sur le 18 km de St Off en Trail ; 1er sur le 17 km de la Run Express de Poisy ; 2\u00e8me sur le D\u00e9fi de Fort-l\u2019Ecluse.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Principaux outsiders masculins :<\/strong><\/p>\n<p><strong>\u2013 Michel Barralon\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme et Team Rrun Seynod), n\u00e9 le 15 juin 1965 et demeurant \u00e0 Moye.<br \/>\n* Course des Etangs : 5\u00e8me en 55\u201941 sur le 15 km en 2017 ; 6\u00e8me en 55\u201902 sur le 15 km en 2016 ; 4\u00e8me en 52\u201957 sur le 15 km en 2014 ; 4\u00e8me en 55\u201926 sur le 15 km en 2011 ; 4\u00e8me en 55\u201959 sur le 15 km en 2009.<br \/>\n* 2018 : 14\u00e8me sur les Championnats des Savoie de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 23\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 57\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country V\u00e9t\u00e9rans Hommes ; 2\u00e8me sur le 10,6 km des Foul\u00e9es de Gruffy ; 7\u00e8me sur le 27 km des Princes en Foul\u00e9es.<br \/>\n* 2017\u00a0: 23\u00e8me sur les Championnats de France de Cross-Country V\u00e9t\u00e9rans 2 Hommes ; 8\u00e8me sur le 46 km du Trail des Recul\u00e9es ; 10\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 7\u00e8me sur le 27 km des Princes en Foul\u00e9es ; 5\u00e8me sur le 15 km de la Course des Etangs ; 63\u00e8me (66\u00e8me avec l\u2019Open Hommes) sur les Championnats de France de Course en Montagne Hommes ; 6\u00e8me sur le 55 km du Trail de la Vall\u00e9e du Lac ; 43\u00e8me sur le 7,6 km du TPS Vertical K2 Villaroger \u2013 Les Arcs ; 61\u00e8me (86\u00e8me avec l\u2019Open) sur les Championnats de France de Kilom\u00e8tre Vertical ; 11\u00e8me sur le 7 km du B\u00e9lier ; 24\u00e8me sur le 27 km du B\u00e9lier ; 17\u00e8me sur le 42 km du B\u00e9lier ; 33\u00e8me (36\u00e8me avec l\u2019Open, 2\u00e8me V2) sur les Championnats de France de Trail Long.<\/p>\n<p><strong>\u2013 Thierry Belzuz<\/strong>\u00a0(Gendarmerie Nationale Seynod), n\u00e9 le 26 septembre 1969 et demeurant \u00e0 Seynod.<br \/>\n* Course des Etangs : 6\u00e8me en 56\u201949 sur le 15 km en 2017 ; 5\u00e8me en 54\u201946 sur le 15 km en 2016.<br \/>\n* 2018 : 1er sur le 42 km du Trail des Fontaines ; 7\u00e8me sur le 27 km de la Massingienne ; 11\u00e8me sur le 16 km de l\u2019Agglocityrun74\u00a0; 4\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy\u00a0; 5\u00e8me sur le 35 km du Trail du Laudon.<br \/>\n* 2017 : 20\u00e8me sur le Trail Blanc du Semnoz ; 7\u00e8me sur le 25 km du Trail Les Collines du Diable ; 3\u00e8me sur le 27 km de la Massingienne ; 17\u00e8me sur le 33 km du Trail des Glaisins ; 4\u00e8me sur le 27 km du Trail du Mont Saint-Michel ; 48\u00e8me sur le 51 km du Trail Nivolet-Revard ; 6\u00e8me sur le 15 km de la Course des Etangs ; 26\u00e8me sur la Maxi-Race du Lac d\u2019Annecy ; 2\u00e8me\u00a0sur le 32 km du Trail du Pays de Serres ; 3\u00e8me sur le 24 km du Trail des Buis ; 3\u00e8me sur le 45 km du Trail Semnoz Tour ; 2\u00e8me sur le 22 km du Trail de Musi\u00e8ges ; 7\u00e8me sur le 22 km du Trail des Gli\u00e8res ; 8\u00e8me\u00a0sur le 30 km de St Off en Trail ; 5\u00e8me sur le 17 km de la Run Express de Poisy ; 9\u00e8me sur le Cross des Glaisins V\u00e9t\u00e9rans Hommes.<\/p>\n<p><strong>\u2013 Samuel Caillet\u00a0<\/strong>(Team Rrun Seynod), n\u00e9 le 8 f\u00e9vrier 1981 et demeurant \u00e0 Saint-Ours.<br \/>\n* Course des Etangs : 6\u00e8me en 29\u201955 sur le 8 km en 2017 ; 7\u00e8me en 56\u201919 sur le 15 km en 2016 ; 7\u00e8me en 28\u201952 sur le 8 km en 2013 ; 3\u00e8me en 55\u201954 sur le 15 km en 2012 ; 1er en 28\u201932 sur le 8 km en 2010.<br \/>\n* 2018 : 4\u00e8me sur le 24 km d\u2019Ocres et Limons de Mormoiron ; 3\u00e8me sur le 14 km du Winter Trail \u00e0 Saint-Pierre-de-Chartreuse ; 4\u00e8me sur le 26,5 km du Belledonne Gelon Trail ; 4\u00e8me sur le 22 km du Trail de Vulcain ; 6\u00e8me sur le 27 km de la Massingienne ; 5\u00e8me sur la Menthonnaise ; 6\u00e8me sur le 33 km du Trail des Glaisins ; 3\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 1er sur les Drailles du Lan\u00e7on ; 4\u00e8me sur le 27 km des Princes en Foul\u00e9es ; 4\u00e8me sur le 35 km du Trail du Laudon ; 6\u00e8me sur le 51 km du Trail Nivolet-Revard.<br \/>\n* 2017\u00a0: 5\u00e8me sur le 23 km de la Nuit du Grand Veymont ; 5\u00e8me sur le 27 km du N\u00eemes Urban Trail\u00a0; 9\u00e8me sur le 24 km de la Course des Fougueurs\u00a0; 13\u00e8me sur le 14 km du Lyon Urban Trail ; 11\u00e8me sur le 23 km des Foul\u00e9es de Gruffy ; 6\u00e8me sur le 8 km de la Course des Etangs ; 9\u00e8me sur le 13,6 km de la Tresservienne ; 14\u00e8me sur le 23 km du Grand Raid 73 ; 95\u00e8me (99\u00e8me avec l\u2019Open Hommes) sur les Championnats de France de Course en Montagne Hommes ; 4\u00e8me sur le 22 km de la Cusy\u2019Hard ; 1er ex aequo sur le 42 km de la Mont\u00e9e du Revard ; 1er sur la Massignolande ; 7\u00e8me sur le KV de Cr\u00e8ve-T\u00eate ; 17\u00e8me sur le 19 km du Mad\u2019Trail ; 45\u00e8me sur le 65 km de la 6000D ; 7\u00e8me sur le 12 km du Trail Semnoz Tour ; 10\u00e8me sur le 22 km du Trail des Gli\u00e8res\u00a0; 1er par \u00e9quipe sur le 21 km de la Chamb\u00e9rienne en duo ; 6\u00e8me sur le 22 km du Trail de Montagnole ; 10\u00e8me sur le 23 km de la Sange\u2019Run ; 16\u00e8me sur la Corrida d\u2019Aix-les-Bains.<\/p>\n<p><strong>\u2013 Emilien Grillet<\/strong>\u00a0(V\u00e9lo Club Rumillien), n\u00e9 le 22 mars 2001 et demeurant \u00e0 Saint-Sylvestre.<br \/>\n* 2018 : 17\u00e8me sur le 14 km des Foul\u00e9es de Gruffy.<br \/>\n* 2017 : 11\u00e8me sur le Trail Blanc du Semnoz ; 72\u00e8me en 36\u201910 sur le 10 km du Lac d\u2019Annecy (record personnel sur 10 bornes).<\/p>\n<p><strong>\u2013 Nicolas Inaudi<\/strong>, n\u00e9 le 21 janvier 1978 et demeurant \u00e0 Brison-Saint-Innocent.<br \/>\n* 2018 : 6\u00e8me en 34\u201924 sur le 10 km de la Course des Fougueurs ; 4\u00e8me sur le 11,7 km de l\u2019Agglocityrun74 ; 35\u00e8me en 34\u201916 sur le 10 km du Grand Lac.<br \/>\n* 2017 : 34\u00e8me en\u00a034\u201948 sur le 10 km du Lac du Bourget ; 7\u00e8me sur le 13,6 km de la Tresservienne ; 8\u00e8me sur le 8 km d\u2019Odyssea Chamb\u00e9ry ; 12\u00e8me sur le Tour du Lac d\u2019Aiguebelette ; 3\u00e8me sur le 12 km de la Gr\u00e9sylienne ; 5\u00e8me sur l\u2019Urban Race Seynod ; 10\u00e8me sur le Barbython ; 32\u00e8me sur la Corrida\u00a0d\u2019Aix-les-Bains.<\/p>\n<p><strong>\u2013 Dorian Marchal <\/strong>(Crazyounguys et Tobesport), n\u00e9 le 12 juillet 1995 et demeurant \u00e0 Bussigny.<br \/>\n* Course des Etangs : 7\u00e8me en 30\u201901 sur le 8 km en 2017.<br \/>\n* 2018 : 1er sur le Cross Populaire Hommes de Lausanne ; 8\u00e8me sur le 23 km du Trail des Cabornis ; 58\u00e8me en 33\u201906 sur le 10 km de Villeurbanne (record personnel sur 10 bornes) ; 6\u00e8me sur le 17 km du Trail des Glaisins ; 23\u00e8me en 1h14\u201949 sur le 20 km de Lausanne ; 8\u00e8me sur les 4 h 00 de l\u2019Ultra Mont\u00e9e Thollon-les-M\u00e9mises.<br \/>\n* 2017 : 12\u00e8me en 1h18\u201904 sur le Semi-Marathon du CEP ; 9\u00e8me sur le 17 km du Trail des Glaisins ; 14\u00e8me en 35\u201928 sur le 10 km du Lac Kir ;\u00a045\u00e8me en 1h12\u201921 sur le 20 km de Lausanne ;\u00a013\u00e8me en 34\u201956 sur le 10 km de Gen\u00e8ve ; 10\u00e8me sur le 13 km de la Chambottine ; 21\u00e8me sur le D\u00e9fi du Vignoble ; 7\u00e8me sur le 8 km de la Course des Etangs ; 6\u00e8me sur le 13,6 km de la Tresservienne ; 119\u00e8me en 36\u201917 sur le 10 km de l\u2019Equipe ; 5\u00e8me sur le 30 km du Montreux Trail Festival ; 26\u00e8me sur la Youth Chamonix Courmayeur ; 1er sur le 30 km du SwissPeaks Trail ; 3\u00e8me sur le 20 km de l\u2019Urbantrail des Singes ; 28\u00e8me en\u00a033\u201959 sur le 10 km du Lac d\u2019Annecy ; 8\u00e8me\u00a0sur le 2,5 km du Trail de Tourrettes-sur-Loup ; 1er ex aequo sur le 30 km du Trail de Tourrettes-sur-Loup ; 2\u00e8me sur le 13 km du Trail des Gli\u00e8res ; 4\u00e8me sur le 20,6 km des D\u00e9fis du Jubil\u00e9 ; 1er sur la Course des Lumi\u00e8res ; 4\u00e8me en 25\u201939\u2019\u20199 sur les Hommes I de la Course de l\u2019Escalade.<\/p>\n<p><strong>\u2013 Julien Tapiero\u00a0<\/strong>(Team Rrun Seynod et La Ronde De Chavanod), n\u00e9 le 30 octobre 1985 et demeurant \u00e0 Gruffy.<br \/>\n* Course des Etangs : 6\u00e8me en 55\u201904 sur le 15 km en 2016.<br \/>\n* 2018 : 3\u00e8me sur le 27 km de la Massingienne ; 14\u00e8me sur le 17 km du Trail des Glaisins ; 4\u00e8me sur le 22 km du Trail de la Mandallaz ; 43\u00e8me sur le 27 km du Trail Nivolet-Revard.<br \/>\n* 2017 : 14\u00e8me sur le Trail Blanc du Semnoz ; 7\u00e8me sur la F\u00e9e Blanche ; 199\u00e8me ex aequo sur le 23 km du Trail des Cabornis ; 12\u00e8me sur le Trail de l\u2019Aigle Blanc ; 21\u00e8me sur le 17 km du Trail des Glaisins ; 2\u00e8me sur le Trail de la Mandallaz ; 4\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 14\u00e8me sur le 48 km du Trail des Coursi\u00e8res ; 30\u00e8me sur la Short-Race du Lac d\u2019Annecy ; 6\u00e8me sur le Trail des Cr\u00eates \u00e0 Saint-Paul-de-Jarrat ; 37\u00e8me sur le Cross du Mont-Blanc ; 54\u00e8me sur le 61 km du Trail du Tour des Fiz ; 168\u00e8me Sur les Traces des Ducs de Savoie ; 10\u00e8me sur le 18 km de St Off en Trail ; 25\u00e8me sur le 26 km du Lyon Urban Trail by Night ; 9\u00e8me sur l\u2019Urban Race Seynod ; 6\u00e8me sur le 17 km de la Run Express de Poisy.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>Autres outsiders masculins :<\/strong><\/p>\n<p><strong>\u2013 Beno\u00eet Berth\u00e9<\/strong>\u00a0(Les Alligators Seynod Triathlon), n\u00e9 le 19 septembre 1982.<br \/>\n* Course des Etangs : 10\u00e8me en 30\u201936 sur le 8 km en 2016 ; 19\u00e8me en 1h01\u201953 sur le 15 km en 2009.<br \/>\n* 2018 : 17\u00e8me sur le 27 km de la Massingienne ; 7\u00e8me sur le 22 km du Trail de la Mandallaz.<br \/>\n* 2017 : 5\u00e8me sur l\u2019Hivernale de M\u00e9audre ; 7\u00e8me en 1h21\u201929 sur le Semi-Marathon du Grand Fond Bressan ; 39\u00e8me en 1h18\u201936 sur le Semi-Marathon de Bourg-en-Bresse ; 7\u00e8me sur les 11 km de Contrevoz ; 5\u00e8me sur le 19 km du Trail du Laudon ; 3\u00e8me sur le 21 km du Trail de Douvres ; 6\u00e8me sur le 13 km de la Chambottine ; 10\u00e8me en 35\u201950 sur le 10 km de Th\u00f4nes ; 9\u00e8me sur le Kilom\u00e8tre Vertical de l\u2019Aravis Sky Pursuit ; 8\u00e8me sur le 20 km de l\u2019Aravis Sky Pursuit ; 4\u00e8me sur le 10 km de la Ronde des Cyclamens ; 5\u00e8me en 2h50\u201922 sur le Marathon International du Beaujolais ; 13\u00e8me sur la Corrida de Chavanod ; 15\u00e8me sur le Cross des Glaisins Hommes.<\/p>\n<p><strong>\u2013 Edouard Claude<\/strong>, n\u00e9 le 20 ao\u00fbt 2000 et demeurant \u00e0 Cusy.<br \/>\n* 2018 : 12\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy.<br \/>\n* 2017 : 19\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 11\u00e8me sur la Short-Race du Lac d\u2019Annecy ; 6\u00e8me sur le 22 km de la\u00a0Cusy\u2019Hard ;\u00a036\u00e8me sur la Youth Chamonix Courmayeur ; 18\u00e8me sur le 15 km du Trail des Aiguilles Rouges ; 5\u00e8me sur le 10 km de la Chamb\u00e9rienne ; 9\u00e8me\u00a0sur le 18 km de St Off en Trail.<\/p>\n<p><strong>\u2013 Emmanuel Maison<\/strong>\u00a0(Rumilly Haute-Savoie Athl\u00e9tisme, section d\u2019Annecy Haute-Savoie Athl\u00e9tisme), n\u00e9 le 15 d\u00e9cembre 1978 et demeurant \u00e0 Rumilly.<br \/>\n* Course des Etangs : 9\u00e8me en 58\u201903 sur le 15 km en 2017 ; 12\u00e8me en 58\u201911 sur le 15 km en 2016 ; 15\u00e8me en 34\u201929 sur le 8 km en 2015 ; 16\u00e8me en 34\u201945 sur le 8 km en 2014 ; 9\u00e8me en 1h00\u201913 sur le 15 km en 2013 ; 18\u00e8me en 30\u201929 sur le 8 km en 2012 ; 7\u00e8me en 59\u201921 sur le 15 km en 2011 ; 11\u00e8me en 59\u201911 sur le 15 km en 2010 ; 13\u00e8me en 59\u201940 sur le 15 km en 2009.<br \/>\n* 2018 : 11\u00e8me sur le 22 km semi-nocturne r\u00e9duit \u00e0 14,5 km de la Course des Fougueurs ; 8\u00e8me sur le 16 km de la Massingienne ; 25\u00e8me sur le 27 km des Princes en Foul\u00e9es ; 19\u00e8me sur le D\u00e9fi de Fort-l\u2019Ecluse.<br \/>\n* 2017 : 18\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 13\u00e8me sur le 13 km de la Chambottine ; 8\u00e8me sur le 13 km de la Cusy\u2019Hard ; 6\u00e8me sur le 10 km de la Savoyarde Trail ; 15\u00e8me sur le 18 km de St Off en Trail.<\/p>\n<p><strong>\u2013 Aubin Perret<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme), n\u00e9 le 7 mars 1997.<br \/>\n* Course des Etangs : 12\u00e8me en 58\u201911 sur le 15 km en 2016 ; 15\u00e8me en 34\u201929 sur le 8 km en 2015 ; 16\u00e8me en 34\u201945 sur le 8 km en 2014.<br \/>\n* 2018 :\u00a043\u00e8me sur les Championnats des Savoie de Cross-Country Hommes\u00a0; 65\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Hommes\u00a0; 131\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Hommes\u00a0; 7\u00e8me sur le 11,7 km de l\u2019Agglocityrun74 ; 19\u00e8me en 1h24\u201915 sur Grenoble Vizille ; 67\u00e8me en\u00a036\u201904 sur le 10 km du Grand Lac (record personnel sur 10 bornes) ; 86\u00e8me en 1h28\u201951 sur le Semi-Marathon du Lac d\u2019Annecy.<br \/>\n* 2017 : 43\u00e8me sur les Championnats des Savoie de Cross-Country Hommes\u00a0; 101\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Hommes\u00a0; 141\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Hommes\u00a0; 11\u00e8me sur la F\u00e9e Blanche ; 11\u00e8me sur le 16 km de la Massingienne ;\u00a065\u00e8me en\u00a036\u201931 sur le 10 km du Lac du Bourget ; 103\u00e8me en 1h27\u201955 sur le Semi-Marathon du Lac d\u2019Annecy ; 10\u00e8me sur le 25 km de la Chambottine ; 34\u00e8me en 1h30\u201910\u00a0sur le Semi-Marathon du Be Run ; 22\u00e8me sur le Kilom\u00e8tre Vertical du Chartreuse Trail Festival ; 40\u00e8me sur le 26 km du Chartreuse Trail Festival ; 56\u00e8me sur le Kilom\u00e8tre Vertical du Mont-Blanc ; 15\u00e8me sur la Young Race Marathon ; 14\u00e8me sur le 38 km de la Sky Race de Montgen\u00e8vre ; 7\u00e8me sur le 11 km du Trail de l\u2019Aigle ; 8\u00e8me sur le 10 km de la Ronde des Cyclamens ; 48\u00e8me sur le 27 km du B\u00e9lier ; 208\u00e8me en\u00a039\u201935 sur le 10 km du Lac d\u2019Annecy ; 50\u00e8me sur Lavy des Cimes ; 11\u00e8me sur le Cross des Glaisins Hommes ; 8\u00e8me sur la Corrida de Bellegarde.<\/p>\n<p><strong>\u2013 Sacha Piccon<\/strong>, n\u00e9 le 31 juillet 1995 et demeurant \u00e0 Massingy.<br \/>\n* 2018 : 9\u00e8me sur le 16 km de la Massingienne.<br \/>\n* 2017 : 36\u00e8me sur les Championnats des Savoie de Cross-Country Hommes\u00a0; 24\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Hommes\u00a0; 61\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Hommes\u00a0; 163\u00e8me sur les Championnats de France de Cross-Country Elite Hommes ; 5\u00e8me sur le 16 km de la Massingienne ; 6\u00e8me sur le 11,7 km de l\u2019Agglocityrun74 ; 11\u00e8me sur l\u2019Urban Race Seynod.<br \/>\n<span style=\"color: #ffffff;\">..<\/span><br \/>\n<span style=\"color: #ffffff;\"> .<\/span><br \/>\n<strong>Favorite :<\/strong><\/p>\n<p><strong>\u2013 Nathalie Peillex\u00a0<\/strong>(Aix Savoie Triathlon), n\u00e9e le 5 ao\u00fbt 1973 et demeurant \u00e0 Aix-les-Bains.<br \/>\n* Course des Etangs :\u00a01\u00e8re femme ex aequo avec Karine Marguerettaz en 1h01\u201937 sur le 15 km en 2017 ; 1\u00e8re femme ex aequo avec\u00a0Karine Marguerettaz en 1h00\u201956 sur le 15 km en 2016 ; 2\u00e8me femme en 1h00\u201916 sur le 15 km en 2014 ; 1\u00e8re femme en 1h02\u201956 sur le 15 km en 2013 ; 1\u00e8re femme en 1h01\u201943 sur le 15 km en 2012 ; 2\u00e8me femme en 1h01\u201952 sur le 15 km en 2011 ; 2\u00e8me femme en 1h01\u201930 sur le 15 km en 2010 ; 2\u00e8me femme en 1h05\u201902 sur le 15 km en 2009.<br \/>\n* 2018 : 1\u00e8re femme sur le 10 km de la Course des Fougueurs ; 1\u00e8re femme sur le 12,6 km de la Chatvoyarde ; 6\u00e8me femme sur la Tartencelloise.<br \/>\n* 2017 : 2\u00e8me femme sur l\u2019Antychoise ; 1\u00e8re femme sur le 12,6 km de la Chatvoyarde ; 2\u00e8me femme sur la Tartencelloise ; 2\u00e8me femme sur le 8 km d\u2019Odyssea Chamb\u00e9ry ; 3\u00e8me femme sur le Tour du Lac d\u2019Aiguebelette ; 4\u00e8me femme sur le 21 km de la Chamb\u00e9rienne ; 1\u00e8re femme sur le 18 km de St Off en Trail ; 2\u00e8me femme sur la Course P\u00e9destre des Hermones ; 3\u00e8me femme sur le Barbython.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nOutsider f\u00e9minin :<\/strong><\/p>\n<p><strong>\u2013 Marie Roupioz<\/strong>, n\u00e9e le 5 avril 1991 et demeurant \u00e0 Boussy.<br \/>\n* Course des Etangs : 9\u00e8me femme en 1h15\u201904 sur le 15 km en 2017 ; 17\u00e8me femme en 1h19\u201928 sur le 15 km en 2016.<br \/>\n* 2018 : 3\u00e8me femme sur le 10,6 km des Foul\u00e9es de Gruffy.<br \/>\n* 2017 : 8\u00e8me femme sur le 10,5 km des Foul\u00e9es de Gruffy ; 20\u00e8me femme sur le 13 km de la Chambottine ; 9\u00e8me femme sur le 15 km de la Course des Etangs ; 6\u00e8me femme sur le 13 km de la Cusy\u2019Hard ; 12\u00e8me femme sur l\u2019Urban Race Seynod ; 64\u00e8me femme en 44\u201954 sur le 10 km de V\u00e9nissieux.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPRONOSTICS SUR LE 8 KM :<br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>Records \u00e0 battre sur le parcours emprunt\u00e9 en 2009-2010 et depuis 2014 :<\/strong><\/p>\n<p>\u2013 Participation : <strong>238\u00a0inscrits<\/strong> en 2017.<br \/>\n\u2013 Hommes : <b>Stany Paumier<\/b>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien) en <strong>27\u201926\u00a0<\/strong>en 2017.<br \/>\n\u2013 Femmes : <strong>Alexandra Chambard\u00a0<\/strong>(Athl\u00e9 Saint-Julien 74) en<strong>\u00a034\u201902\u00a0<\/strong>en 2014. <span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<br \/>\n.<strong><br \/>\n<\/strong><\/span><strong>Liste des inscrits :<\/strong><\/p>\n<p>Elle figure sur le site Web L-Chrono :<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/registrations-list\">https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/registrations-list<\/a><br \/>\n<span style=\"color: #ffffff;\">.<br \/>\n.<br \/>\n<\/span><strong>Analyse :<\/strong><\/p>\n<p>A l\u2019image du mano a mano opposant\u00a0<strong>Maxime Grenot<\/strong> \u00e0 <strong>Simon Paccard\u00a0<\/strong>sur le 15 km, un autre duel s\u2019annonce particuli\u00e8rement ind\u00e9cis sur le 8 bornes : celui auquel se livreront <strong>Ludovic Baur<\/strong> et <strong>Arnaud Deletraz<\/strong>. Ind\u00e9cis car ces deux magnifiques athl\u00e8tes d\u00e9tiennent quasiment le m\u00eame chrono r\u00e9f\u00e9rence sur 10 km : 32\u201933 pour Ludo en avril 2018, 32\u201930 pour Arnaud mais en avril 2014. S\u2019ils se boostent mutuellement, ils pourraient bien s\u2019approcher du record de cette comp\u00e8te, port\u00e9 l\u2019an pass\u00e9 \u00e0 27\u201926 par <strong>Stany Paumier<\/strong>\u00a0qui avait mis \u00e0 profit le terrain sec mais aussi la pr\u00e9sence d\u2019un redoutable adversaire, \u00e0 savoir le Marocain <strong>Anas Saaidou<\/strong>\u00a0qui ne d\u00e9crochera qu\u2019\u00e0 400 m de la ligne.<\/p>\n<p>Sinon, un autre jeunot, en dehors de Paccard et de Grillet, pourrait s\u2019illustrer : le cadet, et orienteur, <strong>Louis Parent<\/strong>, 8\u00e8me sur le pr\u00e9c\u00e9dent opus.\u00a0Ce ph\u00e9nom\u00e8ne avait d\u00e9j\u00e0 fait un tabac le 18 novembre dernier apr\u00e8s avoir termin\u00e9 2\u00e8me du 9,8 km de la Run Express de Poisy. Seul le renomm\u00e9\u00a0<strong>Christophe Cicero<\/strong> s\u2019\u00e9tait av\u00e9r\u00e9 plus rapide que lui mais pour&#8230; seulement 8 petites secondes !<\/p>\n<p>S\u2019attacheront \u00e0 contrarier les ambitions affich\u00e9es par Louis : tout d\u2019abord,\u00a0<strong>Paul Chauvetet<\/strong> qui vient de boucler le 10 bornes de Villeurbanne\u00a0en 34\u201913, soit une seconde de plus que son temps \u00e9talon remontant \u00e0 2014. Ensuite, le triathl\u00e8te <strong>Cl\u00e9ment B\u00e9chet<\/strong>, fort de sa 5\u00e8me place, engrang\u00e9e la saison derni\u00e8re.<\/p>\n<p>On soulignera avec bonheur la participation de l\u2019embl\u00e9matique\u00a0<strong>Christophe Assailly <\/strong>qui depuis trois ans cavale uniquement pour le plaisir, sans aucun objectif. Except\u00e9 cependant cette ann\u00e9e o\u00f9 il a l\u2019intention de partir \u00e0 la d\u00e9couverte de la spartan race en s\u2019engageant sur quelques comp\u00e8tes. Raison pour laquelle il s\u2019est inscrit sur ce 8 km afin de recouvrer un certain niveau.<\/p>\n<p>5\u00e8me en 2016 puis 4\u00e8me en 2017, <strong>Anne Michel<\/strong> aura la faveur des pronostics. Cette Annemassienne de souche qui a un coeur \u00e9norme a sensiblement progress\u00e9 l\u2019an pass\u00e9, comme en t\u00e9moigne sa nouvelle marque r\u00e9f\u00e9rence sur 10 bornes, accomplie en\u00a041\u201928 le 29 octobre \u00e0 Lausanne. Soit 2\u201920 de gagn\u00e9es par rapport \u00e0 2016 sur ce m\u00eame 10 km.<br \/>\nSinon,<strong> Nathalie Vincent<\/strong> comme <strong>Alexandra Cuttaz<\/strong>\u00a0ont le potentiel pour grimper sur la bo\u00eete.<\/p>\n<p><strong>F.V.<br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nFavoris :<\/strong><\/p>\n<p><strong>\u2013 Ludovic Baur<\/strong> (Team Rrun Seynod et Athl\u00e9tique Sport Aixois), n\u00e9 le 22 mai 1989 et demeurant \u00e0 Massingy.<br \/>\n* Course des Etangs : 2\u00e8me en 51\u201942 sur le 15 km en 2016.<br \/>\n* 2018 : 27\u00e8me sur les Championnats des Savoie de Cross-Country Hommes\u00a0; 9\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Hommes\u00a0; 42\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Hommes\u00a0; 136\u00e8me sur les Championnats de France de Cross-Country Elite Hommes ; 15\u00e8me en\u00a032\u201933 sur le 10 km du Grand Lac (record personnel sur 10 bornes).<br \/>\n* 2017 : 4\u00e8me en 1h13\u201949 sur le Semi-Marathon des Lacs du Sud (Nouvelle-Z\u00e9lande, record personnel sur semi) ; 3\u00e8me sur le 25km de la Chambottine ; 7\u00e8me par \u00e9quipe sur la R-Race Relais de 2 du Lac d\u2019Annecy ; 2\u00e8me sur le 13 km de la Cusy\u2019Hard ; 4\u00e8me sur la Mont\u00e9e du Cr\u00eat d\u2019Eau ; 6\u00e8me sur la Ronde de Chavanod ; 13\u00e8me sur la Corrida d\u2019Aix-les-Bains.<\/p>\n<p><strong>\u2013 Arnaud Deletraz\u00a0<\/strong>(Salomon Running), n\u00e9 le 19 juillet 1986 et demeurant \u00e0 Annecy.<br \/>\n* 2018 : 3\u00e8me sur le 23 km du Trail des Cabornis ; 1er sur le 16 km de l\u2019Agglocityrun74.<br \/>\n* 2017 : 15978\u00e8me en 1h53\u201930 sur le Semi-Marathon de Paris ; 2\u00e8me sur le 11,7 km de l\u2019Agglocityrun74 ; 59\u00e8me en 2h33\u201908 sur le Marathon de Paris (record personnel sur marathon) ; 4\u00e8me en \u00e9quipe mixte sur la R-Race Relais de 4 du Lac d\u2019Annecy ; 40\u00e8me\u00a0sur les Championnats de France de Course en Montagne Hommes ; 52\u00e8me en 2h58\u201915 sur la Course Sierre-Zinal ; 4\u00e8me sur le 12 km de la Machu\u2019Run ; 24\u00e8me sur le Grand Trail des Templiers.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Principaux outsiders masculins :<\/strong><\/p>\n<p><strong>\u2013 Christophe Assailly<\/strong>, n\u00e9 le<strong>\u00a0<\/strong>21 juillet 1971 et demeurant \u00e0 Manigod.<br \/>\n* 2016 : 3\u00e8me sur les Championnats des Savoie de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 16\u00e8me sur les Championnats Rh\u00f4ne-Alpes de Cross-Country V\u00e9t\u00e9rans Hommes ; 20\u00e8me sur les Championnats Centre-Est de Cross-Country V\u00e9t\u00e9rans Hommes ; 1er sur le Trail de l\u2019Aigle Blanc ; 12\u00e8me en 34\u201935 sur le 10 km de Grignon.<\/p>\n<p><strong>\u2013 Cl\u00e9ment B\u00e9chet <\/strong>(Aix Savoie Triathlon), n\u00e9 le 1er octobre 1996 et demeurant \u00e0 H\u00e9ry-sur-Alby.<strong><br \/>\n<\/strong>* Course des Etangs : 5\u00e8me en 29\u201952 sur le 8 km en 2017.<br \/>\n* 2018 : 4\u00e8me sur le 16 km de la Massingienne ; 6\u00e8me sur le 14 km des Foul\u00e9es de Gruffy.<br \/>\n* 2017 : 11\u00e8me sur le 14 km des Foul\u00e9es de Gruffy ; 5\u00e8me sur le 8 km de la Course des Etangs ; 3\u00e8me sur le 13 km de la Cusy\u2019Hard.<\/p>\n<p><strong>\u2013 Paul Chauvetet<\/strong> (Team Rrun Seynod), n\u00e9 le 9 novembre 1994 et demeurant \u00e0 Rumilly.<br \/>\n* Course des Etangs : 8\u00e8me en 57\u201926 sur le 15 km en 2015.<br \/>\n* 2018 : 7\u00e8me en 35\u201928 sur le 10 km de la Course des Fougueurs ; 91\u00e8me en 34\u201913 sur le 10 km de Villeurbanne.<br \/>\n* 2017 : 137\u00e8me en\u00a035\u201931 sur le 10 km de V\u00e9nissieux ; 11\u00e8me sur la Corrida de Chavanod.<\/p>\n<p><strong>\u2013 Louis Parent <\/strong>(Annecy Sports Orientation), n\u00e9 le 31 juillet 2001 et demeurant \u00e0 Dingy-Saint-Clair.<br \/>\n* Course des Etangs : 8\u00e8me en 30\u201908 sur le 8 km en 2017.<br \/>\n* 2017 : 8\u00e8me sur le 8 km de la Course des Etangs ; 17\u00e8me par \u00e9quipe sur la R-Race Relais de 4 du Lac d\u2019Annecy ; 5\u00e8me sur le 15 km du B\u00e9lier ; 5\u00e8me sur le 13 km du Trail des Gli\u00e8res ; 2\u00e8me sur le 9,8 km de la Run Express de Poisy.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Autres outsiders masculins :<\/strong><\/p>\n<p><strong>\u2013<\/strong>\u00a0<b>Alexandre Cuttaz<\/b> (ASPTT Annecy Athl\u00e9tisme), n\u00e9 le 26 avril 1975 et demeurant \u00e0 Cuvat.<br \/>\n* Course des Etangs : 14\u00e8me en 32\u201937 sur le 8 km en 2017 ; 3\u00e8me en 30\u201904 sur le 8 km en 2014.<br \/>\n* 2018 :\u00a020\u00e8me sur les Championnats des Savoie de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 39\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 87\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 19\u00e8me sur le 11,7 km de l\u2019Agglocityrun74.<br \/>\n* 2017 : 24\u00e8me sur les Championnats des Savoie de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 46\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 115\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 496\u00e8me en 1h42\u201929 sur le Semi-Marathon du Lac d\u2019Annecy ; 14\u00e8me sur le 8 km de la Course des Etangs ; 9\u00e8me sur le 13 km de la Cusy\u2019Hard ; 11\u00e8me sur le 7,6 km de la Ronde de la Presqu\u2019\u00eele du L\u00e9man ; 9\u00e8me sur le 10 km de la Ronde des Cyclamens ; 92\u00e8me en 36\u201957 sur le 10 km du Lac d\u2019Annecy ; 80\u00e8me en 1h20\u201941 sur le Semi-Marathon de Lyon ; 21\u00e8me par \u00e9quipe en 2h46\u201905 pour le compte de l\u2019ASPTT Annecy Athl\u00e9tisme sur l\u2019Ekiden de Grenoble ; 22\u00e8me sur le 9,7 km du Cross du Laudon.<\/p>\n<p><strong>\u2013 Gilles Farina\u00a0<\/strong>(Faucigny Athl\u00e9tic Club), n\u00e9 le 4 mars 1959 et demeurant \u00e0 Thyez.<br \/>\n* 2018 : 30\u00e8me sur\u00a0le D\u00e9fi de Fort-l\u2019Ecluse.<br \/>\n* 2017 : 32\u00e8me sur les Foul\u00e9es Blanches des Brasses ; 13\u00e8me en 40\u201900 sur le 10 km de la Vente des Vins des Hospices de Nuits-Saint-Georges ; 26\u00e8me en 36\u201914 sur le 10 km de Cluses ; 26\u00e8me sur le 6 km de l\u2019Ultra Tour du M\u00f4le ; 110\u00e8me (117\u00e8me avec l\u2019Open Hommes) sur les Championnats de France de Course en Montagne Hommes ; 13\u00e8me sur l\u2019Assaut des M\u00e9mises ; 50\u00e8me sur le 23 km du Cross du Mont-Blanc ; 8\u00e8me\u00a0sur le 7,6 km de la Ronde de la Presqu\u2019\u00eele du L\u00e9man ; 12\u00e8me sur la Grimp\u00e9e du M\u00f4le ; 19\u00e8me sur la Mont\u00e9e du Cr\u00eat d\u2019Eau ; 29\u00e8me sur le 27 km du B\u00e9lier ; 20\u00e8me sur le 13,5 km de la Ventre \u00e0 Terre ; 11\u00e8me sur les Foul\u00e9es Maglanchardes ; 15\u00e8me sur la Grimp\u00e9e du Pays Rochois ; 8\u00e8me sur le 11 km de la Course de la Saint-Bruno ; 14\u00e8me sur le 15 km du Trail du Massif des Brasses ; 13\u00e8me sur la Persjussienne ; 4\u00e8me \u00e9quipe mixte en 2h49\u201907 pour le compte du Faucigny Athl\u00e9tic Club sur l\u2019Ekiden de Grenoble.<\/p>\n<p><strong>\u2013 David Larrieu\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), n\u00e9 le 12 juillet 1984 et demeurant \u00e0 Viuz-la-Chi\u00e9saz.<br \/>\n* Course des Etangs : 11\u00e8me en 57\u201947 sur le 15 km en 2016 ; 12\u00e8me en 29\u201939 sur le 8 km en 2013.<br \/>\n* 2018 : 84\u00e8me\u00a0sur les Championnats des Savoie de Cross-Country Hommes ; 60\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Court Hommes ; 129\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Court Hommes ; 26\u00e8me sur la F\u00e9e Blanche ; 15\u00e8me sur le 16 km de la Massingienne ; 93\u00e8me en\u00a037\u201908 sur le 10 km du Grand Lac ; 93\u00e8me sur le 27 km du Trail Nivolet-Revard.<br \/>\n* 2017 : 127\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Hommes ; 157\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Hommes ; 47\u00e8me sur le 24 km de la Course des Fougueurs ; 54\u00e8me sur le 22 km du Trail des Recul\u00e9es ; 56\u00e8me sur le 23,5 km des Foul\u00e9es de Gruffy ;\u00a0141\u00e8me en 1h29\u201945 sur le Semi-Marathon du Lac d\u2019Annecy ; 6\u00e8me en \u00e9quipe mixte sur le relais de 2 de la Vela Corsa ; 54\u00e8me sur le 22 km de la Cusy\u2019Hard ; 1103\u00e8me sur le Marathon du Mont-Blanc ; 458\u00e8me en 3h20\u201930 sur le Marathon des Alpes-Maritimes Nice-Cannes ; 92\u00e8me sur Lavy des Cimes.<\/p>\n<p><strong>\u2013 Nicolas Tournier<\/strong>, n\u00e9 le 23 avril 1974 et demeurant \u00e0 Aoste (d\u00e9partement de l\u2019Is\u00e8re).<br \/>\n* Course des Etangs : 10\u00e8me en 30\u201949 sur le 8 km en 2017 ; 6\u00e8me en 30\u201914 sur le 8 km en 2016 ; 5\u00e8me en 30\u201951 sur le 8 km en 2015 ; 6\u00e8me en 30\u201953 sur le 8 km en 2014 ; 14\u00e8me en 29\u201939 sur le 8 km en 2012.<br \/>\n* 2018 : 2\u00e8me sur le 5 km du Tour P\u00e9destre de Saint-Jean-de-Moirans ; 8\u00e8me sur les 11 km de Contrevoz ; 3\u00e8me sur le 10 km du Run\u2019Cugnot ; 24\u00e8me en 36\u201912 sur le 10 km de Chassieu.<br \/>\n* 2017 : 73\u00e8me en 36\u201922 sur le 10 km de Moirans ; 20\u00e8me en 36\u201929 sur le 10 km de Grignon ; 10\u00e8me sur le 8 km de la Course des Etangs ; 2\u00e8me sur le 5 km de la Ronde des Couleurs ; 4\u00e8me sur le 10 km de la St-Albanaise ; 5\u00e8me sur le 5 km des Courses de la Rosi\u00e8re ; 12\u00e8me sur le 10 km de la Run In 2 Mure ; 7\u00e8me en 37\u201957 sur le 10 km du Val Gelon ; 8\u00e8me en 35\u201947 sur le 10 km de la Foire de Savoie ; 11\u00e8me sur le 12 km de la Gr\u00e9sylienne ; 1er sur le 9 km du Cross des Ma\u00efs ; 13\u00e8me sur le 11 km de la Corrida de Sassenage ; 14\u00e8me sur le Barbython.<\/p>\n<p><strong>\u2013 Pierre-Antoine Vatinel\u00a0<\/strong>(Arve Athl\u00e9tisme Bonneville Pays Rochois, section de l\u2019Entente Athl\u00e9tique de l\u2019Arve), n\u00e9 le 23 avril 1971 et demeurant \u00e0 La Roche-sur-Foron.<br \/>\n* Course des Etangs : 12\u00e8me en 30\u201953 sur le 8 km en 2016.<br \/>\n* 2018 : 79\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country V\u00e9t\u00e9rans Hommes ; 8\u00e8me sur le 13 km du Trail du Laudon.<br \/>\n* 2017 : 22\u00e8me sur les Championnats des Savoie de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 55\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 90\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country V\u00e9t\u00e9rans Hommes\u00a0; 10\u00e8me sur la Menthonnaise ; 6\u00e8me sur le 7,6 km de la Cape\u00e7one ; 5\u00e8me sur le 13 km du Trail du Gypa\u00e8te ; 3107\u00e8me en 1h10\u201909 sur le 10 km du Lac d\u2019Annecy ; 47\u00e8me sur la Course P\u00e9destre des Hermones ; 20\u00e8me sur le 9,7 km du Cross du Laudon.<\/p>\n<p><strong>&#8211; Florian Zuccalli<\/strong>\u00a0(Les Princes en Foul\u00e9es),\u00a0n\u00e9 le 28 octobre 1989 et demeurant \u00e0 Seyssel (Haute-Savoie).<br \/>\n* Course des Etangs : 24\u00e8me en\u00a034\u201914 sur le 8 km en 2017.<br \/>\n* 2018 : 14\u00e8me sur le 22 km semi-nocturne r\u00e9duit \u00e0 14,5 km de la Course des Fougueurs ; 11\u00e8me sur le 16 km de la Massingienne ; 5\u00e8me sur le 12 km du Trail de la Michaille ; 37\u00e8me sur le D\u00e9fi de Fort-l\u2019Ecluse.<br \/>\n* 2017 : 22\u00e8me en 38\u201911 sur le 10 km de la Course des Fougueurs ; 22\u00e8me sur le 16 km de la Massingienne ; 10\u00e8me sur le 12 km du Trail des Glaisins ; 32\u00e8me sur le 13 km de la Chambottine ; 24\u00e8me sur le 8 km de la Course des Etangs ; 227\u00e8me (52\u00e8me sur l\u2019Open Hommes) sur les Championnats de France de Course en Montagne Hommes ; 17\u00e8me sur les Foul\u00e9es Enthousiastes ; 15\u00e8me sur le 11 km du Trail de Musi\u00e8ges ; 43\u00e8me sur le Trail de la Valserine ; 17\u00e8me sur le Cross de la Semine ; 33\u00e8me sur le D\u00e9fi de Fort-l\u2019Ecluse.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Favorite :<\/strong><\/p>\n<p><strong>\u2013<\/strong>\u00a0<b>Anne Michel<\/b> (Thonon Athl\u00e9tic Club), n\u00e9e le 17 janvier 1974 et demeurant \u00e0 Annemasse.<br \/>\n* Course des Etangs : 4\u00e8me femme en 37\u201956 sur le 8 km en 2017 ; 5\u00e8me femme en 38\u201925 sur le 8 km en 2016<br \/>\n* 2018 : 27\u00e8me femme en 41\u201954 sur le 10 km du Grand Lac ; 16\u00e8me femme en 42\u201939 sur le 10 km de Lausanne dans le cadre du 20 km de Lausanne.<br \/>\n* 2017 : 60\u00e8me femme en 44\u201958 sur le 10 km de Lausanne dans le cadre du 20 km de Lausanne ; 4\u00e8me femme sur le 8 km de la Course des Etangs ; 2\u00e8me femme sur le 6 km de la Cusy\u2019Hard ; 6\u00e8me femme sur le 10 km du Mont-Blanc ; 2\u00e8me femme sur le 7,6 km de la Ronde de la Presqu\u2019\u00eele du L\u00e9man ; 4\u00e8me femme en 43\u201903 sur le 10 km de Th\u00f4nes ; 5\u00e8me femme sur le 5 km de la Montheysanne ; 79\u00e8me femme en 1h31\u201953 sur le 20 km International Marseille Cassis ; 41\u00e8me femme en 41\u201928 sur le 10 km de Lausanne dans le cadre du Marathon de Lausanne (record personnel sur 10 bornes) ; 10\u00e8me en 20\u201948 sur les Femmes III de la Course de l\u2019Escalade ; 5\u00e8me femme sur la Corrida de Bellegarde.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>Outsiders f\u00e9minins :<\/strong><\/p>\n<p><strong>\u2013<\/strong>\u00a0<b>Alexandra Cuttaz<\/b> (ASPTT Annecy Athl\u00e9tisme), n\u00e9e le 14 juin 1969 et demeurant \u00e0 Cuvat.<br \/>\n* Course des Etangs : 5\u00e8me femme en 38\u201933 sur le 8 km en 2017 ; 12\u00e8me femme en 40\u201932 sur le 8 km en 2016 ; 12\u00e8me femme en 41\u201902 sur le 8 km en 2014.<br \/>\n* 2018 : 93\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Femmes\u00a0; 148\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Femmes\u00a0; 7\u00e8me femme sur le 11,7 km de l\u2019Agglocityrun74.<br \/>\n* 2017 : 69\u00e8me sur les Championnats des Savoie de Cross-Country Femmes\u00a0; 82\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes Est de Cross-Country Elite Femmes ; 150\u00e8me sur les Championnats Auvergne-Rh\u00f4ne-Alpes de Cross-Country Elite Femmes\u00a0; 176\u00e8me en 1h42\u201905 sur les Championnats de France de Semi-Marathon Femmes ; 37\u00e8me femme en 45\u201910 sur le 10 km du Lac du Bourget ; 37\u00e8me femme en 1h42\u201928 sur le Semi-Marathon du Lac d\u2019Annecy ; 5\u00e8me femme sur le 8 km de la Course des Etangs ; 10\u00e8me femme sur le 13 km de la Cusy\u2019Hard ; 3\u00e8me femme sur le 7,6 km de la Ronde de la Presqu\u2019\u00eele du L\u00e9man ; 3\u00e8me femme sur le 10 km de la Ronde des Cyclamens ; 35\u00e8me femme en 44\u201907 sur le 10 km du Lac d\u2019Annecy (record personnel sur 10 bornes) ; 39\u00e8me femme en 1h38\u201939 sur le Semi-Marathon de Lyon (record personnel sur semi) ; 6\u00e8me en \u00e9quipe mixte en 2h49\u201922 pour le compte de l\u2019ASPTT Annecy Athl\u00e9tisme sur l\u2019Ekiden de Grenoble ; 10\u00e8me femme sur le 9,7 km du Cross du Laudon.<\/p>\n<p><strong>\u2013 Nathalie Vincent\u00a0<\/strong>(Annecy-le-Vieux Of Course), n\u00e9e le 4 ao\u00fbt 1970.<br \/>\n* Course des Etangs : 3\u00e8me femme en 38\u201936 sur le 8 km en 2015 ; 4\u00e8me femme en 38\u201917 sur le 8 km en 2014 ; 12\u00e8me femme en 1h17\u201951 sur le 15 km en 2013.<br \/>\n* 2017 : 5\u00e8me femme sur le 16 km de l\u2019Agglocityrun74.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPALMARES DEPUIS 2009\u00a0:<\/strong><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>3 mai 2009\u00a0:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(185 class\u00e9s dont 34 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>S\u00e9bastien Couval<\/strong>\u00a0(Team Mermillod Triathlon) en 54\u201921.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 21\u00e8me au scratch)\u00a0:\u00a0<strong>Karine Marguerettaz<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 1h02\u201911.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web des Alligators Seynod Triathlon :<br \/>\n<a href=\"http:\/\/www.lesalligators-triathlon.fr\/wp-content\/uploads\/2013\/10\/15kmscratch.pdf\">http:\/\/www.lesalligators-triathlon.fr\/wp-content\/uploads\/2013\/10\/15kmscratch.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(166 class\u00e9s dont 58 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Manuel Inacio<\/strong>\u00a0(Annecy-le-Vieux Of Course) en\u00a028\u201923.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 35\u00e8me au scratch)\u00a0:\u00a0<strong>Candice Buosi<\/strong>\u00a0(Athl\u00e9tique Sport Mo\u00fbtiers) en 36\u201917.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web Le-Sportif.com :<br \/>\n<a href=\"http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif225_pub07052009_course_des_etangs_8km.pdf\">http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif225_pub07052009_course_des_etangs_8km.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n2 mai 2010<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(207 class\u00e9s dont 47 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>David Marsan<\/strong>\u00a0(La Motte-Servolex) en 53\u201935.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 18\u00e8me au scratch)\u00a0:\u00a0<strong>Sandrine Motto-Ros<\/strong>\u00a0(Annecy-le-Vieux Of Course) en 1h01\u201907.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la Course des Etangs\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%20scratch%202010.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%20scratch%202010.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(163 class\u00e9s dont 64 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Samuel Caillet<\/strong>\u00a0(Athl\u00e9tique Sport Aixois) en 28\u201932.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 36\u00e8me au scratch)\u00a0:\u00a0<strong>Martine Vergas<\/strong>\u00a0(La Biolle) en 35\u201957.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la Course des Etangs\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%20scratch%202010.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%20scratch%202010.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n1er mai 2011<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(173 class\u00e9s dont 34 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Abdesalam Kiday<\/strong>\u00a0(Maroc, Athl\u00e9 Saint-Julien 74) en 51\u201919.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 18\u00e8me au scratch)\u00a0:\u00a0<strong>Karine Marguerettaz<\/strong>\u00a0(Seynod) en 1h01\u201910.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la Course des Etangs\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km_%20scratch_2011.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km_%20scratch_2011.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(168 class\u00e9s dont 60 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Camille Laroche<\/strong>\u00a0(Les Alligators Seynod Triathlon) en 27\u201918.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 18\u00e8me au scratch)\u00a0:\u00a0<strong>Isaline Thibon<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 31\u201919.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web de la Course des Etangs\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km_%20scratch_2011.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km_%20scratch_2011.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n29 avril 2012<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(167 inscrits, 164 class\u00e9s dont 46 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Michel Juillard<\/strong>\u00a0(Athl\u00e9tic Club Ch\u00e2tenois-les-Forges Athl\u00e9tisme) en 50\u201936.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 15\u00e8me au scratch)\u00a0:\u00a0<strong>Nathalie Peillex<\/strong>\u00a0(Aix Savoie Triathlon) en 1h01\u201943.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web VotreCourse.com\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%202012.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%202012.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(176 inscrits, 167 class\u00e9s dont 60 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Abdesalam Kiday<\/strong>\u00a0(Maroc, La Foul\u00e9e d\u2019Annemasse) en 25\u201945.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 25\u00e8me au scratch)\u00a0:\u00a0<strong>Alexandra Chambard<\/strong>\u00a0(Les Alligators Seynod Triathlon) en 32\u201931.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web VotreCourse.com\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%202012.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%202012.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n5 mai 2013<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(200 inscrits, 196 class\u00e9s dont 41 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:<strong>\u00a0Jean-Baptiste Faivre<\/strong>\u00a0(GoodPeopleRun) en 56\u201924.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 11\u00e8me au scratch)\u00a0:\u00a0<strong>Karine Marguerettaz<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 1h00\u201936.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web VotreCourse.com\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%202013.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/15km%202013.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(193 inscrits, 187 class\u00e9s dont 69 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Eric Carassus<\/strong>\u00a0(Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) en 26\u201927.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 33\u00e8me au scratch)\u00a0:\u00a0<strong>Corinne Leclerc<\/strong>\u00a0(Belley Sport P\u00e9destre) en 33\u201949.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web VotreCourse.com\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%202013.pdf\">http:\/\/www.coursedesetangs.fr\/wp-content\/themes\/etang\/images\/pdf\/8km%202013.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n4 mai 2014<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(143 inscrits, 141 class\u00e9s dont 23 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Nabil Bouchelaghem<\/strong>\u00a0(Athl\u00e9tique Sport Aixois) en 51\u201933.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 17\u00e8me au scratch)\u00a0:\u00a0<strong>Karine Marguerettaz<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en\u00a0<strong>58\u201959, record du parcours emprunt\u00e9 en 2009-2010 et depuis 2014<\/strong>.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web L-Chrono\u00a0:<br \/>\n<a href=\"http:\/\/www.l-chrono.com\/resultats2014\/etangs_15km.pdf\">http:\/\/www.l-chrono.com\/resultats2014\/etangs_15km.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(180 inscrits, 170 class\u00e9s dont 75 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>Ouaid Bouchelaghem<\/strong>\u00a0(Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) en 29\u201909.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 9\u00e8me au scratch)\u00a0:\u00a0<strong>Alexandra Chambard<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en\u00a0<strong>34\u201902, record du parcours emprunt\u00e9 en 2009-2010 et depuis 2014<\/strong>.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web L-Chrono\u00a0:<br \/>\n<a href=\"http:\/\/www.coursedesetangs.fr\/wp-content\/uploads\/2013\/12\/8-km.pdf\">http:\/\/www.l-chrono.com\/resultats2014\/etangs_8km.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>3 mai 2015<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(137 inscrits, 129 class\u00e9s dont 29 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Laurent Marconnet<\/strong>\u00a0(Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) en\u00a050\u201947.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 18\u00e8me au scratch)\u00a0:\u00a0<strong>Murielle Grillet<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 1h01\u201938.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web Le-Sportif.com :<br \/>\n<a href=\"http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif571_pub07052015_st_felix_15_km.pdf\">http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif571_pub07052015_st_felix_15_km.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(180 inscrits, 173 partants, 172 class\u00e9s dont 63 femmes)\u00a0:<br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<strong>S\u00e9bastien Bernardo<\/strong>\u00a0(Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) en 29\u201927.<br \/>\n\u2013 1\u00e8re (1\u00e8re V1, 20\u00e8me au scratch)\u00a0:<strong>\u00a0Birgit Ortega<\/strong>\u00a0(Allemagne, ASPTT Annecy Athl\u00e9tisme) en 35\u201901.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web Le-Sportif.com :<br \/>\n<a href=\"http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif292_pub07052015_st_felix_8_km.pdf\">http:\/\/resultats.le-sportif.com\/fichiers_resultats\/lesportif292_pub07052015_st_felix_8_km.pdf<\/a><a href=\"http:\/\/www.l-chrono.com\/resultats2015\/course_des_etangs_8.pdf\"><br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n1er mai 2016<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0(198 inscrits, 192 class\u00e9s dont 44 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Laurent Marconnet<\/strong>\u00a0(Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) en\u00a051\u201935.<br \/>\n\u2013 1\u00e8re ex aequo (1\u00e8re V1 ex aequo, 27\u00e8me au scratch ex aequo)\u00a0:\u00a0<b>Nathalie Peillex<\/b>\u00a0(Aix Savoie Triathlon) en 1h00\u201956.<br \/>\n\u2013 1\u00e8re ex aequo (1\u00e8re V1 ex aequo, 27\u00e8me au scratch ex aequo)\u00a0:\u00a0<b>Karine Marguerettaz\u00a0<\/b>(ASPTT Annecy Athl\u00e9tisme) en 1h00\u201956.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web Courzyvite :<br \/>\n<a href=\"http:\/\/www.l-chrono.com\/resultats2016\/course_des_etangs_15.pdf\">http:\/\/www.l-chrono.com\/resultats2016\/course_des_etangs_15.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0(217 inscrits, 202 class\u00e9s dont 80 femmes)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<b>J\u00e9r\u00f4me Tissier<\/b>\u00a0(Team Technicien du Sport Seynod) en 27\u201954.<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 34\u00e8me au scratch)\u00a0:<strong>\u00a0Aur\u00e9lie Perret<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 34\u201916.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web L-Chrono :<br \/>\n<a href=\"http:\/\/www.l-chrono.com\/resultats2016\/course_des_etangs_8.pdf\">http:\/\/www.l-chrono.com\/resultats2016\/course_des_etangs_8.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong>14 mai 2017<\/strong>\u00a0<strong>:<\/strong><\/p>\n<p><strong>15 km<\/strong>\u00a0<strong>(249 inscrits, 235 partants dont 72 femmes, 235 class\u00e9s dont 72 femmes, record de participation)\u00a0:<\/strong><br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Lhoussine Boussague<\/strong>\u00a0(Maroc, Annecy Haute-Savoie Athl\u00e9tisme et Wifaq Sportive Athletic Chichaoua) en\u00a0<strong>49\u201943,<\/strong>\u00a0<strong>record du parcours emprunt\u00e9 en 2009-2010 et depuis 2014<\/strong>.<br \/>\n\u2013 1\u00e8re ex aequo (1\u00e8re V1 ex aequo, 21\u00e8me au scratch ex aequo)\u00a0:\u00a0<b>Nathalie Peillex<\/b>\u00a0(Aix Savoie Triathlon) en 1h01\u201937.<br \/>\n\u2013 1\u00e8re ex aequo (1\u00e8re V1 ex aequo, 21\u00e8me au scratch ex aequo)\u00a0:\u00a0<b>Karine Marguerettaz\u00a0<\/b>(ASPTT Annecy Athl\u00e9tisme) en 1h01\u201937.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web L-Chrono :<br \/>\n<a href=\"http:\/\/www.l-chrono.com\/resultats2017\/course_des_etangs_15.pdf\">http:\/\/www.l-chrono.com\/resultats2017\/course_des_etangs_15.pdf<\/a><\/p>\n<p><strong>8 km<\/strong>\u00a0<strong>(238 inscrits, 235 partants dont 112 femmes, 234 class\u00e9s dont 112 femmes, record de participation)\u00a0:<\/strong><br \/>\n\u2013 1er (1er V1)\u00a0:\u00a0<b>Stany Paumier<\/b>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien) en\u00a0<strong>27\u201926, record du parcours emprunt\u00e9 en 2009-2010 et depuis 2014<\/strong>.<br \/>\n\u2013 1\u00e8re (1\u00e8re V2, 29\u00e8me au scratch)\u00a0:<strong>\u00a0Yvona Jenc<\/strong>\u00a0(Tch\u00e9quie et Suisse, La Foul\u00e9e d\u2019Annemasse, section de l\u2019Entente Athl\u00e9tique de l\u2019Arve) en 34\u201939.<br \/>\n\u2013 R\u00e9sultats complets sur le site Web L-Chrono :<br \/>\n<a href=\"http:\/\/www.l-chrono.com\/resultats2017\/course_des_etangs_8.pdf\">http:\/\/www.l-chrono.com\/resultats2017\/course_des_etangs_8.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nDEUX PARCOURS\u00a0:<\/strong><\/p>\n<p>Aussi bien le 15 que le 8 km se faufilent au c\u0153ur d\u2019une nature riche et pr\u00e9serv\u00e9e, qui tutoient notamment les fameux marais de Beaumont (15 ha) et de Crosagny (8 ha), celui-ci \u00e9tant constitu\u00e9 d\u2019eau libre sur plus de la moiti\u00e9 de sa superficie.<\/p>\n<p><strong>\u2013 15 km pour 220 m de d\u00e9nivel\u00e9.<\/strong><br \/>\nPoint culminant\u00a0: 427 m d\u2019altitude.<br \/>\nDeux ravitaillements\u00a0: km 5,5 et km 10.<\/p>\n<p><strong>\u2013 8 km (pr\u00e9cis\u00e9ment 8,074 km) pour 112 m de d\u00e9nivel\u00e9.<\/strong><br \/>\nPoint culminant\u00a0: 404 m d\u2019altitude.<br \/>\nUn ravitaillement\u00a0: km 4,5.<br \/>\nParcours emprunt\u00e9 par la Marche Populaire.<\/p>\n<p><strong>Evolution :<\/strong><br \/>\n\u2013 2009-2010-2014-2015-2016-2017-2018 :\u00a0d\u00e9part au complexe sportif.<br \/>\n\u2013 2011-2012-2013 :\u00a0d\u00e9part au chef-lieu ; itin\u00e9raire un peu plus court que le pr\u00e9c\u00e9dent.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>LA COURSE DES ETANGS SUR LE SITE WEB COURZYVITE :<\/strong><\/p>\n<p><strong>\u2013 R\u00e9sultats, compte rendu et photos de l\u2019\u00e9dition 2013\u00a0:<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2013\/05\/04\/resultats-compte-rendu-et-photos-de-la-course-des-etangs-05-05-13\/\">https:\/\/www.courzyvite.run\/blog\/2013\/05\/04\/resultats-compte-rendu-et-photos-de-la-course-des-etangs-05-05-13\/<\/a><\/p>\n<p><strong>\u2013 Pr\u00e9sentation de l\u2019\u00e9dition 2016 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/04\/30\/presentation-de-la-course-des-etangs-01-05-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/04\/30\/presentation-de-la-course-des-etangs-01-05-16\/<\/a><\/p>\n<p><strong>\u2013 Pr\u00e9sentation de l\u2019\u00e9dition 2017 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2017\/05\/14\/presentation-de-la-course-des-etangs-14-05-17\/\">https:\/\/www.courzyvite.run\/blog\/2017\/05\/14\/presentation-de-la-course-des-etangs-14-05-17\/<\/a><\/p>\n<p><strong>\u2013 R\u00e9sultats, compte rendu et photos de l\u2019\u00e9dition 2017 :<\/strong><br \/>\n<a href=\"https:\/\/www.courzyvite.run\/blog\/2017\/05\/30\/resultats-compte-rendu-et-photos-de-la-course-des-etangs-14-05-17\/\">https:\/\/www.courzyvite.run\/blog\/2017\/05\/30\/resultats-compte-rendu-et-photos-de-la-course-des-etangs-14-05-17\/<\/a><br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #ffffff;\">.<br \/>\n<\/span>.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>INFOS PRATIQUES\u00a0:<\/strong><\/p>\n<p><strong>Deux courses :<br \/>\nLe 15 km :<br \/>\n<\/strong>\u2013 Participants : cadets, juniors, espoirs, seniors et v\u00e9t\u00e9rans.<br \/>\n\u2013 Dimensions : 15 km pour 220 m de d\u00e9nivel\u00e9.<br \/>\n<strong>Le 8 km :<br \/>\n<\/strong>\u2013 Participants : cadets, juniors, espoirs, seniors et v\u00e9t\u00e9rans.<strong><br \/>\n<\/strong>\u2013 Dimensions : 8 km pour 112 m de d\u00e9nivel\u00e9 (8,074 km pour 112 m de d\u00e9nivel\u00e9).<\/p>\n<p><strong>Une randonn\u00e9e :<br \/>\nLa Marche Populaire :<br \/>\n<\/strong>\u2013 Participants : tout public.<br \/>\n\u2013 Dimensions : 8 km pour 112 m de d\u00e9nivel\u00e9 (8,074 km pour 112 m de d\u00e9nivel\u00e9).<\/p>\n<p><strong>Inscriptions :<\/strong><strong><br \/>\n\u2013 En ligne :<\/strong>\u00a0jusqu\u2019au vendredi 11 mai \u00e0 23 h 00 sur le site Web L-Chrono :<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/select_competition\">https:\/\/inscriptions-l-chrono.com\/coursedesetangs2018\/select_competition<\/a><br \/>\n<strong>\u2013 Samedi 12 mai : <\/strong>entre\u00a09 h 00 et 12 h 00 puis entre 14 h 00 et 17 h 00 \u00e0 la salle des f\u00eates de Saint-F\u00e9lix.<br \/>\n<strong>\u2013\u00a0Jour J :<\/strong>\u00a0entre 7 h 30 et 9 h 00 au complexe sportif de Saint-F\u00e9lix.<br \/>\nAttention,\u00a0inscriptions limit\u00e9es \u00e0 499 places.<\/p>\n<p><strong>Montants :<\/strong><strong><br \/>\nEn ligne :<br \/>\n<\/strong>\u2013 Le 15 km :\u00a012 euros + 1 euro de frais de gestion du site Web L-Chrono.<br \/>\n\u2013 Le 8 km : 12 euros + 1 euro de frais de gestion du site Web L-Chrono.<br \/>\n\u2013 La Marche Populaire : 5 euros + 1 euro de frais de gestion du site Web L-Chrono.<br \/>\n<strong>Samedi 12 mai :<br \/>\n<\/strong>\u2013 Le 15 km :\u00a012 euros.<br \/>\n\u2013 Le 8 km : 12 euros.<br \/>\n\u2013 La Marche Populaire : 5 euros.<br \/>\n<strong>Jour J :<\/strong><br \/>\n\u2013 Le 15 km :<strong>\u00a0<\/strong>14 euros.<br \/>\n\u2013 Le 8 km :\u00a014 euros.<br \/>\n\u2013 La Marche Populaire : 5 euros.<\/p>\n<p><strong>D\u00e9parts :<\/strong><strong>\u00a0<\/strong><br \/>\n<strong>Horaires :<\/strong><br \/>\n\u2013 Le 15 km :<strong>\u00a0<\/strong>9 h 30.<br \/>\n\u2013 Le 8 km :<strong>\u00a0<\/strong>9 h 50.<br \/>\n\u2013 La Marche Populaire : 9 h 00.<br \/>\n<strong>Lieu :<\/strong>\u00a0complexe sportif de Saint-F\u00e9lix.<\/p>\n<p><strong>Renseignements compl\u00e9mentaires :<\/strong><br \/>\n<strong>\u2013 E-mail de Philippe Jacquelin<\/strong>, pr\u00e9sident de Saint-F\u00e9lix Notre Village\u00a0:\u00a0<strong><br \/>\n<\/strong><a href=\"mailto:philippe@coursedesetangs.fr\">philippe@coursedesetangs.fr<\/a><br \/>\n<strong>\u2013 Page Facebook Ev\u00e9nement de la Course des Etangs<\/strong><strong>\u00a0:<br \/>\n<\/strong><a href=\"https:\/\/www.facebook.com\/events\/2080715232186217\/\">https:\/\/www.facebook.com\/events\/2080715232186217\/<\/a><br \/>\n<strong>\u2013 Si<\/strong><strong>te Web de la Course des Etangs :<br \/>\n<\/strong><a href=\"http:\/\/www.coursedesetangs.fr\/\">http:\/\/www.coursedesetangs.fr\/<\/a><br \/>\n<strong>\u2013 T\u00e9l\u00e9phones de Philippe Jacquelin<\/strong>, pr\u00e9sident de Saint-F\u00e9lix Notre Village\u00a0:\u00a004-50-60-95-33 ou 06-81-44-50-66.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>PHOTOS :<\/strong><\/p>\n<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46682 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04624-1.jpg?resize=500%2C751&#038;ssl=1\" alt=\"\" width=\"500\" height=\"751\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04624-1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04624-1.jpg?resize=100%2C150&amp;ssl=1 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Maxime Grenot <\/strong>(Team Rrun Seynod et ASPTT Annecy Athl\u00e9tisme), un des favoris du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par <strong>Rachel Bellot\u00a0<\/strong>\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Maxime s\u2019appropriera, sur le 4\u00e8me Trail Ch\u00e9ran Semnoz (23,5 km), la 2\u00e8me place (2\u00e8me senior) en 2h05\u201953.<br \/>\nImage r\u00e9alis\u00e9e sur le pont de l\u2019Ab\u00eeme, au km 16,3.<strong><br \/>\n<\/strong><\/p>\n<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46683 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04620-1.jpg?resize=500%2C751&#038;ssl=1\" alt=\"\" width=\"500\" height=\"751\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04620-1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC04620-1.jpg?resize=100%2C150&amp;ssl=1 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Simon Paccard <\/strong>(Crazyounguys, Team Rrun Seynod et ASPTT Annecy Athl\u00e9tisme), un des favoris du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par<strong> Rachel Bellot<\/strong>\u00a0\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Simon s\u2019appropriera, sur le 4\u00e8me Trail Ch\u00e9ran Semnoz (23,5 km), la 3\u00e8me place (1er junior) en 2h08\u201959.<br \/>\nImage r\u00e9alis\u00e9e sur le pont de l\u2019Ab\u00eeme, au km 16,3.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46684 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-1.jpg?resize=860%2C573&#038;ssl=1\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-1.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-1.jpg?resize=820%2C547&amp;ssl=1 820w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-1.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-1.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 38 : <strong>Michel Barralon<\/strong> (Team Rrun Seynod et ASPTT Annecy Athl\u00e9tisme), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 3 mai 2015 par le<b> Pixels-Club<\/b>\u00a0\u00e0\u00a0l\u2019occasion de la 7\u00e8me Course des Etangs o\u00f9 Michel s\u2019appropriera, sur le 15 km, la 6\u00e8me place (1er V2) en 55\u201902.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_3080-e1526179157703.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15983 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_3080-e1526179157703.jpg?resize=467%2C700&#038;ssl=1\" alt=\"\" width=\"467\" height=\"700\" \/><\/a><strong>Thierry Belzuz\u00a0<\/strong>(Gendarmerie Nationale Seynod), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par <strong>Edouard\u00a0Lebeau<\/strong>\u00a0\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Emilien s\u2019appropriera, sur la 2\u00e8me Gruff\u2019\u00e0 l\u2019Eau (14 km), la 4\u00e8me place (1\u00e8re V1) en 2h13\u201922.<br \/>\nImage r\u00e9alis\u00e9e dans les gorges du Ch\u00e9ran.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/97-e1526036396597.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15874 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/97-e1526036396597.jpg?resize=860%2C573&#038;ssl=1\" alt=\"\" width=\"860\" height=\"573\" \/><\/a><strong>Samuel Caillet<\/strong> (Team Rrun Seynod), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0 l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Samuel s\u2019appropriera, sur le 8 km, la 6\u00e8me place (2\u00e8me senior) en 29\u201955.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<strong><br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0005-e1525972576132.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15846 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0005-e1525972576132.jpg?resize=465%2C700&#038;ssl=1\" alt=\"\" width=\"465\" height=\"700\" \/><\/a>Emilien Grillet\u00a0<\/strong>(V\u00e9lo Club Rumillien), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par\u00a0<strong>Corentin Vanzo<\/strong>\u00a0\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Emilien s\u2019appropriera, sur la 2\u00e8me Gruff\u2019\u00e0 l\u2019Eau (14 km), la 17\u00e8me place (2\u00e8me cadet) en 1h18\u201923.<br \/>\nImage r\u00e9alis\u00e9e dans les gorges du Ch\u00e9ran.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/picture_076-e1526165302773.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15958 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/picture_076-e1526165302773.jpg?resize=468%2C700&#038;ssl=1\" alt=\"\" width=\"468\" height=\"700\" \/><\/a><strong>Nicolas Inaudi\u00a0<\/strong>(Brison-Saint-Innocent), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 21 mai 2017 \u00e0\u00a0l\u2019occasion de la 33\u00e8me Tresservienne o\u00f9 Nicolas s\u2019appropriera, sur le 13,6 km, la 7\u00e8me place (5\u00e8me senior) en 50\u201944.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15934 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/picture_074.jpg?resize=468%2C700\" alt=\"\" width=\"468\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/picture_074.jpg?w=468&amp;ssl=1 468w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/picture_074.jpg?resize=420%2C628&amp;ssl=1 420w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><strong>Dorian Marchal\u00a0<\/strong>(Crazyounguys et Tobesport), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 21 mai 2017 \u00e0\u00a0l\u2019occasion de la 33\u00e8me Tresservienne o\u00f9 Dorian s\u2019appropriera, sur le 13,6 km, la 6\u00e8me place (1er espoir) en 50\u201938.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15875 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0124-Copie.jpg?resize=860%2C574\" alt=\"\" width=\"860\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0124-Copie.jpg?w=881&amp;ssl=1 881w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0124-Copie.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0124-Copie.jpg?resize=768%2C513&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Au premier plan :<b> Julien Tapiero<\/b> (Team Rrun Seynod et La Ronde de Chavanod), un des principaux outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0 l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 Julien s\u2019appropriera, sur le 15 km, la 6\u00e8me place (3\u00e8me senior) en 55\u201904.<br \/>\nImage r\u00e9alis\u00e9 au moulin.<strong><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15915 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2504.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2504.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2504.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2504.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/strong>Dossard 41 : <strong>Beno\u00eet Berth\u00e9<\/strong>\u00a0(Les Alligators Seynod Triathlon), un des outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 29 juillet 2018 par <strong>David Nicod<\/strong> (Les Trailers des Aravis) \u00e0 l\u2019occasion du 1er Aravis Sky Pursuit o\u00f9 Beno\u00eet s\u2019appropriera, sur le 20 km, la 8\u00e8me place (6\u00e8me senior) en 2h42\u201916.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15973 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0309.jpg?resize=464%2C700\" alt=\"\" width=\"464\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0309.jpg?w=464&amp;ssl=1 464w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0309.jpg?resize=420%2C634&amp;ssl=1 420w\" sizes=\"auto, (max-width: 464px) 100vw, 464px\" \/><strong>Edouard Claude<\/strong>, un des outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par<strong>\u00a0Corentin Vanzo<\/strong>\u00a0\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Edouard s\u2019appropriera, sur le 4\u00e8me Trail Ch\u00e9ran Semnoz (23,5 km), la 12\u00e8me place (3\u00e8me junior) en 2h19\u201908.<br \/>\nImage r\u00e9alis\u00e9e dans les gorges du Ch\u00e9ran.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMGP3466-e1526054333245.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15889 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMGP3466-e1526054333245.jpg?resize=467%2C700&#038;ssl=1\" alt=\"\" width=\"467\" height=\"700\" \/><\/a><strong>Emmanuel Maison\u00a0<\/strong>(Rumilly Haute-Savoie Athl\u00e9tisme, section d\u2019Annecy Haute-Savoie Athl\u00e9tisme), un des outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 1er mai 2011 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 3\u00e8me Course des Etangs o\u00f9 Manu s\u2019appropriera, sur le 15 km, la 7\u00e8me place (4\u00e8me senior) en 59\u201921.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019\u00e9tang de Crosagny.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15868 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0522.jpg?resize=860%2C572\" alt=\"\" width=\"860\" height=\"572\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0522.jpg?w=958&amp;ssl=1 958w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0522.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0522.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 73 :<strong> Aubin Perret\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), un des outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 Aubin s\u2019appropriera, sur le 15 km, la 12\u00e8me place (1er junior) en 58\u201911.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15971 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0545.jpg?resize=860%2C571\" alt=\"\" width=\"860\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0545.jpg?w=886&amp;ssl=1 886w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0545.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0545.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Sacha Piccon <\/strong>(Massingy), un des outsiders du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 12 novembre 2017 par <strong>Jean-Claude Delachenal<\/strong>\u00a0\u00e0\u00a0l\u2019occasion du 2\u00e8me Urban Race Seynod o\u00f9 Sacha s\u2019appropriera la 11\u00e8me place (7\u00e8me senior) en 51\u201914.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15978 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_24.jpg?w=1720&amp;ssl=1 1720w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 521 :<strong>\u00a0Nathalie Peillex\u00a0<\/strong>(Aix Savoie Triathlon), favorite du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Nathalie s\u2019appropriera, sur le 15 km, la 1\u00e8re place (1\u00e8re V1) en 1h01\u201937.<br \/>\nUne victoire partag\u00e9e avec <strong>Karine Marguerettaz<\/strong> (dossard 544, ASPTT Annecy Athl\u00e9tisme).<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019\u00e9tang de Crosagny.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15866 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC0029-1.jpg?resize=500%2C332\" alt=\"\" width=\"500\" height=\"332\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC0029-1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC0029-1.jpg?resize=420%2C279&amp;ssl=1 420w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Dossard 894 : <strong>Marie Roupioz<\/strong> (Boussy), un des outsiders f\u00e9minins du 15 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 8 avril 2018 par <strong>Sylvie Lebeau<\/strong>\u00a0\u00e0\u00a0l\u2019occasion des 8\u00e8mes Foul\u00e9es de Gruffy o\u00f9 Marie s\u2019appropriera, sur le 10,6 km, la 3\u00e8me place f\u00e9minine (1\u00e8re senior, 30\u00e8me au scratch) en 51\u201951.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15869 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_9510.jpg?resize=422%2C637\" alt=\"\" width=\"422\" height=\"637\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_9510.jpg?w=422&amp;ssl=1 422w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_9510.jpg?resize=420%2C634&amp;ssl=1 420w\" sizes=\"auto, (max-width: 422px) 100vw, 422px\" \/>Dossard 48 :<strong> Ludovic Baur\u00a0<\/strong>(Team Rrun Seynod et Athl\u00e9tique Sport Aixois), un des favoris du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 Ludo s\u2019appropriera, sur le 15 km, la 2\u00e8me place (2\u00e8me senior) en 51\u201942.<br \/>\nA droite, on reconna\u00eet le laur\u00e9at\u00a0<strong>Laurent Marconnet<\/strong> (Team Technicien du Sport Seynod et ASPTT Annecy Athl\u00e9tisme) qui devancera Ludo de 7\u2019\u2019.<br \/>\nImage r\u00e9alis\u00e9e lors de l\u2019attaque lanc\u00e9e par Laurent \u00e0 500 m de l\u2019arriv\u00e9e, que ne parviendra pas \u00e0 contrer Ludo.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15911 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/13507110_10154298966319176_2231233502704871970_n.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/13507110_10154298966319176_2231233502704871970_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/13507110_10154298966319176_2231233502704871970_n.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/13507110_10154298966319176_2231233502704871970_n.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Avec un maillot blanc :<strong>\u00a0Arnaud Deletraz\u00a0<\/strong>(Salomon Running), un des favoris du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 26 juin 2016 par <strong>Philippe Bourgine\u00a0<\/strong>\u00e0\u00a0l\u2019occasion du 14\u00e8me Marathon du Mont-Blanc o\u00f9 Arnaud s\u2019appropriera la 28\u00e8me place (21\u00e8me senior) en 4h39\u201930.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/AAA_00421-e1526139107227.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15943 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/AAA_00421-e1526139107227.jpg?resize=860%2C573&#038;ssl=1\" alt=\"\" width=\"860\" height=\"573\" \/><\/a>Dossard 478 :<strong> Christophe Assailly\u00a0<\/strong>(Manigod), un des principaux outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 31 mars 2012 par <strong>Pascal Pierrain<\/strong>\u00a0(Photogone)\u00a0\u00e0\u00a0l\u2019occasion du 4\u00e8me Trail des Glaisins o\u00f9 Christophe s\u2019appropriera, sur le 29 km, la 1\u00e8re place (1er V1) en 2h34\u201930.<br \/>\nImage r\u00e9alis\u00e9e peu apr\u00e8s le M\u00e9morial du Capitaine Anjot, soit un peu au-del\u00e0 du km 8.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15922 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/106-2.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/106-2.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/106-2.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/106-2.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Cl\u00e9ment B\u00e9chet <\/strong>(Aix Savoie Triathlon), un des principaux outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club<\/strong>\u00a0\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Cl\u00e9ment s\u2019appropriera, sur le 8 km, la 5\u00e8me place (2\u00e8me espoir) en 29\u201952.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019\u00e9tang de Crovagny.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15886 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/2018.-7-sur-154.jpg?resize=860%2C572\" alt=\"\" width=\"860\" height=\"572\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/2018.-7-sur-154.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/2018.-7-sur-154.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/2018.-7-sur-154.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Paul Chauvetet\u00a0<\/strong>(Team Rrun Seynod), un des principaux outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 3 mars 2018 par <strong>Emmanuel Dupuis\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 4\u00e8me Course des Fougueurs o\u00f9 Paul s\u2019appropriera, sur le 10 km, la 7\u00e8me place (5\u00e8me senior) en 35\u201927.<br \/>\nImage r\u00e9alis\u00e9e au km 1,5.<\/p>\n<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15888 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/54-2.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/54-2.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/54-2.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/54-2.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Louis Parent\u00a0<\/strong>(Annecy Sports Orientation), un des principaux outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Louis s\u2019appropriera, sur le 8 km, la 8\u00e8me place (1er cadet) en 30\u201908.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15923 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/119.jpg?resize=466%2C700\" alt=\"\" width=\"466\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/119.jpg?w=466&amp;ssl=1 466w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/119.jpg?resize=420%2C631&amp;ssl=1 420w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><strong>Alexandre Cuttaz\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Alexandre s\u2019appropriera, sur le 8 km, la 14\u00e8me place (4\u00e8me V1) en 32\u201937.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15932 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/30171438_1512300882230591_6496486118354409961_o.jpg?resize=465%2C700\" alt=\"\" width=\"465\" height=\"700\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/30171438_1512300882230591_6496486118354409961_o.jpg?w=465&amp;ssl=1 465w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/30171438_1512300882230591_6496486118354409961_o.jpg?resize=420%2C632&amp;ssl=1 420w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/>Dossard 323 :<strong> Gilles Farina\u00a0<\/strong>(Faucigny Athl\u00e9tic Club), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 29 avril 2018 par <strong>Philippe Milliroux <\/strong>(Philophoto Photographe en Pays de Gex, Grand Gen\u00e8ve, Ain, Jura),<strong>\u00a0<\/strong>\u00e0\u00a0l\u2019occasion du 12\u00e8me D\u00e9fi de Fort-l\u2019Ecluse o\u00f9 Gilles s\u2019appropriera la 30\u00e8me place (2\u00e8me V2) en 1h26\u201925.<br \/>\nImage r\u00e9alis\u00e9e au km 1,5.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15936 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_4515.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_4515.jpg?w=884&amp;ssl=1 884w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_4515.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_4515.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>David Larrieu\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 30 octobre 2016 par le <strong>Comit\u00e9 des F\u00eates de Saint-Germain-sur-Rh\u00f4ne<\/strong>,\u00a0\u00e0\u00a0l\u2019occasion du 30\u00e8me Cross de la Semine o\u00f9 David s\u2019appropriera la 8\u00e8me place (4\u00e8me espoir-senior) en 51\u201911.<br \/>\nImage r\u00e9alis\u00e9e au bois de la Rouge, km 8,6.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_12-e1526057137601.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15895 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_12-e1526057137601.jpg?resize=464%2C700&#038;ssl=1\" alt=\"\" width=\"464\" height=\"700\" \/><\/a>Dossard 13 :<strong>\u00a0Nicolas Tournier\u00a0<\/strong>(Aoste, d\u00e9partement de l\u2019Is\u00e8re), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Nicolas s\u2019appropriera, sur le 8 km, la 10\u00e8me place (3\u00e8me V1) en 30\u201949.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15876 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0050-Copie-1.jpg?resize=822%2C588\" alt=\"\" width=\"822\" height=\"588\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0050-Copie-1.jpg?w=822&amp;ssl=1 822w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0050-Copie-1.jpg?resize=420%2C300&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0050-Copie-1.jpg?resize=768%2C549&amp;ssl=1 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/>&#8211; Dossard 312, au centre avec un maillot mauve :<strong>\u00a0Nicolas Tournier\u00a0<\/strong>(Aoste, d\u00e9partement de l\u2019Is\u00e8re), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\n&#8211; Dossard 347, \u00e0 l\u2019extr\u00eame gauche avec un maillot blanc : <strong>Pierre-Antoine Vatinel<\/strong> (Arve Athl\u00e9tisme Bonneville Pays Rochois, section de l\u2019Entente Athl\u00e9tique de l\u2019Arve), un des outsiders de ce 8 km.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 les deux coureurs s\u2019approprieront, sur le 8 km, les r\u00e9sultats suivants :<br \/>\n\u2013 La 6\u00e8me place (2\u00e8me senior) en 30\u201914 pour Nicolas.<br style=\"font-size: 15.2015px;\" \/>\u2013 La 12\u00e8me place (3\u00e8me V1) en 30\u201953 pour Pierre-Antoine.<br \/>\nImage r\u00e9alis\u00e9e au d\u00e9part.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15924 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/151.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/151.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/151.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/151.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Florian Zuccalli\u00a0<\/strong>(Les Princes en Foul\u00e9es), un des outsiders du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 Florian s\u2019appropriera, sur le 8 km, la 24\u00e8me place (5\u00e8me senior) en 34\u201914.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019\u00e9tang de Crovagny.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15980 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2001.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2001.jpg?w=884&amp;ssl=1 884w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2001.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_2001.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>&#8211; Au centre :<b> Anne Michel<\/b> (Thonon Athl\u00e9tic Club), favorite du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\n&#8211; A droite :\u00a0<strong>Alexandra Cuttaz\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), un des outsiders f\u00e9minins de ce 8 km.<br \/>\nClich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs o\u00f9 les deux coureuses s\u2019approprieront, sur le 8 km, les r\u00e9sultats suivants :<br \/>\n\u2013 La 4\u00e8me place f\u00e9minine (2\u00e8me V1, 47\u00e8me au scratch) en 37\u201956 pour Anne.<br \/>\n\u2013 La 5\u00e8me place f\u00e9minine (3\u00e8me V1, 51\u00e8me au scratch) en 38\u201933 pour Alexandra.<br \/>\nImage r\u00e9alis\u00e9e \u00e0\u00a0la remise des prix d\u00e9cern\u00e9e aux V1 f\u00e9minins en dehors du podium scratch.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15870 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0417-Copie.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0417-Copie.jpg?w=883&amp;ssl=1 883w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0417-Copie.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0417-Copie.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>2\u00e8me \u00e0 partir de la gauche :<strong>\u00a0Alexandra Cuttaz\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), un des outsiders f\u00e9minins du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 Alexandra s\u2019appropriera, sur le 8 km, la 12\u00e8me place f\u00e9minine (7\u00e8me V1, 85\u00e8me au scratch) en 40\u201932.<br \/>\nImage r\u00e9alis\u00e9e lors de la remise des prix d\u00e9cern\u00e9e au club le mieux repr\u00e9sent\u00e9, en l\u2019occurrence l\u2019ASPTT Annecy Athl\u00e9tisme.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15884 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1481.jpg?resize=860%2C645\" alt=\"\" width=\"860\" height=\"645\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1481.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1481.jpg?resize=420%2C315&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1481.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 443 :<strong>\u00a0Nathalie Vincent\u00a0<\/strong>(Annecy-le-Vieux Of Course), un des outsiders f\u00e9minins du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nClich\u00e9 pris le 5 mai 2013 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 5\u00e8me Course des Etangs o\u00f9 Nathalie s\u2019appropriera, sur le 15 km, la 12\u00e8me place f\u00e9minine (4\u00e8me V1, 112\u00e8me au scratch) en 1h17\u201951.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15877 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0032-Copie.jpg?resize=828%2C637\" alt=\"\" width=\"828\" height=\"637\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0032-Copie.jpg?w=828&amp;ssl=1 828w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0032-Copie.jpg?resize=420%2C323&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSC_0032-Copie.jpg?resize=768%2C591&amp;ssl=1 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/>&#8211; Dossard 48 :<strong>\u00a0Ludovic Baur\u00a0<\/strong>(Team Rrun Seynod et Athl\u00e9tique Sport Aixois), favori du 8 km, disput\u00e9 le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\n&#8211; Dossard 67 : <b>Samuel Caillet<\/b> (Team Rrun Seynod), un des principaux outsiders du 15 km de cette Course des Etangs.<br \/>\n&#8211; A l\u2019extr\u00eame gauche, portant la barbe : <strong>Julien Tapiero<\/strong> (Team Rrun Seynod et La Ronde de Chavanod), un des principaux outsiders de ce 15 km.<br \/>\nClich\u00e9 pris le 1er mai 2016 par le <strong>Pixels-Club\u00a0<\/strong>\u00e0\u00a0l\u2019occasion de la 8\u00e8me Course des Etangs o\u00f9 les trois coureurs s\u2019approprieront, sur le 15 km, les r\u00e9sultats suivants :<br \/>\n\u2013 La 2\u00e8me place (2\u00e8me senior) en 51\u201942 pour Ludo.<br style=\"font-size: 15.2015px;\" \/>\u2013 La 7\u00e8me place (4\u00e8me senior) en 56\u201919 pour Samuel.<br \/>\n\u2013 La 6\u00e8me place (3\u00e8me senior) en 55\u201904 pour Julien.<br \/>\nImage r\u00e9alis\u00e9e au d\u00e9part.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15885 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?resize=860%2C645\" alt=\"\" width=\"860\" height=\"645\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?w=3648&amp;ssl=1 3648w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?resize=420%2C315&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?resize=1200%2C900&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?w=1720&amp;ssl=1 1720w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/DSCF1754.jpg?w=2580&amp;ssl=1 2580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Au micro :<strong> Philippe Jacquelin<\/strong>, homme-orchestre de la Course des Etangs depuis l\u2019\u00e9dition princeps de 2009.<br \/>\nClich\u00e9\u00a0pris le 5 mai 2013 par le <strong>Pixels-Club<\/strong> \u00e0\u00a0l\u2019occasion de la 5\u00e8me Course des Etangs.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_8-e1526116848969.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15929 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_8-e1526116848969.jpg?resize=860%2C381&#038;ssl=1\" alt=\"\" width=\"860\" height=\"381\" \/><\/a>Au premier plan avec un maillot blanc et un brassard orange : <strong>Philippe Jacquelin<\/strong>, v\u00e9ritable t\u00eate pensante, entour\u00e9 comme un seul homme par sa renversante escouade, forte d\u2019une cinquantaine de b\u00e9n\u00e9voles.<br \/>\nClich\u00e9\u00a0pris le 14 mai 2017 par le <strong>Pixels-Club<\/strong> \u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs.<br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_23-e1526040054163.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15878 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/course_des_etangs_2017_23-e1526040054163.jpg?resize=467%2C700&#038;ssl=1\" alt=\"\" width=\"467\" height=\"700\" \/><\/a><strong>Oxana<\/strong>\u00a0et\u00a0<strong>sa maman<\/strong>, pr\u00e9sents pour la deuxi\u00e8me ann\u00e9e cons\u00e9cutive sur la marche populaire de 8 km, programm\u00e9e le dimanche 13 mai 2018 \u00e0 Saint-F\u00e9lix dans le cadre de la 10\u00e8me \u00e9dition de la Course des Etangs.<br \/>\nEn cons\u00e9quence, un\u00a0euro par dossard sera de nouveau revers\u00e9 aux parents d\u2019Oxana afin de pourvoir soigner leur petite fille, atteinte d\u2019un n\u00e6vus g\u00e9ant cong\u00e9nital dans les premiers mois de grossesse\u00a0<strong><br \/>\n<\/strong>Clich\u00e9 pris le 14 mai 2017 par le <strong>Pixels-Club<\/strong> \u00e0\u00a0l\u2019occasion de la 9\u00e8me Course des Etangs.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e de la marche populaire de 8 km.<strong><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15881 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_1282.jpg?resize=860%2C573\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_1282.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_1282.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_1282.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/strong>A droite :<strong> Lidwine Lachenal<\/strong>, une des chevilles ouvri\u00e8res\u00a0de la soci\u00e9t\u00e9 L-Chrono dont le pr\u00e9sident-fondateur, <strong>Ludovic Galland<\/strong>, assurera ce dimanche le chronom\u00e9trage.<br \/>\nClich\u00e9 pris le 3 mai 2015 par le <strong>Pixels-Club<\/strong> \u00e0\u00a0l\u2019occasion de la 7\u00e8me Course des Etangs.<strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNE COURSE DE VILLAGE QUI PARVIENT A S\u2019IMMISCER DANS LA COUR DES GRANDS Concourue \u00e0 Saint-F\u00e9lix, la Course des Etangs\u00a0qui f\u00eatera ce dimanche 13 mai son 10\u00e8me anniversaire se porte comme un charme, l\u2019accessibilit\u00e9 de ses deux parcours vallonn\u00e9s, un 15 et un 8 km, constituant son ADN. Un \u00e9v\u00e9nement qui tire \u00e9galement partie de sa localisation dans l\u2019Albanais, un territoire \u00e0 forte croissance d\u00e9mographique s\u2019\u00e9tendant sur les Deux Savoie. [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":15882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"PRESENTATION DE LA COURSE DES ETANGS \/ 13-05-18","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[16,13],"tags":[11],"class_list":["post-15793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-haute-savoie","category-presentations-des-courses","tag-news"],"views":4104,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2018\/05\/IMG_0974-e1526215036605.jpg?fit=900%2C504&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7PZ3h-46J","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/15793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/comments?post=15793"}],"version-history":[{"count":0,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/15793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media\/15882"}],"wp:attachment":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media?parent=15793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/categories?post=15793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/tags?post=15793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}