{"id":12428,"date":"2017-12-15T13:44:10","date_gmt":"2017-12-15T12:44:10","guid":{"rendered":"https:\/\/www.courzyvite.run\/blog\/?p=12428"},"modified":"2021-08-03T08:52:25","modified_gmt":"2021-08-03T06:52:25","slug":"presentation-de-la-corrida-de-bellegarde-16-12-17","status":"publish","type":"post","link":"https:\/\/www.courzyvite.run\/blog\/2017\/12\/15\/presentation-de-la-corrida-de-bellegarde-16-12-17\/","title":{"rendered":"PRESENTATION DE LA CORRIDA DE BELLEGARDE \/ 16-12-17"},"content":{"rendered":"<p><strong>LE CABB SUR SA LANCEE !<\/strong><\/p>\n<p>C\u2019est \u00e0 partir de 2015 que le Club Athl\u00e9tique du Bassin Bellegardien (CABB) s\u2019est tourn\u00e9 dans l\u2019organisation annuelle de quatre courses hors stade (1) que sont : le Trail de la Michaille jusqu\u2019en 2016 (2), remplac\u00e9 ensuite par le D\u00e9fi de Fort-l\u2019Ecluse (3) ; la Mont\u00e9e du Cr\u00eat d\u2019Eau ; la Voie du Tram, devenu le Trail de la Valserine \u00e0 compter de 2017 ; enfin, la Corrida de Bellegarde.<br \/>\nRarissime, cette volont\u00e9 d\u2019une formation FFA de centrer son action sur l\u2019\u00e9v\u00e9nementiel, en plus des jeunes, m\u00e9rite vraiment d\u2019\u00eatre soulign\u00e9e, m\u00eame si la r\u00e9ussite n\u2019a pas toujours \u00e9t\u00e9 au rendez-vous, loin s\u2019en faut d\u2019ailleurs. A l\u2019image de la Voie du Tram, annul\u00e9e l\u2019an pass\u00e9, faute d\u2019athl\u00e8tes (3 \u00e0 J-11 !) et de b\u00e9n\u00e9voles.<br \/>\nToutefois, un cap semble avoir \u00e9t\u00e9 franchi cette ann\u00e9e, co\u00efncidant avec la mise en place, le 10 juillet dernier, d\u2019une nouvelle instance dirigeante que pr\u00e9side l\u2019omnipr\u00e9sente et \u00e9nergique\u00a0<strong>Chrystelle<\/strong> <strong>Lassalle-Ghendir<\/strong>. Qu\u2019on en juge :<br \/>\n<strong><br \/>\n&#8211; 23 juillet 2017, Mont\u00e9e du Cr\u00eat d\u2019Eau<\/strong>, cr\u00e9\u00e9e en 1999 par Bellegarde Vals\u2019Running avant d\u2019\u00eatre repris en main par le CABB en 2015 : 148 inscrits, soit la deuxi\u00e8me meilleure participation de l\u2019histoire de cette \u00e9preuve apr\u00e8s 2005 (150 inscrits), except\u00e9 bien s\u00fbr les Championnats de France de Courses en Montagne en 2002 (663 inscrits).<br \/>\nLes deux autres \u00e9ditions orchestr\u00e9es par le CABB avaient donn\u00e9 les chiffres suivants : 137 inscrits en 2015, 134 en 2016. On ajoutera que la formation bellegardienne en a fait, \u00e0 dater de 2016, une \u00e9tape du prestigieux Challenge National de Courses en Montagne, ce qui ne s\u2019\u00e9tait jamais produit dans l\u2019Ain, hormis les France de 2002 (4).<br \/>\n<strong><br \/>\n&#8211; 22 octobre 2017, Trail de la Valserine<\/strong>, succ\u00e9dant \u00e0 la Voie du Tram, cr\u00e9\u00e9e en 1986 par le CABB : 142 inscrits, soit la cinqui\u00e8me meilleure participation apr\u00e8s 1998 (168 class\u00e9s), 1993 (160 class\u00e9s), 2012 (156 inscrits) et 2013 (147 inscrits), tout en \u00e9galant 2014 (5).<br \/>\n<strong><br \/>\n&#8211; 19 novembre 2017, D\u00e9fi de Fort-l\u2019Ecluse<\/strong>, cr\u00e9\u00e9 en 2004 par l\u2019Office de Tourisme de Collonges et sa R\u00e9gion\u00a0avant d\u2019\u00eatre annul\u00e9 de 2014 \u00e0 2016 puis de passer sous la houlette du CABB et de l\u2019association Trail The World en 2017 : 495 inscrits, soit\u00a0le record de participation d\u2019une course nature dans le pays de Gex. Notons que l\u2019ancien record de cette \u00e9preuve remontait \u00e0 2013 (200 inscrits).<\/p>\n<p><strong>Talons d\u2019Achille<\/strong><br \/>\nDu coup, que nous r\u00e9servera en terme d\u2019affluence la Corrida de Bellegarde qu\u2019a con\u00e7ue opportun\u00e9ment l\u2019ancien n\u00b01 du CABB\u00a0<strong>Didier Traor\u00e9<\/strong>,\u00a0et qui soufflera ses trois bougies ce samedi 16 d\u00e9cembre ? Dans un premier temps, on est en droit de redouter l\u2019\u00e9chec au regard des deux \u00e9pisodes ant\u00e9rieurs. D\u00e9nomm\u00e9e Challenge <strong>Ren\u00e9 Mugnier<\/strong> (6), l\u2019\u00e9preuve reine n\u2019avait en effet aimant\u00e9 que 71 athl\u00e8tes en 2015 puis 62 en 2016, auxquels on pouvait ajouter respectivement 4 et 3 cadets, faisant alors \u00e9trangement bande \u00e0 part sur une autre manche.<br \/>\nLes malheureux et sempiternels pr\u00e9jug\u00e9s \u00e0 l\u2019\u00e9gard de Bellegarde, la faiblesse d\u00e9mographique de son bassin de vie (21 373 \u00e2mes en 2014), son relatif \u00e9loignement par rapport aux aires urbaines de Bourg-en-Bresse et d\u2019Annecy, bastions de la course \u00e0 pied par excellence, peuvent expliquer cette d\u00e9saffection. La traditionnelle coupure de fin d\u2019ann\u00e9e, les pr\u00e9mices de la saison hivernale, la multiplication des corridas et autres cross qui pr\u00e9c\u00e8dent le rendez-vous bellegardien ou ont lieu le m\u00eame week-end ne plaident pas non plus en faveur de cette manifestation. Autant de failles qui auraient d\u00fb alors inciter les organisateurs \u00e0 mettre en oeuvre une campagne de communication tous azimuts, ce qui au final n\u2019avait pas \u00e9t\u00e9, h\u00e9las, entrepris.<\/p>\n<p><strong>Une comm\u2019 tonitruante<\/strong><br \/>\nDe cette d\u00e9convenue, la le\u00e7on a \u00e9t\u00e9 cette fois-ci retenue, d\u2019autant plus facilement que les dirigeants cabbistes sortent ragaillardis de leurs incontestables succ\u00e8s\u00a0au Cr\u00eat d\u2019Eau, \u00e0 la Valserine et au Fort-l\u2019Ecluse.<br \/>\nLa comm\u2019 s\u2019est port\u00e9e avant tout sur le tissu local, les corridas ne drainant du monde que dans un p\u00e9rim\u00e8tre restreint en raison d\u2019un temps de course limit\u00e9. Sur Bellegarde intra-muros, un mail a ainsi \u00e9t\u00e9 adress\u00e9 \u00e0 chacune des 140 associations pour encourager leurs adh\u00e9rents \u00e0 disputer collectivement le Challenge Ren\u00e9 Mugnier. En effet, celui-ci r\u00e9compensera, outre les individualit\u00e9s, l\u2019\u00e9quipe la plus rapide en comptabilisant les trois meilleurs comp\u00e9titeurs, mais aussi l\u2019escouade la mieux repr\u00e9sent\u00e9e.<br \/>\nParall\u00e8lement, 1400 flyers ont \u00e9t\u00e9 distribu\u00e9s dans toutes les \u00e9coles primaires de la quatri\u00e8me ville de l\u2019Ain afin de populariser deux des trois courses jeunes, au menu de cette corrida. De m\u00eame, pas moins de quatre m\u00e9dias ont \u00e9t\u00e9 contact\u00e9s, \u00e0 savoir <em>Le Dauphin\u00e9 lib\u00e9r\u00e9<\/em>, <em>La Tribune R\u00e9publicaine<\/em>, <em>La Voix de l\u2019Ain<\/em>, enfin Sorgia FM.<br \/>\nEn dehors du pays bellegardien, qu\u2019il s\u2019agisse de l\u2019Ain ou des Deux Savoie, un message personnalis\u00e9 a \u00e9t\u00e9 envoy\u00e9, par mail ou via Facebook, \u00e0 une kyrielle de coureurs\u00a0et de clubs, sans oublier le tractage de flyers sur les comp\u00e8tes, \u00e0 l\u2019instar de la Corrida d\u2019Aix-les-Bains, le 9 d\u00e9cembre dernier.<\/p>\n<p><strong>La mairie \u00e0 la rescousse<\/strong><br \/>\nAutre carte ma\u00eetresse, et de taille, le soutien total et ind\u00e9fectible apport\u00e9 par la ville de Bellegarde \u00e0 cette corrida, concourue dans le cadre des Lumi-Rh\u00f4ne, l\u2019un des \u00e9v\u00e9nements des Hiver\u2019Vals, animations de fin d\u2019ann\u00e9e orchestr\u00e9es par la municipalit\u00e9. On ne soulignera jamais assez le r\u00f4le-clef endoss\u00e9 par ces quatre incontournables personnalit\u00e9s que sont : <strong>Jacques Decorme<\/strong>, conseiller municipal d\u00e9l\u00e9gu\u00e9 aux associations, aux sports et \u00e0 l\u2019\u00e9v\u00e9nementiel ;\u00a0<strong>Philippe Camps<\/strong>, directeur des services \u00e0 la population et \u00e0 la citoyennet\u00e9 \u00e0 la Ville, \u00e0 l\u2019origine du trac\u00e9 ; <strong>Ludwig Kopp<\/strong>, r\u00e9gisseur g\u00e9n\u00e9ral ;\u00a0<strong>Sophie Ardain<\/strong>, membre du service municipal de la vie associative.<\/p>\n<p><strong>Un parcours nerveux<\/strong><br \/>\nTroisi\u00e8me point fort apr\u00e8s la communication et l\u2019implication de la mairie, l\u2019itin\u00e9raire, qui avait fait consensus sur les deux premi\u00e8res cuv\u00e9es. Long de 7800 m \u00e0 travers une boucle de 1940 m \u00e0 arpenter \u00e0 quatre reprises, il a \u00e9t\u00e9 modifi\u00e9 en rive gauche de la Valserine sur une id\u00e9e de la pr\u00e9sidente du CABB. Les athl\u00e8tes fouleront ainsi plus longtemps les berges du Rh\u00f4ne, remarquablement am\u00e9nag\u00e9es par la mairie et la CNR (7) \u00e0 partir d\u2019octobre 2011.<br \/>\nArch\u00e9type d\u2019une corrida, l\u2019\u00e9preuve ne quitte pas d\u2019une semelle la cit\u00e9 bellegardienne, le th\u00e9\u00e2tre d\u2019op\u00e9rations tutoyant l\u2019hyper-centre. Costaud, ce trac\u00e9 est tout en relance, les virages \u00e0 angle droit ou \u00e0 \u00e9pingles \u00e0 cheveu \u00e9tant l\u00e9gion, sans compter quelques marches d\u2019escalier et deux faux plats montants : le premier pimentant la rive gauche de la Valserine via la rue de la Perte du Rh\u00f4ne ; le second reliant le boulodrome \u00e0 la rue Viala, \u00e0 travers la rue du Docteur Malet puis la rue Francis. Le clou intervient au moment d\u2019enjamber sur une passerelle l\u2019envo\u00fbtante confluence entre le Rh\u00f4ne et la Valserine.<\/p>\n<p><strong>Jamsin en marraine<br \/>\n<\/strong>Cerise sur le g\u00e2teau, les festivit\u00e9s seront parrain\u00e9es par <strong>Lucie Jamsin<\/strong>,\u00a0s\u00e9lectionn\u00e9e \u00e0 sept reprises en \u00e9quipe de France dont six fois en course de montagne (2013 \u00e0 2015 puis 2017) et une autre fois en trail (2017). Pensionnaire de l\u2019Athl\u00e9 Saint-Julien 74 et du Team Trail Isostar, cette femme de 28 ans est tr\u00e8s attach\u00e9e au pays bellegardien pour avoir \u00e9lu domicile \u00e0 Champfromier et bosser \u00e0 Bellegarde comme lieutenante de sapeur-pompier professionnel. Sa pr\u00e9sence n\u2019est donc pas une surprise, d\u2019autant plus qu\u2019elle avait d\u00e9j\u00e0 donn\u00e9 un coup de main au CABB en se pr\u00eatant, le 13 octobre dernier, \u00e0 un reportage photo sur l\u2019itin\u00e9raire du Trail de la Valserine afin de booster cette manifestation.<br \/>\nSamedi, cette Ch\u2019ti pur jus (elle a grandi dans le B\u00e9thunois) partagera le bonheur de courir avec les \u00e9veils athl\u00e9 et les poussins en se positionnant en queue de peloton. Auparavant, gr\u00e2ce \u00e0 <strong>Jenny<\/strong>,<strong>\u00a0<\/strong>coach de fitness \u00e0 domicile, elle se sera \u00e9chauff\u00e9e en musique en leur compagnie, le tout dans une atmosph\u00e8re conviviale et festive, histoire de comm\u00e9morer le 70\u00e8me anniversaire du v\u00e9n\u00e9rable CABB. En revanche, les douleurs \u00e0 son tendon calcan\u00e9en la dissuaderont de prendre le d\u00e9part du Challenge Ren\u00e9 Mugnier.\u00a0\u00a0<strong>\u00a0\u00a0<\/strong>\u00a0<strong>\u00a0<\/strong><\/p>\n<p>Au regard du nombre d\u2019inscrits \u00e0 la cl\u00f4ture des inscriptions en ligne, \u00e0 20h de l\u2019\u00e9ch\u00e9ance, et malgr\u00e9 les multiples atouts que renferme ce rendez-vous, la partie est pourtant loin d\u2019\u00eatre gagn\u00e9e pour Chrystelle Lassalle-Ghendir et sa joyeuse bande, forte de 22 b\u00e9n\u00e9voles. Si les trois courses jeunes progressent sensiblement (42 engag\u00e9s contre 15 en 2016), le Challenge Ren\u00e9 Mugnier, r\u00e9serv\u00e9 aux cadets et aux adultes, est \u00e0 la peine (36 engag\u00e9s contre 34 en 2016). Tr\u00e8s loin des 485 class\u00e9s de la Course des Lumi\u00e8res \u00e0 Ch\u00e2tillon-sur-Chalaronne ou encore des 377 inscrits de la Corrida d\u2019Aix-les-Bains, disput\u00e9es tour \u00e0 tour les 8 et 9 d\u00e9cembre dernier.<br \/>\nMalgr\u00e9 tout, les vaillantes chevilles ouvri\u00e8res bellegardiennes demeurent confiantes, escomptant en effet une petite d\u00e9ferlante le jour J. Les amateurs de corridas leur donneront-ils raison en assurant ainsi la p\u00e9rennit\u00e9 de cette \u00e9patante \u00e9preuve ? A n\u2019en pas douter, c\u2019est tout l\u2019enjeu de cette Corrida de Bellegarde.<\/p>\n<p><strong>F.V. pour le compte \u00e9galement du site Web de l\u2019Athl\u00e9 Saint-Julien 74, en date du samedi 16 d\u00e9cembre 2017 :<br \/>\n<\/strong><a href=\"http:\/\/www.asj74.org\/corrida-de-bellegarde-sur-valeserine\/\">http:\/\/www.asj74.org\/corrida-de-bellegarde-sur-valeserine\/<\/a><\/p>\n<p>(1) 2015 avait m\u00eame vu le Club Athl\u00e9tique du Bassin Bellegardien orchestrer pas moins de cinq courses, ayant \u00e9galement en charge les Championnats de l\u2019Ain de Cross-Country.<span style=\"font-size: 0.95em;\"><br \/>\n<\/span>(2) Depuis 2017, le Trail de la Michaille est sous la responsabilit\u00e9 de l\u2019association Run Valserine.<br \/>\n(3)\u00a0Le D\u00e9fi de Fort-l\u2019Ecluse est organis\u00e9 conjointement par le\u00a0Club Athl\u00e9tique du Bassin Bellegardien et l\u2019association Trail The World.<br \/>\n(4) Toute \u00e9preuve qui sert de support aux Championnats de France de Courses en Montagne int\u00e8gre ipso facto le Challenge National de Courses en Montagne, ce qui a \u00e9t\u00e9 le cas de la Mont\u00e9e du Cr\u00eat d\u2019Eau en 2002.<br \/>\n(5) Les chiffres de la participation sur la Voie du Tram entre 1986 et 1992, en 1994, enfin en 1997, sont introuvables.<br \/>\n(6) <strong>Ren\u00e9 Mugnier<\/strong> est l\u2019un des deux fondateurs, avec<strong> Louis Pery<\/strong>, du Club Athl\u00e9tique du Bassin Bellegardien en 1947. D\u00e9c\u00e9d\u00e9 en mars 2014, il en a \u00e9t\u00e9 le pr\u00e9sident de 1968 \u00e0 2007.<br \/>\n(7) CNR signifie Compagnie Nationale du Rh\u00f4ne.<br \/>\n<span style=\"color: #ffffff;\"><span style=\"color: #ffffff;\">.<br \/>\n<\/span>.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nDUEL DE CHOC ENTRE EMERIC ARNAUD ET SIMON SENN !<\/strong><\/p>\n<p>Ag\u00e9 de 20 ans, le triathl\u00e8te <strong>Emeric Arnaud <\/strong>s\u2019est engag\u00e9 le 4 d\u00e9cembre sur la Corrida de Bellegarde. Du coup, il appara\u00eet comme le grand favori, du moins pour le moment, du Challenge Ren\u00e9 Mugnier, nom attribu\u00e9 \u00e0 l\u2019\u00e9preuve r\u00e9serv\u00e9e aux adultes et aux cadets, longue de 7800 m via une boucle de 1940 m \u00e0 arpenter quatre fois.<br \/>\nInstall\u00e9 \u00e0 Annecy-le-Vieux, ce Mauriennais de souche aura fait parler la poudre en 2017, et ce \u00e0 de nombreuses reprises, notamment en r\u00e9alisant deux performances de haut vol :<br \/>\n\u2013 Son titre de champion de France de triathlon groupes d\u2019\u00e2ge, r\u00e9colt\u00e9 le 16 juillet \u00e0 Gray (Haute-Sa\u00f4ne) sur la courte distance.<br \/>\n\u2013 Son record sur 10 bornes en 31\u201916, accompli le 22 octobre \u00e0 Lausanne.<br \/>\nUltime prestation : sa 3\u00e8me place \u00e0 la Corrida de Chavanod, intervenue le 3 d\u00e9cembre, derri\u00e8re les deux Marocains d\u2019Annecy Haute-Savoie Athl\u00e9tisme\u00a0<strong>Anas Saaidou <\/strong>et <strong>Lhousseine Boussague<\/strong>.<\/p>\n<p><strong>Senn en embuscade<\/strong><br \/>\nCelui qui porte les couleurs d\u2019Annecy Haute-Savoie Athl\u00e9tisme et du Team Rrun Seynod, mais aussi tout r\u00e9cemment, celles de la formation nord-is\u00e9roise des Vallons de La Tour Triathlon, devra n\u00e9anmoins croiser le fer avec le Suisse <strong>Simon Senn<\/strong>. Auteur d\u2019une marque r\u00e9f\u00e9rence sur 10 km en 32\u201945 le 6 mai dernier \u00e0 Gen\u00e8ve, celui-ci encha\u00eene \u00e0 l\u2019heure actuelle les comp\u00e8tes, terminant 8\u00e8me de la Course du Duc puis 6\u00e8me du Cross des Glaisins, respectivement les 2 et 10 d\u00e9cembre.<br \/>\nAthl\u00e8te polyvalent par excellence, le n\u00e9o-pensionnaire du Club Athl\u00e9tique du Bassin Bellegardien (CABB) qui a souffl\u00e9 le 13 d\u00e9cembre ses 31 bougies s\u2019est montr\u00e9 \u00e9galement \u00e0 son avantage cette ann\u00e9e en course nature. N\u2019a-t-il pas enlev\u00e9 de main de ma\u00eetre, le 19 novembre, le redoutable D\u00e9fi de Fort-l\u2019Ecluse, et par ricochet, le Challenge des Trails du Haut-Rh\u00f4ne qui agr\u00e8ge pas moins de neuf manches concourues dans l\u2019Ain et en Pays de Savoie ?<\/p>\n<p><strong>Le trail \u00e0 l\u2019honneur<\/strong><br \/>\nCinq excellents trailers devraient \u00eatre aux avant-postes :<br \/>\n\u2013\u00a0<b>Jeffrey Fleury<\/b>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien), 31 ans. Les deux entorses \u00e0 la cheville entravant son d\u00e9but d\u2019ann\u00e9e ne l\u2019ont pas emp\u00each\u00e9 de briller. En t\u00e9moignent ses prouesses cet automne sur le Trail de la Valserine (2\u00e8me) puis sur le Semi-Marathon de V\u00e9nissieux (15\u00e8me en 1h13\u201952 pour son galop d\u2019essai).<br \/>\n<strong>&#8211; Sylv\u00e8re Pruvost<\/strong> (La Foul\u00e9e d\u2019Annemasse et Team The Nord Face), 33 ans. L\u2019asphalte n\u2019\u00e9tant pas sa tasse de th\u00e9, il accourt d\u2019abord pour faire plaisir aux dirigeants du CABB, impressionn\u00e9 qu\u2019il est de les voir s\u2019investir corps et \u00e2me sur les quatre courses qu\u2019ils organisent.\u00a0N\u2019emp\u00eache, et m\u00eame si le 10 bornes se r\u00e9duit pour lui \u00e0 une seule exp\u00e9rience, engrang\u00e9e au d\u00e9but de sa carri\u00e8re (37\u201927 en 2008 \u00e0 Annemasse), celui qui est d\u00e9sormais install\u00e9 \u00e0 Cornier pourrait bien tirer son \u00e9pingle du jeu. Ses victoires en octobre dernier sur la Persjussienne et le 21 km de la Chamb\u00e9rienne \u00e0 travers des parcours assez roulants le prouvent amplement.<br \/>\n<strong>\u2013\u00a0Marc Tamanini<\/strong>\u00a0(Thonon Athl\u00e9tic Club), 31 ans le 30 d\u00e9cembre prochain. Cette ann\u00e9e, il a battu son temps \u00e9talon sur 10 bornes \u00e0 Aix-les-Bains en 34\u201952. Son ultime dossard remonte au D\u00e9fi de Fort-l\u2019Ecluse qu\u2019il a boucl\u00e9 au 11\u00e8me rang.<br \/>\n<strong>\u2013 Didier Thiaffey-Rencorel<\/strong> (ASPTT Annecy Athl\u00e9tisme, Team Craft-Salming et Team St\u00e4ubli Sports),\u00a035 ans. Il b\u00e9n\u00e9ficie de deux atouts : la connaissance du trac\u00e9 pour avoir fini 9\u00e8me en 2016\u00a0; son record sur 10 km en 34\u201931, acquis l\u2019an pass\u00e9 \u00e0 Aix-les-Bains.<br \/>\n<strong>\u2013 Romain Wyndaele<\/strong>\u00a0(Team Ravanel and Co), 21 ans. Connu pour \u00eatre l\u2019un des meilleurs espoirs des Pays de Savoie, il s\u2019est montr\u00e9 \u00e0 son avantage sur le Cross des Glaisins en grimpant sur la 3\u00e8me marche apr\u00e8s un d\u00e9part canon en solitaire. C\u2019est d\u2019autant plus m\u00e9ritoire qu\u2019il reprenait la comp\u00e9tition apr\u00e8s avoir \u00e9t\u00e9 victime, le 20 juillet dernier, d\u2019une grosse entorse au genou o\u00f9 il s\u2019\u00e9tait quasiment rompu tous les ligaments. Il ne rechaussera ses running qu\u2019\u00e0 la fin du mois d\u2019octobre. 33\u201914 est sa meilleure perf sur 10 km, obtenue le 9 novembre 2014 \u00e0 Montereau lorsqu\u2019il enfilait la tunique ycaunaise de l\u2019Union Sportive de Joigny.<\/p>\n<p><strong>Laure Tassion au d\u00e9part ?<\/strong><br \/>\nAvec Emeric Arnaud, la pistarde <strong>Laure Tassion<\/strong> (Athl\u00e9 Saint-Julien 74) pourrait bien \u00eatre l\u2019une des attractions si elle d\u00e9cidait de courir \u00e0&#8230; domicile, cette enfant du Beaufortain \u00e9tant prof d\u2019EPS au coll\u00e8ge Louis Dumont \u00e0 Bellegarde.<br \/>\nAncienne skieuse de fond de haut niveau jusqu\u2019en 2013, celle qui compte 27 printemps excelle aujourd\u2019hui sur 1500 m, son record s\u2019\u00e9levant \u00e0 4\u201935, r\u00e9alis\u00e9 l\u2019an pass\u00e9. Une prouesse de niveau N4, \u00e0 l\u2019instar de son meilleur chrono sur 800 m, accompli en 2\u201915, \u00e9galement en 2016. Sur 10 bornes, elle est parvenue \u00e0 son acm\u00e9 le 9 avril dernier \u00e0 Aix-les-Bains apr\u00e8s avoir conclu en 37\u201923.<\/p>\n<p><strong>Une flop\u00e9e d\u2019outsiders<\/strong><br \/>\nDu coup, le plateau f\u00e9minin a de bonnes chances de s\u00e9duire. C\u2019est d\u2019autant plus vrai qu\u2019est annonc\u00e9e la venue de la Franco-Britannique\u00a0<strong>Emilie Shaw<\/strong>, 35 ans, enracin\u00e9e dans le pays bellegardien pour \u00eatre originaire de Giron de par sa m\u00e8re et r\u00e9sider \u00e0 Champfromier, tout en \u00e9tant licenci\u00e9e \u00e0 Run Valserine. En grande forme cet automne, elle a fait tomber dans son escarcelle le Trail de la Valserine, le 11 km de l\u2019Izernight puis le Cross de la Semine, ces deux ultimes \u00e9preuves \u00e0\u2026 14h30 d\u2019intervalle !<br \/>\nAutre valeur s\u00fbre pr\u00e9sente, l\u2019Annemassienne de souche\u00a0<strong>Anne Michel<\/strong>\u00a0(Thonon Athl\u00e9tic Club), 43 ans, qui avait accapar\u00e9 la 6\u00e8me position sur la pr\u00e9c\u00e9dente \u00e9dition de la Corrida de Bellegarde. Elle pourrait se mettre davantage en \u00e9vidence au vu de sa nouvelle marque r\u00e9f\u00e9rence sur 10 bornes, \u00e9tablie le 22 octobre dernier \u00e0 Lausanne en 41\u201929, soit un gain d\u20191\u201934 au regard de son ancien temps \u00e9talon, survenu trois mois auparavant \u00e0 Th\u00f4nes.<br \/>\nPareillement, on soulignera la possible participation de :<br \/>\n\u2013\u00a0<strong>Karine Marguerettaz<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) qui, en d\u00e9pit de ses 43 ans, continue \u00e0 \u00e9cumer dans son d\u00e9partement les courses sur route. Record sur 10 km en 37\u201924 en 2011 \u00e0 Annemasse.<br \/>\n\u2013\u00a0<strong>S\u00e9verine Gaillard\u00a0<\/strong>(Chamonix Mont-Blanc Marathon), 39 ans, laur\u00e9ate de la Corrida de Bellegarde en 2016, 6\u00e8me sur la Corrida d\u2019Aix-les-Bains en 2017. Record sur 10 km en 40\u201911 l\u2019an pass\u00e9 \u00e0 Grenoble.<br \/>\n\u2013\u00a0<strong>Nad\u00e8ge Vignand\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme), 45 ans ce 19 d\u00e9cembre, 2\u00e8me en 2015 puis 3\u00e8me en 2016 sur la Corrida de Bellegarde, 10\u00e8me sur la Corrida d\u2019Aix-les-Bains en 2017. Record sur 10 km en 42\u201957 en 2014 \u00e0 Th\u00f4nes.<\/p>\n<p><strong>F.V.<br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>ARTICLE DU QUOTIDIEN <em>LE DAUPHINE LIBERE<\/em> :<\/strong><\/p>\n<p>Ci-dessous, vous trouverez un reportage sur\u00a0<strong>Lucie Jamsin<\/strong>, marraine de la 3\u00e8me Corrida de Bellegarde. Il figure en page sports de l\u2019\u00e9dition de Bellegarde et Pays de Gex, en date du samedi 21 octobre 2017. Son auteur est le correspondant <strong>Jacques Bosson<\/strong>.<br \/>\nCe papier a \u00e9t\u00e9 publi\u00e9 \u00e0 la veille du 23\u00e8me Grand Trail des Templiers o\u00f9 elle s\u2019appropriera la 7\u00e8me place f\u00e9minine (7\u00e8me senior, 51\u00e8me au scratch) en 8h30\u201940. Mais le plus important pour elle est d\u2019avoir enlev\u00e9 l\u2019\u00e9preuve chez les Fran\u00e7aises, ce qui lui a permis d\u2019int\u00e9grer l\u2019\u00e9quipe nationale de trail qui compte sept femmes. A l\u2019issue du\u00a0stage de printemps, du niveau de forme et du suivi m\u00e9dical, six d\u2019entre elles auront la chance de disputer les 8\u00e8mes Championnats du Monde qui auront lieu le 12 mai 2018 \u00e0 Penyagolosa, en Espagne.<span style=\"color: #000000;\">\u00a0\u00a0<\/span><\/p>\n<p>\n\t\t<div class=\"wppdfemb-frame-container-1\" style=\"-webkit-overflow-scrolling:auto;\">\n\t\t\t<iframe class=\"pdfembed-iframe nonfullscreen wppdf-emb-iframe-1\"\n\t\t\t\tsrc=\"https:\/\/www.courzyvite.run\/blog\/?pdfemb-data=eyJ1cmwiOiJodHRwczpcL1wvd3d3LmNvdXJ6eXZpdGUucnVuXC9ibG9nXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDE3XC8xMlwvUERGLVBhZ2UtMjgtZWRpdGlvbi1kZS1iZWxsZWdhcmRlLWV0LXBheXMtZGUtZ2V4LTIwMTcxMDIxLTEucGRmIiwidGl0bGUiOiJQREYtUGFnZS0yOC1lZGl0aW9uLWRlLWJlbGxlZ2FyZGUtZXQtcGF5cy1kZS1nZXgtMjAxNzEwMjEgKDEpIiwiaW5kZXgiOjEsInBkZklEIjowfQ\"\n\t\t\t\ttitle=\"PDF-Page-28-edition-de-bellegarde-et-pays-de-gex-20171021 (1)\"\t\t\t\tdata-pdf-id=\"0\"\n\t\t\t\tdata-pdf-index=\"1\"\n\t\t\t\tstyle=\"border:none;width:100%;max-width:100%;height:100vh;\"\n\t\t\t\tscrolling=\"yes\">\n\t\t\t<\/iframe>\n\t\t<\/div>\n\n\t\t<strong><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPALMARES DEPUIS 2015\u00a0<span style=\"font-size: 0.95em;\">:<br \/>\n<\/span><\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>19 d\u00e9cembre 2015 :\u00a0<\/strong><\/p>\n<p><strong>Scratch<\/strong>\u00a0<strong>(6572 m ; 71\u00a0inscrits, 71 partants, 70 class\u00e9s, record de participation)\u00a0:<\/strong><br \/>\n\u2013 1er (1er senior)\u00a0:\u00a0<strong>Abdesalam Kiday<\/strong>\u00a0(Maroc, Club Athl\u00e9tique du Bassin Bellegardien et Team Running Conseil Annemasse) en 20\u201937.<br \/>\n\u2013 2\u00e8me (2\u00e8me senior)\u00a0:\u00a0<strong>Otmane Belharbazi\u00a0<\/strong>(Club Athl\u00e9tique du Bassin Bellegardien) en 20\u201949.<br \/>\n\u2013 3\u00e8me (3\u00e8me senior)\u00a0:\u00a0<strong>Sergio Dias\u00a0<\/strong>(Portugal, Club Athl\u00e9tique du Bassin Bellegardien) en 21\u201904.<br \/>\n\u2013 4\u00e8me (1er V1)\u00a0:\u00a0<strong>El Yazid El Madi<\/strong>\u00a0(Maroc, Club Athl\u00e9tique du Bassin Bellegardien) en 21\u201940.<br \/>\n\u2013 5\u00e8me (4\u00e8me senior)\u00a0:\u00a0<strong>Yanis Lecompte<\/strong>\u00a0(Cornier) en 21\u201942.<\/p>\n<p><strong>Femmes\u00a0<\/strong>(21 class\u00e9es)\u00a0:<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 27\u00e8me au scratch)\u00a0:\u00a0<strong>Julie Faure<\/strong>\u00a0(Bessat Sports d\u2019Hiver et Team Fischer) en 27\u201925.<br \/>\n\u2013 2\u00e8me (1\u00e8re V1, 30\u00e8me au scratch)\u00a0:\u00a0<strong>Nad\u00e8ge Vignand<\/strong>\u00a0(ASPTT Annecy Athl\u00e9tisme) en 27\u201956.<br \/>\n\u2013 3\u00e8me (2\u00e8me senior, 33\u00e8me au scratch)\u00a0:\u00a0<strong>Carole Fournier<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 28\u201915.<br \/>\n\u2013 4\u00e8me (2\u00e8me V1, 38\u00e8me au scratch)\u00a0:<strong>\u00a0Clotilde Heberl\u00e9<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 29\u201920.<br \/>\n\u2013 5\u00e8me (3\u00e8me senior, 39\u00e8me au scratch)\u00a0:\u00a0<strong>Sandrine Favre-Victoire\u00a0<\/strong>(Annecy Haute-Savoie Athl\u00e9tisme) en 29\u201922.<\/p>\n<p><strong>R\u00e9sultats complets :<\/strong><br \/>\nIls figurent sur le site Web Courzyvite :<br \/>\n<a href=\"http:\/\/www.courzyvite.run\/15Resultats\/FouleeBellegardienne2015.pdf\">http:\/\/www.courzyvite.run\/15Resultats\/FouleeBellegardienne2015.pdf<br \/>\n<\/a><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\n17 d\u00e9cembre 2016 :<\/strong><\/p>\n<p><strong>Scratch<\/strong>\u00a0(7775 m ; 62 inscrits, 58 partants, 54 class\u00e9s)\u00a0:<br \/>\n\u2013 1er (1er senior)\u00a0:<strong>\u00a0Abdesalam Kiday\u00a0<\/strong>(Maroc, Club Athl\u00e9tique du Bassin Bellegardien et Team Running Conseil Annemasse) en 24\u201956.<br \/>\n\u2013 2\u00e8me (1er V1)\u00a0:\u00a0<strong>Paul Waroquier<\/strong>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien et Stade Gen\u00e8ve Athl\u00e9tisme) en 25\u201935.<br \/>\n\u2013 3\u00e8me (2\u00e8me senior)\u00a0:\u00a0<strong>S\u00e9bastien Giani<\/strong>\u00a0(Club Athl\u00e9tique du Bassin Bellegardien) en 25\u201936.<br \/>\n\u2013 4\u00e8me (2\u00e8me V1)\u00a0:\u00a0<strong>El Yazid El Madi\u00a0<\/strong>(Maroc, Club Athl\u00e9tique du Bassin Bellegardien) en 26\u201942.<br \/>\n\u2013 5\u00e8me (3\u00e8me senior)\u00a0:\u00a0<strong>Tiago Teixeira\u00a0<\/strong>(Portugal, Thonon Athl\u00e9tic Club, section du L\u00e9man Athl\u00e9tic Club) en 26\u201951.<\/p>\n<p><strong>Femmes<\/strong>\u00a0(14 partantes, 13 class\u00e9es)\u00a0:<br \/>\n\u2013 1\u00e8re (1\u00e8re senior, 25\u00e8me au scratch)\u00a0:\u00a0<strong>S\u00e9verine Gaillard<\/strong>\u00a0(Chamonix Mont-Blanc Marathon) en 32\u201912.<br \/>\n\u2013 2\u00e8me (1\u00e8re junior, 28\u00e8me au scratch)\u00a0:\u00a0<strong>Sara Caiado\u00a0<\/strong>(Portugal, Athl\u00e9tisme Viseu Gen\u00e8ve) en 32\u201939.<br \/>\n\u2013 3\u00e8me (1\u00e8re V1, 33\u00e8me au scratch)\u00a0:\u00a0<strong>Nad\u00e8ge Vignand\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme) en 33\u201938.<br \/>\n\u2013 4\u00e8me (2\u00e8me V1, 39\u00e8me au scratch)\u00a0:<strong>\u00a0Clotilde Heberl\u00e9<\/strong>\u00a0(Athl\u00e9 Saint-Julien 74) en 34\u201958.<br \/>\n\u2013 5\u00e8me (2\u00e8me senior, 40\u00e8me au scratch)\u00a0:<strong>\u00a0Carole Fournier\u00a0<\/strong>(Athl\u00e9 Saint-Julien 74) en 35\u201911.<strong><br \/>\n<\/strong><br \/>\n<strong>R\u00e9sultats complets :<\/strong><br \/>\nIls figurent sur le site Web Courzyvite :<strong><br \/>\n<\/strong><a href=\"http:\/\/www.l-chrono.com\/resultats2016\/corrida_de_bellegarde_6.pdf\">http:\/\/www.l-chrono.com\/resultats2016\/corrida_de_bellegarde_6.pdf<\/a><strong><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nLA CORRIDA DE BELLEGARDE SUR LE SITE WEB COURZYVITE :<\/strong><\/p>\n<p><strong>\u2013 R\u00e9sultats, compte rendu et photos de l\u2019\u00e9dition 2015 :<\/strong><br \/>\nBient\u00f4t en ligne !<\/p>\n<p><strong>\u2013 Pr\u00e9sentation de l\u2019\u00e9dition 2016 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/12\/17\/presentation-de-la-corrida-de-bellegarde-17-12-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/12\/17\/presentation-de-la-corrida-de-bellegarde-17-12-16\/<\/a><\/p>\n<p><span style=\"color: #000000;\"><strong>\u2013 R\u00e9sultats, compte rendu et photos de l\u2019\u00e9dition 2016 :<br \/>\n<\/strong><a href=\"https:\/\/www.courzyvite.run\/blog\/2016\/12\/24\/resultats-et-compte-rendu-de-la-corrida-de-bellegarde-17-12-16\/\">https:\/\/www.courzyvite.run\/blog\/2016\/12\/24\/resultats-et-compte-rendu-de-la-corrida-de-bellegarde-17-12-16\/<\/a><\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong style=\"font-size: 0.95em;\"><br \/>\n<\/strong><strong>INFOS PRATIQUES :<\/strong><\/p>\n<p><strong>Quatre courses :<\/strong><br \/>\n<strong>3 courses enfants :<\/strong><br \/>\n\u2013 Course n\u00b01 r\u00e9serv\u00e9e aux \u00e9veils athl\u00e9 gar\u00e7ons-filles (2011-2010-2009) : 500 m (une petite boucle).<br \/>\n\u2013 Course n\u00b02 r\u00e9serv\u00e9e aux poussins-poussines (2008-2007) : 1000 m (deux petites boucles).<br \/>\n\u2013 Course n\u00b03 r\u00e9serv\u00e9e aux benjamins-benjamines (2006-2005) et aux minimes gar\u00e7ons-filles (2004-2003) : 2000 m (une grande boucle).<br \/>\n<strong>Une course cadets et adultes :<\/strong><br \/>\n\u2013 Course n\u00b04 ou Challenge Ren\u00e9 Mugnier r\u00e9serv\u00e9e aux cadets, juniors, espoirs, seniors et v\u00e9t\u00e9rans hommes-femmes : 7800 m (quatre grandes boucles).<\/p>\n<p><strong>Parcours :<br \/>\n<\/strong>Site Web du Club Athl\u00e9tique du Bassin Bellegardien :<br \/>\n<a href=\"http:\/\/cabb.kalisport.com\/public\/1368\/upload\/files\/corrida-de-bellegarde\/parcours-corrida-enfants-et-adultes.pdf\">http:\/\/cabb.kalisport.com\/public\/1368\/upload\/files\/corrida-de-bellegarde\/parcours-corrida-enfants-et-adultes.pdf<\/a><\/p>\n<p><strong>Un challenge\u00a0:<\/strong><br \/>\n<strong>Le Challenge D\u00e9partemental des Courses Hors Stade de l\u2019Ain.<\/strong><\/p>\n<p><strong>Inscriptions :\u00a0<\/strong><br \/>\n<strong>\u2013 En ligne :\u00a0<\/strong>jusqu\u2019au vendredi 15 d\u00e9cembre \u00e0 20 h 00 sur le site Web L-Chrono\u00a0:<br \/>\n<a href=\"https:\/\/inscriptions-l-chrono.com\/corridadebellegarde2017\/select_competition\">https:\/\/inscriptions-l-chrono.com\/corridadebellegarde2017\/select_competition<\/a><br \/>\n<strong>\u2013\u00a0Jour J :\u00a0<\/strong>entre 14 h 00 et 15 h 30 au boulodrome, place Henri Dunand \u00e0 Bellegarde.<\/p>\n<p><strong>Montants :<br \/>\nEn ligne :<\/strong><br \/>\n<strong>\u2013 Course cadets et adultes\u00a0 :<\/strong>\u00a09 euros (8 euros + 1 euro de frais de gestion d\u2019Internet).<br \/>\n<strong>\u2013 Courses enfants :<\/strong>\u00a04 euros (3 euros + 1 euro de frais de gestion d\u2019Internet).<br \/>\n<strong>Jour J\u00a0:<br \/>\n<\/strong><strong>\u2013 Course cadets et adultes :<\/strong>\u00a09 euros.<br \/>\n<strong>\u2013 Courses enfants :<\/strong>\u00a04 euros.<\/p>\n<p><strong>Remise des dossards :<\/strong><br \/>\n<strong>\u2013\u00a0Lieu :<\/strong>\u00a0boulodrome, place Henri Dunand \u00e0 Bellegarde.<br \/>\n<strong>\u2013 Horaire :<\/strong>\u00a0entre 14 h 00 et 15 h 30.<\/p>\n<p><strong>Vestiaires et douches :<\/strong><br \/>\n<strong>\u2013\u00a0Lieu :<\/strong>\u00a0centre sportif Marcel Berthet, 55 rue Francis \u00e0 Bellegarde.<br \/>\n<strong>\u2013 Horaire :<\/strong>\u00a0entre 14 h 00 et 17 h 30.<\/p>\n<p><strong>D\u00e9parts :<\/strong><br \/>\n<strong>Horaires :<\/strong><br \/>\n\u2013 Echauffement musical des enfants par <strong>Jenny<\/strong>, coach de fitness \u00e0 domicile : 15 h 40.<br \/>\n\u2013 Course n\u00b01 r\u00e9serv\u00e9e aux \u00e9veils athl\u00e9 gar\u00e7ons-filles (2011-2010-2009) : 16 h 00.<br \/>\n\u2013 Course n\u00b02 r\u00e9serv\u00e9e aux poussins-poussines (2008-2007) : 16 h 05.<br \/>\n\u2013 Course n\u00b03 r\u00e9serv\u00e9e aux benjamins-benjamines (2006-2005) et aux minimes gar\u00e7ons-filles (2004-2003) : 16 h 15.<br \/>\n\u2013 Echauffement musical des cadets et des adultes par\u00a0Jenny, coach de fitness \u00e0 domicile : 16 h 15.<br \/>\n\u2013 Course n\u00b04 ou Challenge Ren\u00e9 Mugnier r\u00e9serv\u00e9e aux cadets, juniors, espoirs, seniors et v\u00e9t\u00e9rans hommes-femmes : 16 h 30.<\/p>\n<p><strong>Arriv\u00e9e :<br \/>\nRemise des prix :<\/strong> 17 h 30.<\/p>\n<p><strong>Renseignements compl\u00e9mentaires :<br \/>\n&#8211; E-mail du Club Athl\u00e9tique du Bassin Bellegardien : <\/strong><a href=\"mailto:contact.cabb@yahoo.fr\">contact.cabb@yahoo.fr<\/a><strong><br \/>\n&#8211; Page Facebook Ev\u00e9nement de la Corrida de Bellegarde :<br \/>\n<\/strong><a href=\"https:\/\/www.facebook.com\/events\/283856852123245\/\">https:\/\/www.facebook.com\/events\/283856852123245\/<\/a><strong><br \/>\n&#8211; Site Web de la manifestation : <\/strong><a href=\"http:\/\/cabb.kalisport.com\/corrida-de-bellegarde\">http:\/\/cabb.kalisport.com\/corrida-de-bellegarde<\/a><br \/>\n<strong>&#8211; T\u00e9l\u00e9phone de Chrystelle Lassalle-Ghendir<\/strong>, pr\u00e9sidente du Club Athl\u00e9tique du Bassin Bellegardien : 06-12-99-17-22.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><strong><br \/>\nPHOTOS :<\/strong><br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37638452142_54f112c8de_c-e1513313887664.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12505 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37638452142_54f112c8de_c-e1513313887664.jpg?resize=465%2C700&#038;ssl=1\" alt=\"\" width=\"465\" height=\"700\" \/><\/a>Parcours de la Corrida de Bellegarde.<br \/>\nIl empruntera cette passerelle qui enjambe la Valserine au moment o\u00f9 cette rivi\u00e8re se jette dans le Rh\u00f4ne.<br \/>\nClich\u00e9 de <strong>Claude Duchene<\/strong>.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12506 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37000543113_f149fa875b_b.jpg?resize=860%2C571\" alt=\"\" width=\"860\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37000543113_f149fa875b_b.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37000543113_f149fa875b_b.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37000543113_f149fa875b_b.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Parcours de la Corrida de Bellegarde.<br \/>\nDe nouveau la passerelle qui traverse la Valserine au moment o\u00f9 celle-ci se fait avaler toute crue par le troisi\u00e8me fleuve fran\u00e7ais.<br \/>\nClich\u00e9 de <strong>Claude Duchene<\/strong>.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12597 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?resize=860%2C860\" alt=\"\" width=\"860\" height=\"860\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?resize=420%2C420&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?resize=90%2C90&amp;ssl=1 90w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/24296310_921485441333513_2802856967892700551_n.jpg?resize=75%2C75&amp;ssl=1 75w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Emeric Arnaud\u00a0<\/strong>(Annecy Haute-Savoie Athl\u00e9tisme et Vallons de La Tour Triathlon), grandissime favori de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 16 juillet 2017 \u00e0 l\u2019occasion du Championnat de France de Triathlon Groupes d\u2019\u00e2ge, concouru \u00e0 Gray (Haute-Sa\u00f4ne), o\u00f9 Jeffrey s\u2019appropriera la 1\u00e8re place (1er senior 1) en 2h01\u201954.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12606 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_6013-e1511060731706.jpg?resize=800%2C534\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_6013-e1511060731706.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_6013-e1511060731706.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_6013-e1511060731706.jpg?resize=768%2C513&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><span class=\"text_exposed_show\">Le Suisse\u00a0<strong>Simon Senn\u00a0<\/strong>(Club Athl\u00e9tique du Bassin Bellegardien), outsider n\u00b01 de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 23 septembre 2017 par\u00a0<strong>Jean-Luc Caron<\/strong>\u00a0(Partenaire-Images),\u00a0\u00e0 l\u2019occasion du 6\u00e8me Trail de Musi\u00e8ges o\u00f9 Simon s\u2019appropriera, sur le 11 km, la 1\u00e8re place (1\u00e8re senior) en 49\u201930.<br \/>\nImage r\u00e9alis\u00e9e \u00e0\u00a0l\u2019arriv\u00e9e.<\/span><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12567 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37878567391_2e1f14efdf_z-1.jpg?resize=427%2C640\" alt=\"\" width=\"427\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37878567391_2e1f14efdf_z-1.jpg?w=427&amp;ssl=1 427w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37878567391_2e1f14efdf_z-1.jpg?resize=420%2C630&amp;ssl=1 420w\" sizes=\"auto, (max-width: 427px) 100vw, 427px\" \/><strong>Jeffrey Fleury\u00a0<\/strong>(Club Athl\u00e9tique du Bassin Bellegardien), un des outsiders de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 22 octobre 2017 par\u00a0<strong>Claude Duchene<\/strong>\u00a0\u00e0 l\u2019occasion du 1er Trail de la Valserine, concouru entre Bellegarde et Champfromier, o\u00f9 Jeffrey s\u2019appropriera la 2\u00e8me place (2\u00e8me senior) en 1h51\u201951.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12601 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4201.jpg?resize=860%2C567\" alt=\"\" width=\"860\" height=\"567\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4201.jpg?w=967&amp;ssl=1 967w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4201.jpg?resize=420%2C277&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4201.jpg?resize=768%2C507&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Sylv\u00e8re Pruvost<\/strong>\u00a0(La Foul\u00e9e d\u2019Annemasse, section de l\u2019Entente Athl\u00e9tique de l\u2019Arve ; Team The North Face), un des outsiders de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 13 novembre 2016 par <strong>Jean-Claude Delachenal<\/strong> \u00e0 l\u2019occasion de la 33\u00e8me Course de la Colline, concourue \u00e0 V\u00e9traz-Monthoux, o\u00f9 Sylv\u00e8re s\u2019appropriera sur le 13,1 km la 1\u00e8re place (1er senior) en 47\u201928.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 300 m de l\u2019arriv\u00e9e.<span class=\"text_exposed_show\"><br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12612 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0865.jpg?resize=860%2C571\" alt=\"\" width=\"860\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0865.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0865.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0865.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><strong>Marc Tamanini\u00a0<\/strong>(Thonon Athl\u00e9tic Club, section du L\u00e9man Athl\u00e9tic Club), un des outsiders de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 19 novembre 2017 par <strong>Jean-Claude Delachenal<\/strong>\u00a0\u00e0 l\u2019occasion du 11\u00e8me D\u00e9fi de Fort-l\u2019Ecluse, concouru \u00e0 L\u00e9az, o\u00f9 Marc s\u2019appropriera la 11\u00e8me place (7\u00e8me senior) en 1h18\u201939.<br \/>\nImage r\u00e9alis\u00e9e \u00e0\u00a0la Porte de France de Fort-l\u2019Ecluse, peu avant l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12610 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_7190.jpg?resize=800%2C532\" alt=\"\" width=\"800\" height=\"532\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_7190.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_7190.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_7190.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><strong>Didier Thiaffey-Rencorel\u00a0<\/strong>(ASPTT Annecy Athl\u00e9tisme, Team Craft-Salming et Team St\u00e4ubli Sports), un des outsiders de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 18 juillet 2015 par <strong>Jean-Claude Delachenal<\/strong>\u00a0\u00e0 l\u2019occasion du 7\u00e8me 10 km de Th\u00f4nes o\u00f9 Didier s\u2019appropriera la 8\u00e8me place (5\u00e8me senior) en 35\u201951.<br \/>\nImage r\u00e9alis\u00e9e \u00e0\u00a0l\u2019arriv\u00e9e.<\/span><br \/>\n<a href=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/33360815614_c1c5544680_z-1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12529 size-full\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/33360815614_c1c5544680_z-1.jpg?resize=410%2C640&#038;ssl=1\" alt=\"\" width=\"410\" height=\"640\" \/><\/a><strong>Romain Wyndaele\u00a0<\/strong>(Team Ravanel and Co), un des outsiders de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 26 mars 2017 par\u00a0<strong>Claude Duchene<\/strong>\u00a0\u00e0 l\u2019occasion du 3\u00e8me Trail de la Michaille, concouru \u00e0 Ch\u00e2tillon-en-Michaille, o\u00f9 Romain s\u2019appropriera sur le 22 km la 7\u00e8me place (5\u00e8me senior) en 1h38\u201950.<br \/>\nImage r\u00e9alis\u00e9e dans la premi\u00e8re mont\u00e9e.<br \/>\n<span style=\"color: #000000;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12570 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/16105685_10211594770930950_2283707130042383120_n-1.jpg?resize=860%2C678\" alt=\"\" width=\"860\" height=\"678\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/16105685_10211594770930950_2283707130042383120_n-1.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/16105685_10211594770930950_2283707130042383120_n-1.jpg?resize=420%2C331&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/16105685_10211594770930950_2283707130042383120_n-1.jpg?resize=768%2C606&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 237 :<strong> Laure Tassion\u00a0<\/strong>(Athl\u00e9 Saint-Julien 74), grandissime favorite de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 8 janvier 2017 par<strong> Philippe Devaux<\/strong>\u00a0\u00e0 l\u2019occasion des Championnats des Savoie de Cross-Country, concourus \u00e0 Pontcharra, o\u00f9 Laure s\u2019appropriera chez les femmes la 4\u00e8me place (4\u00e8me senior) en 22\u201939.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12626 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4455.jpg?resize=860%2C570\" alt=\"\" width=\"860\" height=\"570\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4455.jpg?w=888&amp;ssl=1 888w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4455.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_4455.jpg?resize=768%2C509&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Dossard 106 :<strong>\u00a0S\u00e9verine Gaillard<\/strong>\u00a0(Chamonix Mont-Blanc Marathon),\u00a0un des outsiders f\u00e9minins de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 20 novembre 2016 par <strong>Jean-Claude Delachenal<\/strong>\u00a0\u00e0 l\u2019occasion du 27\u00e8me Cross des B\u00fbches, concouru \u00e0 Marcellaz-en-Faucigny, o\u00f9 S\u00e9verine s\u2019appropriera chez les femmes la 2\u00e8me place (1\u00e8re senior) en 35\u201956.<br \/>\nImage r\u00e9alis\u00e9e au d\u00e9but du 4\u00e8me et dernier tour.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12618 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_06931.jpg?resize=800%2C533\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_06931.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_06931.jpg?resize=420%2C280&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/IMG_06931.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><strong>Anne Michel<\/strong>\u00a0(Thonon-les-Bains), un des outsiders f\u00e9minins de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 11 octobre 2015 par <strong>Jean-Claude Delachenal<\/strong>\u00a0\u00e0 l\u2019occasion de la 30\u00e8me Persjussienne, concourue entre Pers-Jussy et La Chapelle-Rambaud, o\u00f9 Anne s\u2019appropriera la 8\u00e8me place (4\u00e8me V1, 134\u00e8me au scratch) en 1h00\u201931.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12594 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37831027286_bd32930c73_z-1.jpg?resize=449%2C640\" alt=\"\" width=\"449\" height=\"640\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37831027286_bd32930c73_z-1.jpg?w=449&amp;ssl=1 449w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37831027286_bd32930c73_z-1.jpg?resize=420%2C599&amp;ssl=1 420w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/>La Franco-Britannique<strong> Emilie Shaw\u00a0<\/strong>(Run Valserine), un des outsiders f\u00e9minins de la 3\u00e8me \u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017.<br \/>\nClich\u00e9 pris le 22 octobre 2017 par\u00a0<strong>Claude Duchene<\/strong>\u00a0\u00e0 l\u2019occasion du 1er Trail de la Valserine, concouru entre Bellegarde et Champfromier, o\u00f9 Emilie s\u2019appropriera la 1\u00e8re place (1\u00e8re senior, 29\u00e8me au scratch) en 2h13\u201934.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 l\u2019arriv\u00e9e.<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12629 aligncenter\" src=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0480.jpg?resize=860%2C571\" alt=\"\" width=\"860\" height=\"571\" srcset=\"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0480.jpg?w=886&amp;ssl=1 886w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0480.jpg?resize=420%2C279&amp;ssl=1 420w, https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/DSC_0480.jpg?resize=768%2C510&amp;ssl=1 768w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/>Deux des principales figures dirigeantes de Run Valserine, pr\u00e9sentes sur la 3\u00e8me\u00a0\u00e9dition de la Corrida de Bellegarde, disput\u00e9e ce samedi 16 d\u00e9cembre 2017 :<br \/>\n&#8211; Dossard 54 : <strong>Philippe Henry<\/strong>, pr\u00e9sident.<br \/>\n&#8211; Dossard 58 : <strong>Bertrand Grosclaude<\/strong>, charg\u00e9 de la communication.<br \/>\nClich\u00e9 pris le 29 octobre 2017 par <b>Jean-Claude Delachenal<\/b>\u00a0\u00e0 l\u2019occasion du 31\u00e8me Cross de la Semine, concouru \u00e0 Saint-Germain-sur-Rh\u00f4ne, o\u00f9 les deux hommes s\u2019approprieront les places suivantes :<br \/>\n&#8211; Philippe : 95\u00e8me (2\u00e8me V2) en 1h12\u201928.<br \/>\n&#8211; Bertrand : 96\u00e8me (24\u00e8me V1) en\u00a01h12\u201929.<br \/>\nImage r\u00e9alis\u00e9e \u00e0 150 m de l\u2019arriv\u00e9e.<br \/>\n<\/span><\/p>\n<p><strong style=\"font-size: 0.95em;\">\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LE CABB SUR SA LANCEE ! C\u2019est \u00e0 partir de 2015 que le Club Athl\u00e9tique du Bassin Bellegardien (CABB) s\u2019est tourn\u00e9 dans l\u2019organisation annuelle de quatre courses hors stade (1) que sont : le Trail de la Michaille jusqu\u2019en 2016 (2), remplac\u00e9 ensuite par le D\u00e9fi de Fort-l\u2019Ecluse (3) ; la Mont\u00e9e du Cr\u00eat d\u2019Eau ; la Voie du Tram, devenu le Trail de la Valserine \u00e0 compter de 2017 [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":12506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[14,13],"tags":[11],"class_list":["post-12428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ain","category-presentations-des-courses","tag-news"],"views":2710,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.courzyvite.run\/blog\/wp-content\/uploads\/2017\/12\/37000543113_f149fa875b_b.jpg?fit=1024%2C680&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7PZ3h-3es","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/12428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/comments?post=12428"}],"version-history":[{"count":0,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/posts\/12428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media\/12506"}],"wp:attachment":[{"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/media?parent=12428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/categories?post=12428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.courzyvite.run\/blog\/wp-json\/wp\/v2\/tags?post=12428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}